{"id":21129,"date":"2025-03-25T11:58:07","date_gmt":"2025-03-25T11:58:07","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=21129"},"modified":"2025-05-02T17:17:09","modified_gmt":"2025-05-02T17:17:09","slug":"fdssdgg","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/21129","title":{"rendered":"Eine Vision der Erleichterung, nachdem der B\u00fcrgersteig am 14. Februar 2023 gr\u00fcn wird"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"21129\" class=\"elementor elementor-21129\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74897e97 e-flex e-con-boxed e-con e-parent\" data-id=\"74897e97\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12e71e70 elementor-widget elementor-widget-text-editor\" data-id=\"12e71e70\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Ich fragte mich, wann die Erleichterung kommen w\u00fcrde, als ich einen Anruf bekam, dass die Erleichterung kommen w\u00fcrde, nachdem der B\u00fcrgersteig wieder gr\u00fcn geworden war. Ich stand in meiner Gegend in der Stadt des 6. Oktober und vor mir war ein B\u00fcrgersteig, der eigentlich wei\u00df war, aber k\u00fcrzlich gr\u00fcn gestrichen worden war. Die Farbe war noch nicht getrocknet, aber es gab einige Stellen, die nicht gr\u00fcn gestrichen, aber noch wei\u00df waren. Ich stellte mich auf den B\u00fcrgersteig, nahm die noch nicht getrocknete gr\u00fcne Farbe in die Hand und wischte die nicht gr\u00fcn gestrichenen Stellen ab, bis der ganze B\u00fcrgersteig gr\u00fcn war. Das tat ich, um die Erleichterung zu beschleunigen. Neben dem B\u00fcrgersteig war eine Moschee, in der Menschen beteten, also ging ich hinein, um zu beten, und verlie\u00df die Moschee nach dem Gebet inmitten einer Menge von Gl\u00e4ubigen, die \u201eGott ist gro\u00df\u201c skandierten. Dies war ein Anzeichen f\u00fcr eine Erleichterung.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646\u0646\u064a \u0643\u0646\u062a \u0623\u062a\u0633\u0627\u0626\u0644 \u0645\u062a\u064a \u064a\u0643\u0648\u0646 \u0627\u0644\u0641\u0631\u062c \u0641\u0623\u062a\u0627\u0646\u064a \u0647\u0627\u062a\u0641 \u0628\u0623\u0646 \u0627\u0644\u0641\u0631\u062c \u0633\u064a\u0643\u0648\u0646 \u0628\u0639\u062f \u0623\u0646 \u064a\u0635\u0628\u062d \u0627\u0644\u0631\u0635\u064a\u0641 \u0644\u0648\u0646\u0647 \u0623\u062e\u0636\u0631 \u0648\u0643\u0646\u062a \u0623\u0642\u0641 \u0641\u064a \u0645\u0646\u0637\u0642\u062a\u064a \u0628\u0645\u062f\u064a\u0646\u0629 \u0627\u0644\u0633\u0627\u062f\u0633 \u0645\u0646 \u0623\u0643\u062a\u0648\u0628\u0631 \u0648\u0643\u0627\u0646 \u0623\u0645\u0627\u0645\u064a \u0631\u0635\u064a\u0641 \u0644\u0648\u0646\u0647 \u0627\u0644\u0623\u0633\u0627\u0633\u064a \u0623\u0628\u064a\u0636 \u0648\u0644\u0643\u0646 \u062a\u0645 \u062f\u0647\u0627\u0646\u0647 \u0628\u0627\u0644\u0628\u0648\u064a\u0629 \u062d\u062f\u064a\u062b\u0627\u064b \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0623\u062e\u0636\u0631 \u0648\u0643\u0627\u0646 \u0627\u0644\u062f\u0647\u0627\u0646 \u0644\u0645 \u064a\u062c\u0641 \u0628\u0639\u062f \u0648\u0644\u0643\u0646 \u0643\u0627\u0646 \u0647\u0646\u0627\u0643 \u0645\u0646\u0627\u0637\u0642 \u0642\u0644\u064a\u0644\u0629 \u063a\u064a\u0631 \u0645\u062f\u0647\u0648\u0646\u0629 \u0628\u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0623\u062e\u0636\u0631 \u0648\u0643\u0627\u0646\u062a \u0644\u0627\u062a\u0632\u0627\u0644 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":21130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[112],"tags":[],"class_list":{"0":"post-21129","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2021-"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=21129"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/21129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/21130"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=21129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=21129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=21129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}