{"id":20860,"date":"2025-03-24T12:27:42","date_gmt":"2025-03-24T12:27:42","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=20860"},"modified":"2025-04-27T18:55:56","modified_gmt":"2025-04-27T18:55:56","slug":"dsfrer","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/de\/archives\/20860","title":{"rendered":"Visionen von Jesus, Friede sei mit ihm, und der Vortrag zum Kampftraining am 22. M\u00e4rz 2020"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"20860\" class=\"elementor elementor-20860\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4207a43 e-flex e-con-boxed e-con e-parent\" data-id=\"4207a43\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-333cf1be elementor-widget elementor-widget-text-editor\" data-id=\"333cf1be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Ich sah mich in einem mittelgro\u00dfen geschlossenen Raum mit einer Reihe von K\u00e4mpfern, als w\u00e4ren wir in einer Kriegsbesprechung. Dann trat unser Meister Jesus (Friede sei mit ihm) ein. Ich hie\u00df ihn willkommen und riet ihm, den Anwesenden den Unterschied zwischen einem Propheten und einem Gesandten zu erkl\u00e4ren, da meine Meinung die Anwesenden nicht \u00fcberzeugte. Unser Meister Jesus (Friede sei mit ihm) stand mitten im Raum und hielt eine Art Vortrag, in dem er die Anwesenden \u00fcber die Notwendigkeit guter Kampfvorbereitung durch Training informierte. Im Raum befanden sich einige libysche Kampfpiloten, von denen einige hervorragend ausgebildet waren, andere weniger gut. Einer der hervorragend ausgebildeten Piloten unterhielt sich mit unserem Meister Jesus (Friede sei mit ihm) \u00fcber seine Kampfvorbereitung. Mir kam der Gedanke, dass unser Meister Jesus (Friede sei mit ihm) ihnen am Ende des Vortrags den Unterschied zwischen einem Propheten und einem Gesandten erkl\u00e4ren w\u00fcrde, doch ich wachte vor dem Ende des Vortrags auf.<br class=\"html-br\" \/>Hinweis: Unser Meister Jesus, Friede sei mit ihm, ist der erste und am h\u00e4ufigsten in Visionen gesehene Prophet seit der Mittelschule bis heute, und zwar unz\u00e4hlige Male.<\/h1><h1><strong>Interpretation der Vision in diesem Video<\/strong><\/h1><p><iframe title=\"Visionen von Jesus, Friede sei mit ihm, und der Vortrag zum Kampftraining am 22. M\u00e4rz 2020\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/hoWcYuJmgKE?list=PLGSQ8bPhLqKvbIK2NxQ1CoUA-dKyGIGlP\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0631\u0623\u064a\u062a \u0623\u0646\u0646\u064a \u0641\u064a \u063a\u0631\u0641\u0629 \u0645\u063a\u0644\u0642\u0629 \u0645\u062a\u0648\u0633\u0637\u0629 \u0627\u0644\u062d\u062c\u0645 \u0628\u0647\u0627 \u0639\u062f\u062f \u0645\u0646 \u0627\u0644\u0631\u062c\u0627\u0644 \u0627\u0644\u0645\u0642\u0627\u062a\u0644\u064a\u0646 \u0648\u0643\u0623\u0646\u0646\u0627 \u0643\u0646\u0627 \u0641\u064a \u0627\u062c\u062a\u0645\u0627\u0639 \u062d\u0631\u0628 \u0641\u062f\u062e\u0644 \u0639\u0644\u064a\u0646\u0627 \u0633\u064a\u062f\u0646\u0627 \u0639\u064a\u0633\u0649 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u0641\u0627\u0633\u062a\u0642\u0628\u0644\u062a\u0647 \u0648\u0623\u0648\u0635\u064a\u062a\u0647 \u0623\u0646 \u064a\u0642\u0648\u0644 \u0644\u0644\u0645\u062a\u0648\u0627\u062c\u062f\u064a\u0646 \u0628\u0627\u0644\u063a\u0631\u0641\u0629 \u0627\u0644\u0641\u0631\u0642 \u0628\u064a\u0646 \u0627\u0644\u0646\u0628\u064a \u0648\u0627\u0644\u0631\u0633\u0648\u0644 \u0644\u0623\u0646 \u0645\u0646 \u0643\u0627\u0646 \u0628\u0627\u0644\u063a\u0631\u0641\u0629 \u0643\u0627\u0646\u0648\u0627 \u063a\u064a\u0631 \u0645\u0642\u062a\u0646\u0639\u064a\u0646 \u0628\u0631\u0623\u064a\u064a \u0641\u0648\u0642\u0641 \u0633\u064a\u062f\u0646\u0627 \u0639\u064a\u0633\u0649 \u0639\u0644\u064a\u0647 \u0627\u0644\u0633\u0644\u0627\u0645 \u0641\u064a \u0645\u0646\u062a\u0635\u0641 \u0627\u0644\u063a\u0631\u0641\u0629 \u0648\u0643\u0627\u0646 \u064a\u0644\u0642\u0649 \u0645\u0627 \u064a\u0634\u0628\u0647 \u0627\u0644\u0645\u062d\u0627\u0636\u0631\u0629 \u064a\u0648\u0635\u0649 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":20861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[111],"tags":[],"class_list":{"0":"post-20860","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category--2016-2020"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/20860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=20860"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/posts\/20860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/20861"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=20860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/categories?post=20860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/tags?post=20860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}