{"id":34029,"date":"2025-05-06T11:41:52","date_gmt":"2025-05-06T11:41:52","guid":{"rendered":"https:\/\/tamerbadr.com\/?page_id=34029"},"modified":"2025-07-30T18:12:01","modified_gmt":"2025-07-30T18:12:01","slug":"why-they-converted-to-islam","status":"publish","type":"page","link":"https:\/\/tamerbadr.com\/de\/why-they-converted-to-islam","title":{"rendered":"Warum sind sie Muslime geworden?"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"34029\" class=\"elementor elementor-34029\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f9119a elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6f9119a\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5089027\" data-id=\"5089027\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b66f75 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"2b66f75\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"956\" height=\"825\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/about-dot-vector.png\" class=\"attachment-full size-full wp-image-883\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca8b229 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca8b229\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e331ecf\" data-id=\"e331ecf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb2353a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb2353a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1373dc1\" data-id=\"1373dc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25c3819 elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"25c3819\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Warum sind sie Muslime geworden?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18ab3bd elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"18ab3bd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir sind hier, um ein ehrliches, ruhiges und respektvolles Fenster zum Islam zu \u00f6ffnen.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c46d4b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6c46d4b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Auf dieser Seite stellen wir die Geschichten von Menschen mit unterschiedlichem Hintergrund, aus verschiedenen Kulturen und Religionen vor, die sich nach einer Reise der Recherche und des Nachdenkens mit \u00dcberzeugung f\u00fcr den Islam entschieden haben.<br \/>Es handelt sich dabei nicht nur um pers\u00f6nliche Anekdoten, sondern um ehrliche Zeugnisse, die den tiefgreifenden Wandel zum Ausdruck bringen, den der Islam in ihren Herzen und K\u00f6pfen bewirkt hat, die Fragen, auf die sie Antworten gefunden haben, und die Ruhe, die sie nach dem Islam empfunden haben.<\/h1><h1>Unabh\u00e4ngig davon, ob die Geschichte mit philosophischer Forschung, Neugier oder sogar mit einer ber\u00fchrenden menschlichen Situation begann, der gemeinsame Nenner dieser Erfahrungen ist das Licht, das sie im Islam fanden, und die Gewissheit, die an die Stelle der Zweifel trat.<\/h1><h1>Wir pr\u00e4sentieren diese Geschichten in mehreren Sprachen, sowohl in schriftlicher als auch in visueller Form, um zu inspirieren und den Islam durch eine lebendige menschliche Erfahrung vorzustellen.<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-23af7ed\" data-id=\"23af7ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7bd5986 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bd5986\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0dcd84a\" data-id=\"0dcd84a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6233391 elementor-widget__width-auto elementor-widget-laptop__width-initial elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6233391\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/324423423.png\" class=\"elementor-animation-float attachment-full size-full wp-image-36025\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0f2171 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"b0f2171\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc0d324\" data-id=\"fc0d324\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b1362e elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3b1362e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd61281 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd61281\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-adb20d5\" data-id=\"adb20d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c59897a elementor-widget elementor-widget-heading\" data-id=\"c59897a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gro\u00dfe Pers\u00f6nlichkeiten, die Muslime wurden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f7c83c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f7c83c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8b347b8\" data-id=\"8b347b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca2c07 elementor-widget elementor-widget-toggle\" data-id=\"3ca2c07\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6351\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6351\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Salman Al-Farisi - Der Wahrheitssuchende<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6351\"><p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36214 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/243324.jpg\" width=\"300\" height=\"168\" \/><\/p><h1><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Es war eine Geschichte \u00fcber\u00a0<\/span>Der gro\u00dfe Gefolgsmann Salman al-Farsi <span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\" style=\"color: var( --e-global-color-primary ); font-family: var( --e-global-typography-accent-font-family ), Sans-serif; font-size: var( --e-global-typography-accent-font-size ); font-weight: var( --e-global-typography-accent-font-weight ); background-color: var( --e-global-color-secondary );\">Salman (m\u00f6ge Allah mit ihm zufrieden sein) lebte vor dem Aufkommen des Islams mit dem Magentum, dem Christentum und dem Judentum und suchte so lange nach der wahren Religion, bis Allah ihn zu ihr f\u00fchrte. Er gab seinen Verstand und sein Herz nicht den Traditionen und dem Glauben hin, die er in seinem Heimatland geerbt hatte, denn wenn er bis zu seinem Tod daran festgehalten h\u00e4tte, w\u00e4re er nicht einer der Gef\u00e4hrten des Propheten (Friede sei mit ihm) gewesen. Er w\u00e4re nicht zur Religion des Islam konvertiert und in seiner Vielg\u00f6tterei gestorben.<\/span><\/h1><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\">Obwohl er in Persien inmitten der Feueranbetung aufwuchs, war Salman der Perser auf der Suche nach der wahren Religion und begab sich auf die Suche nach Gott. Er glaubte an die magische Religion und war von dieser Religion nicht \u00fcberzeugt, aber er fand heraus, dass seine Eltern ihr ergeben waren, und so nahm er sie mit ihnen an. Als sich seine Zweifel an seiner Religion und der Religion seiner Familie verst\u00e4rkten, verlie\u00df Salman sein Land und wanderte auf der Suche nach der absoluten religi\u00f6sen Wahrheit in die Levante aus, wo er M\u00f6nche und Priester traf, und nach einer langen Reise kam Salman als Sklave in Medina an, und als er vom Propheten (Friede sei mit ihm) h\u00f6rte, traf er ihn und wurde Muslim, nachdem er von seiner Botschaft \u00fcberzeugt war.<br class=\"html-br\" \/>Salman wuchs in der Nachkommenschaft einer aristokratischen Familie auf, die im Paradies in Persien lebte, und sein Vater liebte ihn so sehr und f\u00fcrchtete ihn so sehr, dass er ihn in seinem Haus einsperrte, und Salman hatte sich im Magianismus weitergebildet, bis er der Bewohner des Feuers wurde, das brennt und es keine Stunde lang verl\u00f6schen l\u00e4sst.<br class=\"html-br\" \/>Eines Tages bat ihn sein Vater, zu seinem Anwesen zu gehen, um sich darum zu k\u00fcmmern, weil er viel zu tun hatte, und er bat ihn, nicht zu sp\u00e4t zu kommen, damit er sich keine Sorgen machen m\u00fcsse. Auf dem Weg zum Anwesen kam Salman an einer Kirche vorbei, in der Menschen beteten, und er trat ein, bewunderte sie und sagte: \"Das - bei Gott - ist besser als die Religion, in der wir sind.\" Er verlie\u00df sie erst, als die Sonne unterging.<br class=\"html-br\" \/>Salman kehrte zu seinem Vater zur\u00fcck und erz\u00e4hlte ihm, was geschehen war, und dass er von dieser Religion beeindruckt war, so dass er ihn in Ketten legte.<br class=\"html-br\" \/>Salman erz\u00e4hlt: \"Ich schickte zu den Christen und sagte: 'Wenn eine Gruppe von Kaufleuten aus der Levante zu euch kommt, erz\u00e4hlt mir von ihnen. Sie erz\u00e4hlten es ihm und er floh aus dem Haus seines Vaters in die Levante.<br class=\"html-br\" \/>Als sein Tod eintrat, wurde ihm empfohlen, zu einem Bischof in Mosul zu gehen, der sich im gleichen Zustand der Rechtschaffenheit befand und auf die Sendung des Propheten wartete, also ging er zu ihm und blieb eine Weile bei ihm. Als dessen Tod eintrat, wurde ihm empfohlen, zu einem Bischof in Nusaybin zu gehen, und die Sache wiederholte sich, bis er zu einem Bischof aus dem Volk von Amauria in Rom kam, der ihm von der Zeit des Propheten, m\u00f6ge Allah ihn segnen und ihm Frieden und Segen gew\u00e4hren, erz\u00e4hlte. Der Bischof sagte zu ihm: \"Mein Sohn, bei Gott, ich wei\u00df nicht, dass es noch jemanden gibt, der so ist, wie wir es waren, deshalb befehle ich dir, zu ihm zu kommen, aber die Zeit ist gekommen, dass ein Prophet aus dem Heiligtum gesandt wird, dessen Auswanderung zwischen zwei Freiheiten in ein w\u00fcstes Land mit Palmen sein wird, und es werden Zeichen an ihm sein, die nicht verborgen sind, und zwischen seinen Schultern ist das Siegel des Prophetentums, und er wird eine Gabe essen und keine Almosen, wenn du also in dieses Land kommen kannst, dann tu es.<br class=\"html-br\" \/>Er ging mit ihnen auf die Suche nach dem Propheten der Endzeit, doch unterwegs verkauften sie ihn an einen Juden und brachten ihn nach Madinah, wo er an den Palmen erkannte, dass es sich um die Stadt des Propheten (Friede sei mit ihm) handelte, wie der Bischof sie ihm beschrieben hatte.<br class=\"html-br\" \/>Salman erz\u00e4hlt die Geschichte von der Ankunft des Propheten in Madinah: \"Allah schickte seinen Propheten (Friede sei mit ihm) nach Mekka, ohne mir irgendetwas von seinen Angelegenheiten zu erz\u00e4hlen, trotz meiner Sklaverei, bis der Gesandte Allahs (Friede sei mit ihm) nach Qibaa kam, w\u00e4hrend ich f\u00fcr meinen Freund in einer Palme arbeitete, als ich die Nachricht von der Ankunft des Propheten h\u00f6rte, kam ich herunter und sagte: \"Was ist das f\u00fcr eine Nachricht?\" Mein Meister hob die Hand und schlug mich hart und sagte: \"Was geht dich das an, geh zur\u00fcck an deine Arbeit?\"<br class=\"html-br\" \/>Salman wollte die Eigenschaften des Propheten (Friede sei mit ihm) pr\u00fcfen, von denen ihm der Bischof erz\u00e4hlt hatte, n\u00e4mlich dass er keine Almosen isst und Geschenke annimmt und dass der Ring des Prophetentums zwischen seinen Schultern liegt und andere Zeichen, also ging er am Abend zum Propheten (Friede sei mit ihm) und nahm Essen mit und sagte ihm, dass dieses Essen Almosen sei, aber der Prophet befahl seinen Gef\u00e4hrten zu essen und er a\u00df nicht, also wusste Salman, dass dies eines der Zeichen war.<br class=\"html-br\" \/>Dann kehrte er wieder zum Propheten (Friede sei mit ihm) zur\u00fcck, holte Essen und sagte ihm, es sei ein Geschenk, und der Prophet (Friede sei mit ihm) und seine Gef\u00e4hrten a\u00dfen, so dass er wusste, dass es das zweite Zeichen war.<br class=\"html-br\" \/>Salman suchte nach dem Ring des Prophetentums und sagte: \"Dann kam ich zum Gesandten Allahs, m\u00f6ge Allah ihn segnen und ihm Frieden gew\u00e4hren, w\u00e4hrend er einem Begr\u00e4bnis folgte, und w\u00e4hrend er in seinen Gef\u00e4hrten war, drehte ich mich um, um auf seinen R\u00fccken zu schauen, ob ich den Ring sehen k\u00f6nnte, der mir beschrieben wurde. Als er sah, dass ich mich umdrehte, wusste er, dass ich mich nach etwas erkundigte, das mir beschrieben worden war, also warf er sein Gewand von seinem R\u00fccken, und ich schaute auf den Ring und erkannte ihn, also kniete ich nieder, um ihn zu k\u00fcssen und weinte.\" Der Prophet (Friede sei mit ihm) bat die Gef\u00e4hrten des Propheten (Friede sei mit ihm), ihm zu helfen, und tats\u00e4chlich wurde Salman befreit und blieb ein Gef\u00e4hrte des Propheten (Friede sei mit ihm), so sehr, dass der Prophet (Friede sei mit ihm) sagte: \"Salman ist einer von uns aus der Familie des Hauses.\"<br class=\"html-br\" \/>Salmans Weg zur Wahrheit war lang und beschwerlich: Er wanderte vom Magiertum in Persien zum Christentum in der Levante und zur Sklaverei auf der arabischen Halbinsel, bis Gott der Allm\u00e4chtige ihn zum Propheten (Friede sei mit ihm) und zum Islam f\u00fchrte.<\/span><\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6352\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6352\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Umar ibn al-Khattab (vom gr\u00f6\u00dften Feind der Muslime zum Kalifen der Muslime)<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6352\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6352\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-36218 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/546543654-300x193.jpg\" width=\"300\" height=\"193\" \/>Umar ibn al-Khattab, der Gef\u00e4hrte des Gesandten Allahs, war ein starker und majest\u00e4tischer Mann, der im Alter von sechsundzwanzig Jahren in den Islam eintrat, und seine Reihenfolge des Eintritts in den Islam war nach neununddrei\u00dfig M\u00e4nnern, d.h. er war der vierzigste Mann in der Reihenfolge derer, die in den Islam eintraten, und es wurde gesagt, f\u00fcnfzig oder sechsundf\u00fcnfzig.<\/h1><h1>Umar ibn al-Khattab (m\u00f6ge Allah ihn segnen und ihm Frieden gew\u00e4hren) war einer der sch\u00e4rfsten Feinde der Muslime, bevor er zum Islam \u00fcbertrat.<\/h1><h1>Der Prophet (Friede und Segen Allahs seien auf ihm) betete: \"O Allah, st\u00e4rke den Islam durch die beiden M\u00e4nner, die dir am liebsten sind, Abu Jahl oder Umar bin al-Khattab\", und er sagte: \"Umar war der geliebtere von den beiden.\" Es war tats\u00e4chlich Umars Eintritt in den Islam.<\/h1><h4>Die Geschichte des Islam von Umar ibn al-Khattab<\/h4><h1>Das Folgende ist die Geschichte von Umar ibn al-Khattab (m\u00f6ge Allah mit ihm zufrieden sein): Umar ibn al-Khattab beschloss, den Propheten Muhammad zu t\u00f6ten, da die Quraisch den Propheten Muhammad t\u00f6ten wollten, und sie berieten sich \u00fcber die Frage, wie sie ihn t\u00f6ten sollten und welcher Mann ihn t\u00f6ten sollte. Umar selbst wurde zum Stellvertreter ernannt, also nahm er an einem sehr hei\u00dfen Tag sein Schwert und ging zum Gesandten Allahs, m\u00f6ge Allah ihn segnen und ihm Frieden gew\u00e4hren, w\u00e4hrend der Prophet mit seinen Gef\u00e4hrten sa\u00df, darunter Abu Bakr al-Siddiq, Ali, Hamza und einige Gef\u00e4hrten, die beim Gesandten Allahs blieben und nicht nach Abessinien gingen. 'Umar ibn al-Khattab wusste, dass sie in Dar al-Arqam am Fu\u00dfe von Safa versammelt waren, und auf seinem Weg begegnete ihm der Gef\u00e4hrte Nu'ayem ibn Abdullah al-Naham, der zu jener Zeit Muslim war, der ihn abfing und fragte: \"Er sagte ihm, er wolle den Gesandten Allahs t\u00f6ten, weil er ihre G\u00f6tter beleidigt und ihre Religion beleidigt habe. Die beiden M\u00e4nner schrien ihn an, und er sagte: \"Was f\u00fcr einen elenden Weg hast du genommen, Umar.\" Er erinnerte ihn an die St\u00e4rke der Banu Abdul Manaf und daran, dass sie ihn nicht gehen lassen w\u00fcrden, woraufhin Umar ihn fragte, ob er Muslim geworden sei, um ihn zu t\u00f6ten. Als Naim sah, dass er sein Ziel, den Gesandten Allahs (Friede und Segen Allahs seien auf ihm) zu t\u00f6ten, nicht aufgeben wollte, hielt er ihn davon ab, indem er ihm sagte, dass seine Familie, seine Schwester, ihr Mann und sein Cousin Muslime geworden seien.<\/h1><h4>Die Haltung von Umar ibn al-Khattab gegen\u00fcber dem Islam seiner Schwester<\/h4><h1>'Umar ibn al-Khattab ging zum Haus seiner Schwester, um sich zu beschweren, nachdem Nu'ayem ihm vom Islam seiner Schwester erz\u00e4hlt hatte. Seine Schwester Fatima war zusammen mit ihrem Mann Sa'id zum Islam \u00fcbergetreten, und der Gef\u00e4hrte Khabbab ibn al-'Art lehrte sie den Koran. Als 'Umar dort ankam, las Khabbab Fatima und ihrem Mann Sa'id den Koran vor, und es wurde aus der Sure Taha gelesen. 'Umar fragte sie nach dem Ger\u00e4usch, das er h\u00f6rte, und sie sagten ihm, es sei nur ein Gespr\u00e4ch zwischen ihnen. 'Umar sagte: \"Vielleicht bist du ungeduldig geworden.\" Sa'id sagte zu ihm: \"Glaubst du, 'Umar, wenn die Wahrheit in deinen H\u00e4nden liegt?\" 'Umar stand auf, um ihn zu schlagen, aber Fatima hielt ihn auf, woraufhin er sie ins Gesicht schlug, woraufhin sie w\u00fctend antwortete: \"Als 'Umar von ihnen ablie\u00df, bat er um das Buch, in dem sie lasen, aber seine Schwester gab ihm das Buch nicht, es sei denn, er w\u00fcrde sich selbst reinigen, also gehorchte er und reinigte sich, dann nahm er das Buch und las aus der Sure \"Taha\", bis er zu der Stelle kam: \"Ich bin Gott, es gibt keinen Gott au\u00dfer mir, so betet mich an und betet f\u00fcr mein Gedenken\" [Taha: 14]. 'Umar staunte \u00fcber die G\u00fcte der Worte, die er las, und dann kam Khabib heraus und erz\u00e4hlte ihm, dass der Gesandte Allahs, Allahs Frieden und Segen seien auf ihm, ihn zum Islam aufgerufen hatte.<\/h1><h4>Das Bekenntnis von Umar ibn al-Khattab zum Islam in den H\u00e4nden des Propheten<\/h4><h1>Als Umar die Verse las, fragte er Khabbab, wo der Gesandte Allahs sei, damit er zu ihm gehen und sich zum Islam bekennen k\u00f6nne, und Khabbab sagte ihm, er sei im Haus von Al-Arqam ibn Abi Al-Arqam. Sie erschraken, als sie Umars Stimme h\u00f6rten, aber Hamza beruhigte sie und sagte: \"Wenn Allah will, wird er Muslim werden, und wenn Er nicht will, wird es f\u00fcr uns ein Leichtes sein, ihn zu t\u00f6ten. Sie brachten ihn zum Gesandten Allahs. Hamza und ein anderer Mann hatten Umar an den Armen gepackt und f\u00fchrten ihn zum Gesandten Allahs, Allahs Frieden und Segen seien auf ihm. Umar sagte dem Gesandten Allahs, dass er zum Islam \u00fcbertreten wolle, woraufhin der Gesandte Allahs, m\u00f6ge Allah ihn segnen und ihm Frieden und Segen schenken, eine gro\u00dfe Verk\u00fcndigung machte, und die Bewohner des Hauses erfuhren von seinem Islam, und sie freuten sich, dass sie durch den Islam von Hamza und Umar st\u00e4rker und m\u00e4chtiger geworden waren.<\/h1><h4>Der Einfluss des Islam von Umar auf die islamische Dawa<\/h4><h1>Umar ibn al-Khattabs \u00dcbertritt zum Islam hatte viele Auswirkungen; damals f\u00fchlten sich die Muslime stolz, stark und unbesiegbar, da keiner von ihnen in der \u00d6ffentlichkeit beten oder die Kaaba umrunden konnte, doch als Umar Muslim wurde, beteten die Gef\u00e4hrten und umrundeten die Kaaba und erhielten Gerechtigkeit von denen, die ihnen Unrecht getan hatten. Umar verk\u00fcndete den Polytheisten seinen Islam, und sie waren durch diese schwierige Nachricht niedergeschlagen, und er erz\u00e4hlte Abu Jahl ohne Furcht und Zittern von seinem Islam. Ibn Mas'ud bezog sich auf diese Bedeutung und sagte: \"Wir konnten nicht in der Kaaba beten, bis Umar Muslim wurde\", und so wurde der Aufruf zum Islam \u00f6ffentlich.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6353\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-6353\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Dr. Ingrid Mattsson<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6353\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-6353\"><h4><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34932 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Ingrid-Mattson12-187x300.jpg\" width=\"187\" height=\"300\" srcset=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Ingrid-Mattson12-187x300.jpg 187w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Ingrid-Mattson12-7x12.jpg 7w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Ingrid-Mattson12.jpg 370w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/>Einf\u00fchrung in das Thema<\/h4><div dir=\"rtl\"><h1>Dr. Ingrid Mattson ist Professorin f\u00fcr Religion am Hartford College in Connecticut. Sie ist in Ontario, Kanada, geboren und aufgewachsen und studierte Philosophie und \u00c4sthetik an der Universit\u00e4t von Waterloo.<\/h1><div dir=\"rtl\"><h1>Mattson konvertierte in ihrem letzten Studienjahr zum Islam, reiste 1987 nach Pakistan, arbeitete dort ein Jahr lang mit Fl\u00fcchtlingen und promovierte 1999 an der Universit\u00e4t von Chicago in Islamwissenschaften.<\/h1><h4>Ihre Geschichte \u00fcber den Islam<\/h4><div dir=\"rtl\"><h1>Dr. Ingrid wurde als Christin erzogen und war nicht religi\u00f6s, und ihre erste Begegnung mit dem Islam fand \u00fcber ihre Liebe zur Kunst statt. Dr. Ingrid erz\u00e4hlt von ihren Reisen zu gro\u00dfen Museen in Toronto, Montreal und Chicago, bis sie den Louvre in Paris besuchte und von der Kunst der Malerei in allen Phasen der Menschheitsgeschichte tief beeindruckt war.<\/h1><div dir=\"rtl\"><h1>Dann traf sie eine Gruppe von Muslimen, \u00fcber die sie sagt: \"Ich traf Menschen, die keine Statuen oder sinnlichen Bilder von ihrem Gott bauten, und als ich sie fragte, antworteten sie, dass der Islam sich sehr vor G\u00f6tzendienst und Menschenanbetung h\u00fctet und dass es sehr einfach ist, Gott zu erkennen, indem man seine Sch\u00f6pfungen betrachtet.\"<\/h1><div dir=\"rtl\"><h1>Ingrid begann ihre Reise, um mehr \u00fcber den Islam zu erfahren, die mit ihrer Konversion zum Islam endete, woraufhin sie sich auf eine Reise des Lernens begab und dann in die Missionsarbeit eintrat.<\/h1><h4>Ihre Beitr\u00e4ge<\/h4><h1 dir=\"rtl\">Ingrid Mattson hat das erste islamische Religionsprogramm in den Vereinigten Staaten von Amerika ins Leben gerufen. 2001 wurde sie zur Pr\u00e4sidentin der Islamischen Gesellschaft von Nordamerika gew\u00e4hlt, die in den Vereinigten Staaten und Kanada rund 20.000 Mitglieder und 350 Moscheen und islamische Zentren z\u00e4hlt; Mattson ist die erste Frau, die diese Position in der Geschichte der Gesellschaft einnimmt.<\/h1><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6354\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-6354\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Der franz\u00f6sische Chirurg Maurice Bucaille<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6354\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-6354\"><h4><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34936 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/An_exclusive_photo_of_Dr._Maurice_Bucaille_presented_to_Farouq_in_2008._Photo_Credit_-_Mrs._Bucailles_Archive-221x300.jpg\" width=\"221\" height=\"300\" srcset=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/An_exclusive_photo_of_Dr._Maurice_Bucaille_presented_to_Farouq_in_2008._Photo_Credit_-_Mrs._Bucailles_Archive-221x300.jpg 221w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/An_exclusive_photo_of_Dr._Maurice_Bucaille_presented_to_Farouq_in_2008._Photo_Credit_-_Mrs._Bucailles_Archive-755x1024.jpg 755w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/An_exclusive_photo_of_Dr._Maurice_Bucaille_presented_to_Farouq_in_2008._Photo_Credit_-_Mrs._Bucailles_Archive-768x1041.jpg 768w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/An_exclusive_photo_of_Dr._Maurice_Bucaille_presented_to_Farouq_in_2008._Photo_Credit_-_Mrs._Bucailles_Archive-9x12.jpg 9w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/An_exclusive_photo_of_Dr._Maurice_Bucaille_presented_to_Farouq_in_2008._Photo_Credit_-_Mrs._Bucailles_Archive.jpg 1124w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/>Wer ist Maurice Bucaille?<\/h4><h1>Als Sohn franz\u00f6sischer Eltern wurde Maurice Bucaille in der christlichen Religion erzogen und schrieb sich nach Abschluss der Sekundarschule f\u00fcr das Medizinstudium an der Universit\u00e4t von Frankreich ein. Er war einer der ersten, die einen medizinischen Abschluss erwarben, und seine Karriere stieg bis zum ber\u00fchmtesten und f\u00e4higsten Chirurgen des modernen Frankreichs, dessen chirurgisches K\u00f6nnen eine wundersame Geschichte war, die sein Leben umkrempelte und sein Wesen ver\u00e4nderte.<\/h1><h4>Die Geschichte des Islam von Maurice Bokay<\/h4><h1>Frankreich ist bekanntlich eines der L\u00e4nder mit dem gr\u00f6\u00dften Interesse an Arch\u00e4ologie und kulturellem Erbe. Als der verstorbene sozialistische franz\u00f6sische Pr\u00e4sident Fran\u00e7ois Mitterrand 1981 die Macht im Land \u00fcbernahm, bat Frankreich \u00c4gypten Ende der 1980er Jahre, die Mumie des \u00e4gyptischen Pharaos f\u00fcr arch\u00e4ologische Untersuchungen und Behandlungen nach Frankreich zu bringen.<\/h1><h1>Der Leichnam des ber\u00fchmtesten \u00e4gyptischen Tyrannen wurde zum Flughafen transportiert, wo der franz\u00f6sische Pr\u00e4sident, seine Minister und die h\u00f6chsten Beamten des Landes auf der Treppe des Flugzeugs Aufstellung nahmen, um dem Pharao von \u00c4gypten einen k\u00f6niglichen Empfang zu bereiten, als ob er noch am Leben w\u00e4re!<\/h1><h1>Als der k\u00f6nigliche Empfang des \u00e4gyptischen Pharaos in Frankreich zu Ende war, wurde die Mumie des Leviathan in einer Prozession getragen und in einen besonderen Fl\u00fcgel des franz\u00f6sischen Zentrums f\u00fcr Altert\u00fcmer gebracht. Danach begannen die gr\u00f6\u00dften Arch\u00e4ologen Frankreichs, Chirurgen und Anatomen, diese Mumie zu untersuchen und ihre Geheimnisse zu entdecken, und der Chefchirurg und erste Verantwortliche f\u00fcr die Untersuchung dieser pharaonischen Mumie war Professor Maurice Bucaille.<\/h1><h1>Die Heiler waren daran interessiert, die Mumie zu restaurieren, aber ihr Chef, Maurice Bokay, hatte ganz andere Interessen: Er wollte herausfinden, wie dieser Pharaonenk\u00f6nig gestorben war, und sp\u00e4t in der Nacht kamen die endg\u00fcltigen Ergebnisse seiner Analyse heraus.<\/h1><h1>Der franz\u00f6sische Chirurg Maurice Bucaille<br \/>Ein R\u00e4tsel ist f\u00fcr ihn jedoch nach wie vor, warum dieser K\u00f6rper - von allen mumifizierten Leichen der Pharaonen - besser erhalten blieb als die anderen, obwohl er aus dem Meer gegraben wurde.<\/h1><h1>Maurice Bucaille war gerade dabei, einen Abschlussbericht \u00fcber eine seiner Meinung nach neue Entdeckung vorzubereiten, n\u00e4mlich die Bergung des Leichnams des Pharaos aus dem Meer und seine Mumifizierung kurz nach dem Ertrinken, als ihm jemand ins Ohr fl\u00fcsterte: Nur keine Eile, die Moslems reden \u00fcber das Ertr\u00e4nken dieser Mumie.<\/h1><h1>Er verurteilte diese Nachricht jedoch aufs Sch\u00e4rfste und war \u00fcberrascht, da eine solche Entdeckung nur durch die Entwicklung der modernen Wissenschaft und durch moderne Computer mit \u00e4u\u00dferster Pr\u00e4zision m\u00f6glich ist: Ihr Koran, an den sie glauben, erz\u00e4hlt eine Geschichte \u00fcber sein Ertrinken und die Sicherheit seines K\u00f6rpers nach dem Ertrinken.<\/h1><h1>Er war fassungslos und wunderte sich: Wie kann das sein, und diese Mumie wurde erst 1898 entdeckt, d.h: Vor fast zweihundert Jahren, w\u00e4hrend ihr Koran schon vor mehr als eintausendvierhundert Jahren existierte!<br \/>Wie kann das wahr sein, wenn die gesamte Menschheit, nicht nur die Muslime, bis vor wenigen Jahrzehnten nichts davon wusste, dass die alten \u00c4gypter die K\u00f6rper ihrer Pharaonen mumifizierten?<\/h1><h1>Maurice Bucaille sa\u00df in dieser Nacht da und starrte auf den Leichnam des Pharaos und dachte dar\u00fcber nach, was ihm sein Freund gefl\u00fcstert hatte, dass der muslimische Koran vom \u00dcberleben dieses Leichnams nach dem Ertrinken spricht, w\u00e4hrend das christliche heilige Buch (das Matth\u00e4us- und Lukasevangelium) vom Ertrinken des Pharaos bei der Verfolgung von Moses spricht, ohne das Schicksal seines Leichnams zu erw\u00e4hnen.<\/h1><h1>Er dachte bei sich: K\u00f6nnte es sein, dass dieser mumifizierte Mann vor mir der Pharao von \u00c4gypten ist, der Mose verfolgt hat?<\/h1><h1>Ist es m\u00f6glich, dass Mohammed dies schon vor mehr als tausend Jahren wusste und ich es erst jetzt erfahre?<\/h1><h1>Maurice Bucay konnte nicht schlafen und bat darum, dass man ihm die Tora bringt, und so las er im Buch Exodus aus der Tora: \"Und das Wasser kehrte zur\u00fcck und bedeckte die Wagen und Reiter des ganzen Heeres des Pharao, die hinter ihnen her ins Meer fuhren, und nicht einer von ihnen blieb \u00fcbrig\" Maurice Bucaille war ratlos.<\/h1><h1>Selbst die Tora spricht nicht davon, dass dieser K\u00f6rper \u00fcberlebte und unversehrt blieb, nachdem der K\u00f6rper des Pharaos behandelt und wiederhergestellt worden war.<\/h1><h1>Frankreich schickte die Mumie in einem luxuri\u00f6sen Glassarg nach \u00c4gypten zur\u00fcck, doch Maurice Bucaille konnte sich nicht beruhigen, da er durch die von den Muslimen verbreiteten Nachrichten \u00fcber die Sicherheit dieses Leichnams ersch\u00fcttert war; er packte seine Koffer und beschloss, nach Saudi-Arabien zu reisen, um an einem medizinischen Kongress teilzunehmen, bei dem eine Gruppe muslimischer Anatomen anwesend sein w\u00fcrde.<\/h1><h1>Einer von ihnen stand auf, schlug den Koran auf und begann, ihm den folgenden Vers vorzulesen: {Heute \u00fcbergeben wir dich mit deinem K\u00f6rper, damit du ein Zeichen bist f\u00fcr die, die nach dir kommen, und dass viele Menschen unsere Zeichen nicht kennen [Yunus: 92].<\/h1><h1>Die Wirkung des Verses auf ihn war schwerwiegend, und er war so ersch\u00fcttert, dass er vor den Zuh\u00f6rern aufstand und lauthals rief: \"Ich bin zum Islam \u00fcbergetreten, und ich glaube an diesen Koran.\"<\/h1><h4>Maurice Bucaille's Beitr\u00e4ge<\/h4><h1>Maurice Bucaille kehrte auf eine andere Weise nach Frankreich zur\u00fcck, als er gegangen war, und dort blieb er zehn Jahre lang und hatte nichts anderes zu tun, als die \u00dcbereinstimmung neu entdeckter wissenschaftlicher Fakten mit dem Heiligen Koran zu studieren und nach einem einzigen wissenschaftlichen Widerspruch im Koran zu suchen, um zu dem Ergebnis der Worte des Allm\u00e4chtigen zu kommen: {Keine Falschheit kann zwischen seinen H\u00e4nden oder hinter ihm entstehen, eine Offenbarung von einem weisen und guten Richter} [Faslat: 42].<\/h1><h1>Die Frucht dieser Jahre, die der Franzose Maurice Bucaille verbrachte, war ein Buch \u00fcber den Heiligen Koran, das alle westlichen L\u00e4nder und ihre Gelehrten ersch\u00fctterte. Der Titel des Buches lautete: \"Der Koran, die Thora, die Bibel und die Wissenschaft. Eine Studie der Heiligen Schriften im Lichte des modernen Wissens\". Was hat dieses Buch bewirkt?<\/h1><h1>Bei seiner ersten Auflage war es in allen Buchhandlungen ausverkauft! Dann wurde es zu Hunderttausenden nachgedruckt, nachdem es aus der Originalsprache (Franz\u00f6sisch) ins Arabische, Englische, Indonesische, Persische, T\u00fcrkische und Deutsche \u00fcbersetzt worden war, und dann in allen Bibliotheken in Ost und West verbreitet, und Sie k\u00f6nnen es in den H\u00e4nden eines jeden \u00e4gyptischen, marokkanischen oder Golf-Jugendlichen in Amerika finden.<\/h1><h1>Die j\u00fcdischen und christlichen Gelehrten, deren Herzen und Augen von Gott verschlossen wurden, haben versucht, auf dieses Buch zu antworten, aber sie haben nichts als polemischen Unsinn und verzweifelte Versuche geschrieben, die von den Einfl\u00fcsterungen Satans diktiert wurden, der letzte von ihnen ist Dr. William Campbell in seinem Buch mit dem Titel \"Der Koran und die Bibel im Licht der Geschichte und der Wissenschaft\".<\/h1><h1>Was noch \u00fcberraschender ist, ist, dass einige Gelehrte im Westen begannen, eine Antwort auf das Buch vorzubereiten, und als er sich in die Lekt\u00fcre vertiefte und dar\u00fcber nachdachte, konvertierte er zum Islam und verk\u00fcndete \u00f6ffentlich die Schahadah in aller \u00d6ffentlichkeit!<\/h1><h4>Maurice Bucaille Zitate<\/h4><h1>Maurice Bucaille sagt in der Einleitung seines Buches: \"Diese wissenschaftlichen Aspekte des Korans haben mich zun\u00e4chst zutiefst erstaunt. Ich h\u00e4tte es nie f\u00fcr m\u00f6glich gehalten, in einem Text, der vor mehr als dreizehn Jahrhunderten geschrieben wurde, so viel Genauigkeit zu so vielen verschiedenen Themen und ihre vollst\u00e4ndige \u00dcbereinstimmung mit den modernen wissenschaftlichen Erkenntnissen zu entdecken.\"<\/h1><h1>Er sagt auch: \"Ich habe zuerst den Koran studiert, ohne vorgefasste Meinungen und mit v\u00f6lliger Objektivit\u00e4t, auf der Suche nach dem Grad der \u00dcbereinstimmung zwischen dem Text des Korans und den Daten der modernen Wissenschaft. Vor diesem Studium wusste ich durch \u00dcbersetzungen, dass im Koran viele Arten von Naturph\u00e4nomenen erw\u00e4hnt werden, aber mein Wissen war kurz.<\/h1><h1>Dank eines sorgf\u00e4ltigen Studiums des arabischen Textes war ich in der Lage, eine Liste zu erstellen, nach der ich feststellte, dass der Koran keine Aussage enth\u00e4lt, die aus der Sicht der modernen Wissenschaft kritisiert werden kann, und mit der gleichen Objektivit\u00e4t habe ich auch das Alte Testament und die Evangelien untersucht.<\/h1><h1>Was das Alte Testament anbelangt, so war es nicht n\u00f6tig, \u00fcber das erste Buch Genesis hinauszugehen, da es Aussagen enth\u00e4lt, die mit der etabliertesten Wissenschaft unserer Zeit nicht vereinbar sind.<\/h1><h1>Was die Evangelien betrifft, so stellen wir fest, dass der Text des Matth\u00e4us-Evangeliums eindeutig im Widerspruch zum Lukas-Evangelium steht, und dass letzteres ausdr\u00fccklich etwas darstellt, das mit den modernen Erkenntnissen \u00fcber das Alter des Menschen auf der Erde nicht vereinbar ist\".<\/h1><h1>Auch Dr. Maurice Bucaille stellt fest: \"Das erste, was in der Seele desjenigen, der den Texten des Korans zum ersten Mal begegnet, Erstaunen hervorruft, ist der Reichtum der behandelten wissenschaftlichen Themen, w\u00e4hrend wir in der Thora - heute - riesige wissenschaftliche Fehler finden, entdecken wir im Koran keinen einzigen Fehler, und wenn der Autor des Korans ein Mensch war, wie konnte er im siebten Jahrhundert Tatsachen schreiben, die nicht zu seiner Zeit geh\u00f6ren?\"<\/h1><h1>1988 verlieh ihm die Franz\u00f6sische Akademie ihren Preis f\u00fcr Geschichte f\u00fcr sein Buch Der Heilige Koran und die moderne Wissenschaft.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6355\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-6355\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Der amerikanische Wissenschaftler Jeffrey Lang<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6355\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-6355\"><h4><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34969 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/0-65-300x155.jpg\" width=\"300\" height=\"155\" \/>Einf\u00fchrung in das Thema<\/h4><h1>Der amerikanische Mathematiker Jeffrey Lang wurde 1954 in Bridgeport, Connecticut, geboren. Er promovierte an der Purdue University und ist derzeit Professor am Fachbereich Mathematik der University of Kansas.<\/h1><h4>Ablehnung des Christentums<\/h4><h1>In seinem Buch Der Kampf um den Glauben erz\u00e4hlt Jeffrey Lange von seiner dramatischen Erfahrung, die es wert ist, erz\u00e4hlt zu werden, damit sich die Menschen ein Bild von der Ausbreitung des Islam im Westen machen k\u00f6nnen und davon, wie sie geschieht.<br \/>Der Mann wuchs in einer christlichen Familie auf, und als der Religionsprofessor versuchte, die Existenz Gottes mit Hilfe der Mathematik zu beweisen, widersprach Jeffrey Lange, ein Sch\u00fcler der High School, dem Professor, der sich \u00fcber ihn \u00e4rgerte und ihn mit einer Verwarnung aus der Klasse warf.<br \/>Der junge Mann kehrte nach Hause zur\u00fcck, und als seine Eltern die Geschichte h\u00f6rten, waren sie schockiert und sagten: \"Du bist ein Atheist geworden, mein Sohn.<br \/>sagt Lang: \"Er verlor tats\u00e4chlich den Glauben an das westliche Christentum.\" Zehn Jahre lang blieb Lang in diesem Zustand des Atheismus, auf der Suche, aber was ihn am meisten st\u00f6rte, war die Unzufriedenheit der Menschen in Europa, trotz ihres luxuri\u00f6sen Lebens.<\/h1><h4>Seine Geschichte \u00fcber den Islam<\/h4><h1>Die \u00dcberraschung kam in Form eines Geschenks von einer saudischen Familie, und Lang beschreibt den Koran wie folgt:<br \/>\"Ich hatte das Gef\u00fchl, vor einem Psychologieprofessor zu stehen, der all meine verborgenen Gef\u00fchle durchleuchtet. Ich versuchte, \u00fcber bestimmte Themen zu sprechen, und stellte fest, dass er direkt vor mir stand, in meine Tiefen eintauchte und mich vor der Wahrheit nackt machte.\"<br \/>Er konvertierte 1980 zum Islam, nachdem er zuvor Atheist war.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6356\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-6356\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Shoji Futaki. Der japanische Arzt<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6356\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-6356\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-36222 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/IMG_20160623_171227-300x214.jpg\" width=\"300\" height=\"214\" \/>Der Islam von Shoji Fotaki ist ein Wendepunkt in der Geschichte Japans und der gesamten s\u00fcdostasiatischen Region. Was ist die Geschichte der Konversion des japanischen Arztes Shoji Fotaki? Der japanische Arzt<br \/>Votaki ist ein japanischer Arzt, der im Alter von siebenundsechzig Jahren zum Islam konvertierte, mit einer liebenswerten und charismatischen sozialen Pers\u00f6nlichkeit, die jeden beeinflusst, der mit ihm in Kontakt kommt. Seine Religion vor dem Islam war der Buddhismus, und er war der Direktor eines gro\u00dfen Krankenhauses im Herzen von Tokio (der Hauptstadt Japans), und dieses Krankenhaus war eine Aktiengesellschaft, die zehntausend Menschen geh\u00f6rte, und Dr. Votaki k\u00fcndigte seit seinem Islam an, dass er alles in seiner Macht stehende tun w\u00fcrde, um die zehntausend Aktion\u00e4re in den Scho\u00df des Islam zu bringen.<\/h1><h1>Neben seiner T\u00e4tigkeit als Krankenhausdirektor war Dr. Futaki 1954 Chefredakteur einer japanischen Monatszeitschrift namens Sekami Jeep. Er interessierte sich f\u00fcr das Thema des Atombombenabwurfs auf Japan und dessen Auswirkungen und versuchte, Gelder daf\u00fcr zu beschaffen. Als er damit scheiterte, zog er von zehn japanischen Unternehmen sechzig Millionen Yen ein, nachdem er gedroht hatte, geheime Nachrichten zu ver\u00f6ffentlichen, die deren Interessen ber\u00fchrten, und wurde nach langen Prozessen zu drei Jahren Gef\u00e4ngnis verurteilt und seine \u00e4rztliche Zulassung wurde entzogen.<\/h1><h4>Islam Geschichte<\/h4><h1>Er begann, verschiedene philosophische, politische und spirituelle B\u00fccher zu lesen. Der Gedanke des Monotheismus begann ihn zu besch\u00e4ftigen, und diese Idee schlug Wurzeln, als er mit einer Reihe von islamischen Pers\u00f6nlichkeiten Kontakt aufnahm, darunter ein Muslim namens Abu Bakr Mori Muto, ehemaliger Pr\u00e4sident der Japan Muslim Association, der ihm sagte: \"Je mehr Muslime es auf der Welt gibt, desto eher wird das Problem der Unterprivilegierten auf der Erde verschwinden, denn der Islam ist eine Religion der Liebe und der Br\u00fcderlichkeit.\"<\/h1><h1>Nachdem sie im Islam Orientierung gefunden hatten, beschlossen Futaki, sein Sohn und ein weiterer Freund, zum Islam zu konvertieren und erkl\u00e4rten ihren Glauben im Islamischen Zentrum in Tokio.<\/h1><h4>Beitr\u00e4ge<\/h4><h1>Der Islam von Shoji Futaki signalisierte die Islamisierung ganz Japans. Aber warum ist sein Islam eine gro\u00dfe Ver\u00e4nderung in Japan?<\/h1><h1>Nach seinem Eintritt in den Islam kam er im M\u00e4rz 1975 an der Spitze von achtundsechzig Personen in die Moschee von Tokio, um sich zum Islam zu bekennen, und er gr\u00fcndete die Vereinigung der islamischen Bruderschaft.<\/h1><h1>Au\u00dferdem erkl\u00e4rten sich am 4.4.1975 in der Moschee von Tokio zweihundert Japaner zum Islam, und so begann Dr. Shoji Futaki, seine japanischen Br\u00fcder in Scharen zum \u00dcbertritt in die Religion Gottes zu bewegen, bis die Zahl der Mitglieder der von ihm geleiteten Vereinigung der islamischen Bruderschaft aus diesen neuen Muslimen fast zwanzigtausend japanische Muslime erreichte, und das in weniger als einem Jahr.<\/h1><h1>Shoji Futakis Islam ist ein Wendepunkt in der Geschichte Japans, ja der gesamten s\u00fcdostasiatischen Region.<\/h1><h1>Es gibt jedoch ein Ph\u00e4nomen, das bei denjenigen auftritt, die die arabische Sprache nicht beherrschen und nicht in muslimischen L\u00e4ndern leben, n\u00e4mlich einige Verunreinigungen durch den Einfluss der Jahiliyyah; Dr. Shawki Futaki war mit den neuen Muslimen seiner islamischen Vereinigung in der Frage des Verbots von Schweinefleisch und Alkoholkonsum nachsichtig, vielleicht hat er eine Entschuldigung f\u00fcr seine Unwissenheit, und vielleicht wollte er sie allm\u00e4hlich erziehen. Deshalb sollten die islamischen L\u00e4nder, insbesondere die arabischen L\u00e4nder, Prediger in diese L\u00e4nder entsenden (2).<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6357\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-6357\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Douglas Archer<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6357\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-6357\"><h1>Die Geschichte von Dr. Douglas Archer, Direktor des Institute of Education in Jamaika Was ist die Geschichte von Dr. Douglas Archers \u00dcbertritt zum Islam? Der Islam ist eine einzigartige Religion<br \/>Douglas Archer, dessen islamischer Name Abdullah ist, war der Direktor des Bildungsinstituts in Jamaika. Bevor er zum Islam konvertierte, war er Protestant der Siebenten-Tags-Adventisten und arbeitete auch an der Universit\u00e4t von Illinois in Amerika.<\/h1><h4>Die Geschichte von Douglas Archer<\/h4><h1>Seine Geschichte mit dem Islam begann, als er an der Universit\u00e4t Vorlesungen \u00fcber Psychologie hielt, und es gab einige muslimische Studenten, die nicht gut Englisch sprachen, so dass er sich nach den Vorlesungen zu ihnen setzen musste, und durch diese Treffen wurde er neugierig auf ihren Glauben und ihre Prinzipien, und er war sehr beeindruckt von ihnen.<\/h1><h1>Eines der wichtigsten Dinge, die sein Interesse am Islam weckten, war sein Studium der Philosophie, in dem er einiges \u00fcber den Islam las.<\/h1><h1>Einer der Gr\u00fcnde, warum er den Islam n\u00e4her kennenlernte, war ein saudischer Student im Aufbaustudium, der in seiner N\u00e4he wohnte und mit ihm viel \u00fcber den Islam sprach, ihm viele islamische B\u00fccher gab und ihn mit zwei muslimischen Professoren an der Universit\u00e4t bekannt machte.<\/h1><h1>Was den entscheidenden Punkt betrifft, der ihn zum Islam gef\u00fchrt hat, sagte er:<br \/>\"Ein weiterer wichtiger Punkt ist, dass ich mich in meiner Doktorarbeit mit Bildung und dem Aufbau von Nationen befasst habe und dabei gelernt habe, was Nationen f\u00fcr ihren sozialen, wirtschaftlichen und politischen Aufbau sowie f\u00fcr ihren geistigen Aufbau brauchen. Ich entdeckte, dass die Grundpfeiler des Islam ein gro\u00dfartiges Fundament und eine wertvolle Basis f\u00fcr den sozialen, wirtschaftlichen und spirituellen Wiederaufbau einer Nation bieten: Warum bin ich zum Islam konvertiert? Weil der Islam eine einzigartige Religion ist, deren Grundpfeiler eine Richtschnur bilden, die sowohl das Gewissen als auch das Leben der Gl\u00e4ubigen leitet.\"<\/h1><h4>Douglas Archer's Beitr\u00e4ge<\/h4><h1>Douglas Archer verteidigte den Islam und sagte: Er ist in der Lage, die Probleme zu l\u00f6sen und die sozialen, spirituellen und politischen Bed\u00fcrfnisse derjenigen zu erf\u00fcllen, die unter Kapitalismus und Kommunismus leben; diese beiden Systeme haben es nicht geschafft, die Probleme der Menschen zu l\u00f6sen, w\u00e4hrend der Islam den Ungl\u00fccklichen Frieden und den Verwirrten und Verlorenen Hoffnung und F\u00fchrung bieten wird.<\/h1><h1>Dr. Douglas Archer, der den Vorsitz des Caribbean Educational Institute innehat, versucht ebenfalls, den Islam auf den Westindischen Inseln durch die wissenschaftlichen Programme des Instituts zu verbreiten, und hat Saudi-Arabien und Kuwait bereist, um sein islamisches Anliegen zu unterst\u00fctzen.<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><h1>\u00a0<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6358\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-6358\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">David Lively<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6358\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-6358\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36226 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/5476.jpg\" width=\"259\" height=\"194\" \/>Die Geschichte des Amerikaners David Lively, dessen Geist und Herz zwei der wichtigsten Lehren des Christentums nicht akzeptieren konnte: die Lehren der Dreifaltigkeit und der Erl\u00f6sung. Was ist die Geschichte von Davids Bekehrung?<br \/>David Lively wurde in Philadelphia, im Nordosten der Vereinigten Staaten, geboren und studierte Mathematik, bis er an der Lehigh University einen Abschluss in Informatik erwarb.<br \/>Er sagt von sich selbst: \"In meiner fr\u00fchen Jugend besuchte ich mit meiner Familie eine protestantische Kirche. Der Protestantismus ist die Lehre der Mehrheit des amerikanischen Volkes, und ich war schon fr\u00fch mit religi\u00f6sen Texten und \u00dcberzeugungen konfrontiert, aber ich merkte, dass mein Geist und mein Herz zwei grundlegende christliche \u00dcberzeugungen nicht akzeptierten, n\u00e4mlich:<br \/>- Die Triangulationslehre (die in jeder Form abgelehnt wird), weil sie der Vernunft widerspricht.<br \/>- Die Heilslehre, die Jesus Christus, Friede sei mit ihm, zugeschrieben wird, ist aufgrund ihrer religi\u00f6sen Widerspr\u00fcchlichkeit im Bereich der Ethik.<br \/>Damals machte ich mich eilig auf die Suche nach einem neuen Glauben, der mich vor Abweichung und Verlust sch\u00fctzen und das spirituelle Vakuum f\u00fcllen w\u00fcrde, unter dem die amerikanische und europ\u00e4ische Jugend leidet und \u00fcber das sie sich beklagt.<\/h1><h4>Die Geschichte von David Lively<\/h4><h1>David Lively sagte \u00fcber sich selbst:<br \/>\"Ich lernte einen amerikanischen Freund kennen, der vor mir zum Islam \u00fcbergetreten war, und er hatte eine englische \u00dcbersetzung des Heiligen Korans, die ich zu meinen religi\u00f6sen B\u00fcchern hinzuf\u00fcgte, und sobald ich anfing, sie zu lesen, wurde mein Herz von den Grunds\u00e4tzen, die der Islam beinhaltet, getr\u00f6stet, und dann wandte ich mich dem Islam zu und betete zu Allah mit diesen Bittgebeten: O Besitzer der Rechtleitung, wenn diese Religion, die Islam genannt wird, nicht deine wahre Religion ist, mit der du zufrieden bist, dann entferne mich von ihr und meinen Mitmuslimen, und wenn sie deine wahre Religion ist, dann bringe mich n\u00e4her zu ihr und erleuchte mich in ihr.<br \/>Es verging keine Woche, in der sich der Islam nicht in meinem Herzen festsetzte und in meinem Gewissen Wurzeln schlug, so dass mein Herz und mein Geist ruhig und meine Seele friedlich waren, und ich ruhte darin, dass der Islam wahrhaftig die Religion Gottes ist, und der Koran ist wahr, wenn er sagt: {Die Religion Gottes ist der Islam} [Al-Imran: 19].\"<\/h1><h4>David Livelys Beitr\u00e4ge<\/h4><h1>Dawud Abdullah al-Tawhidi (dies ist sein Name nach dem Islam) versuchte, die Muslime auf ihre Lage aufmerksam zu machen und sie aufzufordern, ihre Situation zu \u00e4ndern:<br \/>\"Wie gro\u00df ist der Unterschied zwischen dem Islam und den Werten, der Moral und der Ethik, die er beinhaltet, und dem Zustand der Unkenntnis der Muslime \u00fcber ihren Glauben, dem Verlust ihrer Werte und ihrer Abkehr von den Werten und der Ethik des Islam! Die muslimischen Herrscher haben sich nur z\u00f6gerlich f\u00fcr den Islam eingesetzt, obwohl dies ihre h\u00f6chste Aufgabe ist, und die islamischen Gelehrten haben ihre eigentliche Rolle in der da'wah, im ijtihad und in der Ableitung von Urteilen aufgegeben. Was von den islamischen Gelehrten verlangt wird, ist nicht nur die Bewahrung des Erbes, sondern auch die R\u00fcckkehr zur Umsetzung des islamischen Denkens, und dann wird das Licht der Prophetie, des Glaubens, der Anwendung und des Nutzens f\u00fcr andere zu ihnen zur\u00fcckkehren.<br \/>Es ist erstaunlich, dass sich viele junge Menschen in der muslimischen Welt von den spirituellen Werten des Islams und seinen Lehren entfernen, w\u00e4hrend sich die Jugend der westlichen Welt nach diesen Werten sehnt, sie aber in ihren s\u00e4kularen Gesellschaften, die nichts \u00fcber den Islam wissen, nicht findet.\"<br \/>Was den Wunsch dieses amerikanischen Muslims, Daoud al-Tawhidi, betrifft:<br \/>\"Mein Wunsch ist es, meine islamischen Studien fortzusetzen und mich auf dem Gebiet der vergleichenden Religionswissenschaft zu spezialisieren, damit ich an der Ausbildung k\u00fcnftiger Generationen von Muslimen in Amerika mitwirken, der dortigen intellektuellen Invasion entgegenwirken und den Islam unter Nicht-Muslimen verbreiten kann. Ich hoffe auch, dass der Tag kommen wird, an dem ich sehe, dass der Islam einen Einfluss auf die zuk\u00fcnftige Umgestaltung der amerikanischen Gesellschaft hat, und dass ich an der Renaissance des Islam in der ganzen Welt teilnehmen werde; denn der Islam kennt keine Nationalit\u00e4ten, sondern ist eine Rechtleitung, die der Welt gesandt wurde, und der Heilige Koran sagt \u00fcber den Gesandten des Islam: {Wir haben dich nur als Barmherzigkeit f\u00fcr die Welt gesandt} [Al-Anbiya: 107].<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-6359\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-6359\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Der ungarische Wissenschaftler Abdul Karim Germanius<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6359\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-6359\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34979 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Germanus_Gyula_1930s_Grayscale-221x300.jpg\" width=\"221\" height=\"300\" \/>Die Geschichte wird den Orientalisten (Golager Manius) als eine der ber\u00fchmten Personen in Erinnerung behalten, die im Staat Ungarn zum Islam konvertierten.<\/h1><h4>Einf\u00fchrung in das Thema<\/h4><h1>Gulager Manius wurde am 6. November 1884 geboren und gab sich nach seinem Islam einen islamischen Namen, Abdul Karim Germanius.<br \/>Abdulkarim Germanius war in der Lage, den Islam und die muhammedanische Botschaft inmitten seines Arbeitsbereichs zu predigen, wo er als Professor an der Laurentian University t\u00e4tig war. Abdulkarim Germanius wurde von einer gro\u00dfen Zahl von Menschen innerhalb und au\u00dferhalb der Universit\u00e4t verfolgt, und die Universit\u00e4t widmete ihm sogar einen Lehrstuhl f\u00fcr arabische und islamische Geschichte im Namen von Abdulkarim Germanius.<\/h1><h4>Seine Geschichte \u00fcber den Islam<\/h4><h1>Dr. Abdul Karim Germanius erz\u00e4hlt die Hintergr\u00fcnde seiner Konversion zum Islam: \"Es war an einem regnerischen Nachmittag, und ich war noch im Teenageralter, als ich durch die Seiten einer alten illustrierten Zeitschrift bl\u00e4tterte, in der sich aktuelle Ereignisse mit fiktiven Geschichten mischten, mit Beschreibungen einiger entfernter L\u00e4nder; ich hatte einige Zeit lang gleichg\u00fcltig durch die Seiten gebl\u00e4ttert, bis mein Blick pl\u00f6tzlich auf das Bild einer geschnitzten Holztafel fiel, die meine Aufmerksamkeit erregte, das Bild zeigte H\u00e4user mit flachen D\u00e4chern, die hier und da mit runden Kuppeln durchsetzt waren, die sich sanft in den dunklen Himmel erhoben, dessen Dunkelheit von der Mondsichel durchbrochen wurde.<br \/>Das Bild nahm meine Phantasie gefangen, und ich versp\u00fcrte eine unwiderstehliche Sehnsucht, dieses Licht kennenzulernen, das die Dunkelheit auf dem Gem\u00e4lde \u00fcberwand. Ich begann, T\u00fcrkisch, dann Persisch und schlie\u00dflich Arabisch zu studieren, und versuchte, diese drei Sprachen zu beherrschen, um in diese geistige Welt eintreten zu k\u00f6nnen, die dieses blendende Licht \u00fcber die gesamte Menschheit verbreitete.\"<br \/>In einem Sommerurlaub hatte ich das Gl\u00fcck, nach Bosnien zu reisen - das \u00f6stlichste Land, das meinem Land am n\u00e4chsten liegt -, und sobald ich in einem Hotel eingecheckt hatte, eilte ich hinaus, um Muslime in ihrem wirklichen Leben zu sehen, wo ich einen anderen Eindruck gewann als das, was \u00fcber Muslime gesagt wird, und dies war meine erste Begegnung mit Muslimen. Jahre und Jahre vergingen in einem Leben voller Reisen und Studien, und mit jedem Tag, der verging, \u00f6ffneten sich meine Augen f\u00fcr neue und wundersame Horizonte.<br \/>Trotz seiner ausgedehnten Reisen in Gottes Welt, seiner Freude an den arch\u00e4ologischen Wundern Kleinasiens und Syriens, dem Erlernen vieler Sprachen und der Lekt\u00fcre von Tausenden von Seiten gelehrter B\u00fccher las er all dies mit wachem Auge: \"Trotz alledem blieb meine Seele durstig.\"<br \/>Als er sich in Indien aufhielt, sah er eines Nachts - wie ein Schl\u00e4fer sieht -, dass Muhammad, der Gesandte Allahs, m\u00f6ge Allah ihn segnen und ihm Frieden gew\u00e4hren, ihn mit einer mitf\u00fchlenden Stimme ansprach: \"Warum bist du so verwirrt? Der gerade Weg, der vor dir liegt, ist so sicher und gepflastert wie die Oberfl\u00e4che der Erde. Geh mit festen Schritten und der Kraft des Glaubens.\" Am folgenden Freitag fand das gro\u00dfe Ereignis in der Juma Masjid in Delhi statt, als er sich vor Zeugen zum Islam bekannte.<br \/>Hajj Abdulkarim Jarmanous erinnerte sich an diese emotionalen Momente: \"Ich wei\u00df nicht mehr, was es damals war, aber die Leute standen vor mir und umarmten mich, und die armen, m\u00fcden Menschen sahen mich flehend an, baten um Gebete und wollten meinen Kopf k\u00fcssen. Ich betete zu Gott, er m\u00f6ge nicht zulassen, dass diese unschuldigen Seelen mich ansehen, als ob ich ihnen \u00fcberlegen w\u00e4re, denn ich bin nur ein Insekt unter den Insekten der Erde oder ein Wanderer auf der Suche nach Licht, hilflos wie andere ungl\u00fcckliche Gesch\u00f6pfe, und ich sch\u00e4mte mich vor dem Seufzen und Hoffen dieser guten Menschen. Am n\u00e4chsten und \u00fcbern\u00e4chsten Tag kamen die Menschen in Scharen, um mich zu begl\u00fcckw\u00fcnschen, und ich erhielt von ihnen so viel Liebe und Zuneigung, dass ich ein Leben lang davon zehren konnte.<\/h1><h4>Leidenschaft f\u00fcr das Erlernen von Sprachen<\/h4><h1>Abdulkarim Germanos lernte westliche Sprachen: Griechisch, Latein, Englisch, Franz\u00f6sisch, Franz\u00f6sisch, Italienisch, Ungarisch und \u00f6stliche Sprachen: Persisch und Urdu, und beherrschte Arabisch und T\u00fcrkisch unter seinen Professoren: Vampyre und Goldziher, von denen er seine Vorliebe f\u00fcr den islamischen Osten geerbt hat. Nach 1905 setzte er seine Studien an den Universit\u00e4ten von Istanbul und Wien fort: Istanbul und Wien. Er schrieb 1906 ein Buch auf Deutsch \u00fcber die osmanische Literatur und ein weiteres \u00fcber die Geschichte der t\u00fcrkischen Variet\u00e4ten im 17. Jahrhundert, wof\u00fcr er einen Preis erhielt, der ihm einen l\u00e4ngeren Aufenthalt in London erm\u00f6glichte, wo er seine Studien am British Museum abschloss.<br \/>1912 kehrte er nach Budapest zur\u00fcck und wurde Professor f\u00fcr arabische, t\u00fcrkische und persische Sprachen, Geschichte und Kultur des Islams am Orientalischen Gymnasium, dann an der \u00d6stlichen Abteilung der Wirtschaftsuniversit\u00e4t und schlie\u00dflich 1948 Professor und Leiter der arabischen Abteilung der Universit\u00e4t Budapest, wo er bis zu seiner Pensionierung 1965 weiterhin arabische Sprache, Geschichte der islamischen Zivilisation sowie alte und moderne arabische Literatur unterrichtete und versuchte, Verbindungen zwischen der sozialen und psychologischen Wiederbelebung der islamischen Nationen herzustellen.<br \/>Der indische Dichter (Tagore) lud ihn nach Indien ein, um als Professor f\u00fcr islamische Geschichte zu arbeiten, und so lehrte er an den Universit\u00e4ten von: (1929-1932 n. Chr.), wo er sich in der Gro\u00dfen Moschee von Delhi zum Islam bekannte, die Freitagspredigt hielt und den Namen Abdul Karim annahm. Er kam nach Kairo und studierte den Islam bei den Scheichs von Al-Azhar, ging dann als Pilger nach Mekka, besuchte die Moschee des Propheten (Friede sei mit ihm) und schrieb sein Buch \u00fcber seine Pilgerreise: Allahu Akbar, das 1940 in mehreren Sprachen ver\u00f6ffentlicht wurde, und f\u00fchrte wissenschaftliche Untersuchungen (1939-1941) in Kairo und Saudi-Arabien durch, deren Ergebnisse er in zwei B\u00e4nden ver\u00f6ffentlichte: Shawamekh al-Adab al-Arabi, 1952, und Studies in Arabic Linguistic Structures, 1954.<br \/>Im Fr\u00fchjahr 1955 kehrte er zur\u00fcck und verbrachte auf Einladung der Regierung einige Monate in Kairo, Alexandria und Damaskus, um in arabischer Sprache Vortr\u00e4ge \u00fcber zeitgen\u00f6ssisches arabisches Denken zu halten.<\/h1><h4>Seine Beitr\u00e4ge<\/h4><h1>Dr. Abdulkarim Jarmanous hat ein reiches wissenschaftliches Erbe hinterlassen, das sich durch Tiefe und Vielfalt auszeichnet: Die Grammatik der t\u00fcrkischen Sprache (1925), Die t\u00fcrkische Revolution und der arabische Nationalismus (1928), Moderne t\u00fcrkische Literatur (1931), Moderne Str\u00f6mungen im Islam (1932), Die Entdeckung und Eroberung der arabischen Halbinsel, Syriens und des Irak (1940), Die Renaissance der arabischen Kultur (1944) und Studien \u00fcber die Strukturen der arabischen Sprache (1954). (1944), Studies in Arabic Linguistic Structures (1954), Ibn al-Rumi (1956), Among the Thinkers (1958), Towards the Lights of the East, Selected Arab Poets (1961), Islamic Culture, Literature of the Maghreb (1964), und er bereitet drei B\u00fccher vor \u00fcber: Literatur der Hidschra, arabische Reisende und Ibn Battuta sowie die Geschichte der arabischen Literatur.<br \/>Dieser ungarische Professor trug mit seinen in der arabischen Welt bekannten Studien dazu bei, den islamischen Ruf zu verbreiten und gemeinsam mit dem \u00e4gyptischen Scheich Abu Yusuf eine ber\u00fchmte islamische Bibliothek zu gr\u00fcnden. Die ungarische Regierung k\u00fcmmerte sich um diese Bibliothek, die bis heute von ihr unterst\u00fctzt wird, um das islamische Erbe und die Geschichte zu bewahren und die Muslime dort zu f\u00f6rdern.<br \/>Nach den aufregenden Abenteuern, die er auf seinem Weg \u00fcber das Meer nach \u00c4gypten erlebte, hatte er 1939 die Gelegenheit, eine Reise in die W\u00fcste zu unternehmen, besuchte den Libanon und Syrien und unternahm dann seine zweite Pilgerreise. In der Einleitung der 1973 erschienenen Ausgabe von Gott ist gro\u00df schrieb er Folgendes: \"Ich habe die Halbinsel, Mekka und Medina dreimal besucht und meine Erlebnisse w\u00e4hrend meiner ersten Reise in meinem Buch (Allahu Akbar!) ver\u00f6ffentlicht. In den Jahren 1939-1940, nach Ausbruch des Zweiten Weltkriegs, machte ich mich auf den Weg \u00fcber die Donau, um als Seemann das Meer zu erreichen, ohne mich um die Gefahren und die M\u00fcdigkeit zu k\u00fcmmern. Ich erreichte \u00c4gypten und segelte von dort auf die Halbinsel. Ich verbrachte mehrere Monate in Medina, wo ich die mit dem Leben des Propheten (Friede sei mit ihm) verbundenen Orte besuchte: Die Ruinen der Qiblatain-Moschee, den Baqi'a-Friedhof und die Schaupl\u00e4tze der Schlachten von Badr und Uhud. Ich war zu Gast in der von Muhammad Ali gegr\u00fcndeten \u00e4gyptischen Moschee in der Stadt. Abends besuchten mich muslimische Gelehrte, um \u00fcber die Lage des Islam in der Welt zu sprechen. Wie ich in meinem Buch erkl\u00e4re, sp\u00fcrte ich bei ihnen den Geist des Islam, der trotz aller weltlichen Ver\u00e4nderungen in der Welt so stark und tief ist wie eh und je, so wie ich es in meiner Jugendzeit im muslimischen Osten erlebt hatte.\" Sein Traum, mit den Karawanen von Hejaz nach Riad zu reisen, ging 1939 in Erf\u00fcllung, und er erreichte Riad nach vier schwierigen Wochen, deren Einzelheiten er 1957 in seinem ber\u00fchmten Buch (Under the Faint Light of the Crescent Moon) verewigte.<br \/>In seinem anschlie\u00dfenden Buch Towards the Lights of the East (1966) schildert er seine Erfahrungen w\u00e4hrend seiner Reisen zwischen 1955 und 1965. Auf Einladung von Premierminister Abdul Karim Qasim besuchte er 1962 Bagdad, um an den Feierlichkeiten anl\u00e4sslich des 1200. Jahrestages der Gr\u00fcndung Bagdads teilzunehmen. Anschlie\u00dfend wurde er Mitglied des irakischen Wissenschaftsrates und hielt bei der Einweihungsfeier einen Vortrag mit dem Titel: Die Geschichte des Islam in Ungarn: Die Geschichte des Islams in Ungarn. 1964 lud ihn die \u00e4gyptische Regierung ein, an den Feierlichkeiten zum tausendj\u00e4hrigen Bestehen der Al-Azhar teilzunehmen, und 1965 lud ihn K\u00f6nig Faisal bin Saud zur Teilnahme an der Islamischen Konferenz in Mekka ein, wo er im Alter von einundachtzig Jahren zum dritten Mal die Hadsch absolvierte.<br \/>Er schrieb \u00fcber die Geschichte und Literatur der osmanischen T\u00fcrken, untersuchte die zeitgen\u00f6ssischen Entwicklungen der T\u00fcrkischen Republik, erforschte den Islam und die zeitgen\u00f6ssischen islamischen intellektuellen Str\u00f6mungen sowie die arabische Literatur. 1962 ver\u00f6ffentlichte er ein wichtiges Buch mit dem Titel (Geschichte der arabischen Literatur) und davor (Arabische Dichter von der Jahiliyya bis zur Gegenwart), er schrieb \u00fcber arabische Reisende und Geographen (Arabische Geographen, London 1954), und er hat viele Studien \u00fcber Indien. Er schrieb seine B\u00fccher und Forschungen neben Ungarisch auch in anderen Sprachen, wie z.B.: Englisch, Franz\u00f6sisch, Italienisch und Deutsch. Vielleicht war sein einfacher und fesselnder Stil der Grund f\u00fcr die Verbreitung seiner B\u00fccher; so spielte Germanos eine Vorreiterrolle bei der Einf\u00fchrung in die arabische Kultur, die arabische Literatur, den Islam und die Zivilisation des Ostens im Allgemeinen, und nachfolgende Generationen von Ungarn lernten seine Werke kennen und lieben.<\/h1><h4>Sein Tod<\/h4><h1>Abdulkarim Germanus starb am 7. November 1979 im Alter von 96 Jahren und wurde nach islamischem Ritus auf einem Friedhof in Budapest beigesetzt. Das Ungarische Geografische Museum in der Stadt Erd bewahrt das gesamte Archiv dieses ungarischen muslimischen Reisenden und Orientalisten auf.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63510\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-63510\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Emile Brice-Davin. Welt der Zivilisationen und Arch\u00e4ologie<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63510\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-63510\"><h1>Emile presse Daphn\u00e9 war einer der einflussreichsten franz\u00f6sischen Zeitgenossen, die sich mit \u00c4gypten besch\u00e4ftigten, zumal er eine herausragende und vielseitige Pers\u00f6nlichkeit war, die sich nicht auf die Entdeckung der pharaonischen Altert\u00fcmer beschr\u00e4nkte, sondern dar\u00fcber hinaus die islamische Zivilisation erforschte. Die K\u00fchnheit seiner Entdeckungen und die Unerschrockenheit seiner Abenteuer zeugen von seiner Einsicht, seiner scharfen Beobachtungsgabe, seinem umfassenden Wissen und seinem Streben nach Wahrheit.<\/h1><h1>Er bereicherte die Arch\u00e4ologie mit \u00e4u\u00dferst wichtigen Werken, denen er viele Jahre ununterbrochener Arbeit widmete, wobei er neben seinen \u00c4mtern auch ein gro\u00dfes Verm\u00f6gen opferte, das er geerbt hatte, bis er neben Artikeln und Studien vierzehn B\u00fccher vorlegen konnte, von denen sein Buch (\u00c4gyptische Altert\u00fcmer und die Geschichte der \u00e4gyptischen Kunst von den Anf\u00e4ngen der Geschichte bis zur r\u00f6mischen Herrschaft) und seine gro\u00dfe Enzyklop\u00e4die (Arabische Kunst aus der Arch\u00e4ologie \u00c4gyptens vom siebten bis zum Ende des achtzehnten Jahrhunderts) die bedeutendsten sind.<\/h1><h1>Die Leistungen von Emile Davin sind anerkennenswerte Werke, und sein Name sollte neben denen von Champollion, Mariette und Maspero im Ged\u00e4chtnis der Kunstgeschichtsinteressierten bleiben.<\/h1><h1>1829 trat Brice Davin als Bauingenieur in den Dienst von Ibrahim Pascha, dann als Professor f\u00fcr Topographie an der Arkan-Harb-Schule in der Khanqah und als Erzieher der Kinder des Paschas. Aufgrund seiner Arroganz, seines Stolzes und seiner Ablehnung von verwerflichem Verhalten wurde er jedoch oft gereizt und r\u00fccksichtslos gegen\u00fcber seinen Vorgesetzten, bis hin zu t\u00e4tlichen Angriffen, was deren Zorn auf sich zog, bis der Vorfall schlie\u00dflich den Zorn des Gouverneurs gegen ihn hervorrief.<\/h1><h1>Der Ingenieur wurde bald Orientalist und \u00c4gyptologe, lernte Arabisch, seine Dialekte und Intonation und entzifferte Hieroglyphen. 1837 k\u00fcndigte er seine Stelle, da er seine Freiheit als Reisender, Entdecker und Arch\u00e4ologe vorzog.<\/h1><h4>Die Geschichte des Islam von Emile Brice-Davin<\/h4><h1>Emile Brice-Davin hat den Islam sorgf\u00e4ltig studiert, beginnend mit dem Koran, dem Leben des Propheten des Islam und seinem Ruf, und wie die Araber nur rivalisierende St\u00e4mme waren, die sich gegenseitig bek\u00e4mpften, und der Prophet es schaffte, sie zu einer vereinten Nation zu machen, die die beiden gr\u00f6\u00dften Reiche der Welt besiegte: Das Persische Reich und das Byzantinische Reich, und ihre Unterwerfung unter die muslimische Herrschaft.<\/h1><h1>Er erz\u00e4hlt, warum er Muslim geworden ist:<br \/>Er wies darauf hin, dass sich das islamische Recht durch Gerechtigkeit, Wahrheit, Toleranz und Vergebung auszeichnet, zur vollen menschlichen Br\u00fcderlichkeit aufruft, alle Tugenden bef\u00fcrwortet und alle Laster verbietet und dass die islamische Zivilisation eine humanit\u00e4re Zivilisation ist, die in der antiken Welt \u00fcber Jahrhunderte hinweg vorherrschte.<\/h1><h1>So konvertierte er zum Islam, nahm den Namen Idris Davin an, kleidete sich als Bauer und machte sich auf, um seine Mission in Ober\u00e4gypten und im Delta zu erf\u00fcllen.<\/h1><h4>Beitr\u00e4ge von Emile Brice-Davin<\/h4><h1>Die Araber verdanken Bryce Davin auf dem Gebiet der islamischen Arch\u00e4ologie viel mehr als auf dem Gebiet der pharaonischen Arch\u00e4ologie.<\/h1><h1>Dem Zivilisations- und Arch\u00e4ologieforscher Idris Davin ist es gelungen, die pharaonische und die islamische Zivilisation aus ihrem Dornr\u00f6schenschlaf zu erwecken und uns die lebendige und zug\u00e4ngliche arabische humanistische Kunst wiederzugeben, die der Islam diesem franz\u00f6sisch-muslimischen Orientalisten verdankt.<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63511\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-63511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Christopher Chamont<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-63511\"><h1>Er ist einer der ber\u00fchmtesten Wirtschaftswissenschaftler der Welt, konvertierte zum Islam und \u00e4nderte seinen Namen von Christopher Hamont in Ahmed.<\/h1><h1>Aber warum ist der ber\u00fchmte Wirtschaftswissenschaftler zum Islam konvertiert? Das werden wir durch seine Geschichte des Islam herausfinden.<\/h1><h4>Die Geschichte von Christopher Chamont<\/h4><h1>Er fand seinen Weg zum Islam, verstand sein Wesen und seine Gr\u00f6\u00dfe und fand, was er \u00fcber den Prozess der Triangulierung suchte, als er im Heiligen Koran las, dass Jesus (Friede sei mit ihm) ein Gesandter Gottes ist, dass er ein Mensch ist und dass es nur einen Gott gibt, der der Anbetung und des Gehorsams w\u00fcrdig ist.<\/h1><h1>Christopher Chamont begann, mehr \u00fcber den Islam zu lernen, indem er den ins Englische \u00fcbersetzten Koran und einige \u00fcbersetzte B\u00fccher \u00fcber den Islam las, da er in Saudi-Arabien arbeitete und dies ihm die M\u00f6glichkeit gab, mit Muslimen verschiedener Nationalit\u00e4ten in Kontakt zu kommen:<\/h1><h1>\"Meine Interaktionen und Diskussionen mit Muslimen verschiedener Nationalit\u00e4ten hatten einen gro\u00dfen Einfluss auf mein Wissen \u00fcber den Islam, da ich den Wunsch versp\u00fcrte, mehr \u00fcber die Philosophie des Islam zu erfahren.\"<\/h1><h1>So lernte Christopher Chamont den Islam kennen, und so fand er die Wahrheit, die er suchte, und blieb trotz seines Ruhms als einer der renommiertesten Wirtschaftswissenschaftler der Welt dabei.<\/h1><h4>Die Beitr\u00e4ge von Christopher Chamont<\/h4><h1>Christopher Chamont rief die Muslime dazu auf, sich an die Lehren ihrer Religion zu halten, da dies der Grund f\u00fcr ihren Erfolg sei:<\/h1><h1>\"Die Lehren des Islam sind gro\u00dfartig, und wenn die Muslime sich daran halten w\u00fcrden, w\u00fcrden sie die h\u00f6chsten Stufen des Fortschritts, der Macht und der Zivilisation erreichen, aber die Muslime sind nach innen gerichtet, was dazu gef\u00fchrt hat, dass andere sie \u00fcberholt haben, obwohl die fr\u00fchen Muslime die ersten waren, die den Weg der Zivilisation und des wissenschaftlichen, sozialen und wirtschaftlichen Fortschritts gegangen sind.\"<\/h1><h1>Christopher Chamont hat gezeigt, dass die Lehren des Islams der Weg zu Fortschritt und Aufstieg sind, dass der Mangel an Befolgung dieser Lehren der Grund f\u00fcr die R\u00fcckst\u00e4ndigkeit der Muslime ist und dass die R\u00fcckkehr der Muslime zu ihrem Gottesdienst der Schl\u00fcssel zu ihrem Fortschritt und Erfolg ist.<\/h1><h1>Ahmed Chamont sprach auch \u00fcber den Islam und sagte:<br \/>\"Der Islam ist die Religion, die den Geist des Menschen anspricht und seine Hand an den Anfang des Weges stellt, um Gl\u00fcck im Diesseits und im Jenseits zu erreichen. Ich habe im Islam gefunden, wonach ich gesucht habe, und jedes Problem, mit dem der Mensch konfrontiert ist, kann seine L\u00f6sung im Heiligen Koran finden.\"<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63512\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-63512\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Der Orientalist Hussein Ruf. Religion und Soziologie<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63512\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-63512\"><h1>Der 1916 als Sohn christlicher und j\u00fcdischer Eltern in England geborene englische Orientalist und Soziologe studierte zun\u00e4chst den Glauben seiner christlichen und j\u00fcdischen Eltern, dann den Hinduismus und seine Philosophie, insbesondere seine modernen Lehren, sowie die buddhistische Lehre, die er mit einigen altgriechischen Lehren verglich, und schlie\u00dflich einige moderne soziale Theorien und Lehren, insbesondere die Ideen des gro\u00dfen russischen Wissenschaftlers und Philosophen Leo Tolstoi.<\/h1><h4>Der Orientalist Hussein Rufs Geschichte des Islam<\/h4><h1>Herr Rufs Interesse am Islam und sein Studium des Islams kamen im Vergleich zu anderen Religionen und Glaubensrichtungen sp\u00e4t, trotz seines Aufenthalts in einigen arabischen L\u00e4ndern; seine erste Ber\u00fchrung mit dem Islam erfolgte durch die Lekt\u00fcre einer \u00dcbersetzung des Heiligen Korans von Rodwell, die ihn jedoch nicht beeinflusste, da es sich nicht um eine ehrliche und wahrheitsgetreue \u00dcbersetzung handelte, wie viele \u00e4hnliche, durch Unwissenheit oder feindliche Absichten verdorbene \u00dcbersetzungen, die in mehreren Fremdsprachen ver\u00f6ffentlicht wurden.<\/h1><h1>Doch zum Gl\u00fcck f\u00fcr ihn Er lernte einen gebildeten und aufrichtigen Verfechter des Islam kennen, der mit Leidenschaft dabei ist und es sich zur Aufgabe gemacht hat, den Menschen den Islam n\u00e4her zu bringen. Er machte ihn mit einigen Fakten des Islams bekannt und f\u00fchrte ihn zu einer der \u00fcbersetzten Versionen der Bedeutungen des Heiligen Korans, die von einem muslimischen Gelehrten \u00fcbersetzt wurden, und f\u00fcgte eine klare und \u00fcberzeugende Erkl\u00e4rung hinzu, die auf Logik und Vernunft beruht und die wahren Bedeutungen verdeutlicht, die die englische Sprache nicht wiedergeben kann. Er f\u00fchrte ihn auch zu einigen anderen islamischen B\u00fcchern, die sich durch Aufrichtigkeit und klare Beweise auszeichnen. All dies erm\u00f6glichte es ihm, sich eine erste Vorstellung von der Wahrheit des Islam zu machen, was seinen Wunsch weckte, sein Wissen \u00fcber den Islam und seine Grunds\u00e4tze und Ziele durch unvoreingenommene wissenschaftliche Quellen zu erweitern.<\/h1><h1>Seine Kontakte mit einigen islamischen Gruppen und seine eingehende Untersuchung ihrer Verh\u00e4ltnisse best\u00e4tigten das Ausma\u00df des Einflusses des Islams auf ihr Verhalten und ihre Verb\u00e4nde; dies best\u00e4tigte seine anf\u00e4ngliche Vorstellung von der Gr\u00f6\u00dfe des Islams, und er glaubte voll und ganz an ihn.<\/h1><h1>Warum ist dieser englische Orientalist Muslim geworden?<\/h1><h1>Er beschreibt seine Erfahrungen mit dem \u00dcbertritt zum Islam:<br \/>\"Eines Tages im Jahr 1945 wurde ich von einigen Freunden eingeladen, den Eidgebeten beizuwohnen und nach den Gebeten zu essen, was f\u00fcr mich eine gute Gelegenheit war, diese internationale Menge von Muslimen aus der N\u00e4he zu sehen, ohne nationalen oder rassischen Fanatismus... Dort traf ich einen t\u00fcrkischen Prinzen und neben ihm viele mittellose Menschen, die sich alle zum Essen setzten, und man sieht in den Gesichtern der Reichen keine k\u00fcnstliche Demut oder eine falsche Vort\u00e4uschung von Gleichheit, wie der Wei\u00dfe schaut, wenn er mit seinem schwarzen Nachbarn spricht, noch sieht man unter ihnen diejenigen, die sich aus der Versammlung zur\u00fcckziehen oder an eine Seite oder in eine abgelegene Ecke gehen, noch sieht man unter ihnen jenes l\u00e4cherliche Klassengef\u00fchl, das sich hinter falschen Vorh\u00e4ngen der Tugend verstecken kann.\"<\/h1><h1>\"Es gen\u00fcgt mir, wenn ich sage, dass ich \u00fcber alles nachgedacht und kontempliert habe: Nachdem ich alle anderen bekannten Religionen der Welt studiert hatte, fand ich mich spontan zum Glauben an diese Religion gef\u00fchrt, ohne dass ich mich zu ihr hingezogen f\u00fchlte und ohne von einer von ihnen \u00fcberzeugt zu sein.\"<\/h1><h1>Anschlie\u00dfend lobte er die Moral, Toleranz und Gro\u00dfz\u00fcgigkeit der Muslime und wies darauf hin, dass der Islam in der Lage sei, das Problem der sozialen Ungleichheit und der Klassenkonflikte zu l\u00f6sen:<\/h1><h1>\"Ich habe viele L\u00e4nder auf der ganzen Welt bereist, im Osten wie im Westen, und ich hatte die Gelegenheit zu sehen, wie der Fremde an jedem Ort empfangen wird, und zu wissen, dass die Ehrung des Fremden das erste ist, was einem in den Sinn kommt, und dass die erste Sitte darin besteht, sich nach ihm zu erkundigen und nach dem Interesse oder dem Nutzen zu fragen, der sich aus seiner Hilfe ergeben k\u00f6nnte... Ich habe keine Nicht-Muslime gefunden, die es ihnen gleichtun, wenn es darum geht, den Fremden zu empfangen, ihn willkommen zu hei\u00dfen, zu ehren und ihm Freundlichkeit zu erweisen, ohne eine Gegenleistung zu erwarten oder ohne einen Nutzen zu erwarten... In wirtschaftlicher Hinsicht stellen wir fest, dass nur islamische Gruppen die Unterschiede zwischen den Reichen und den Armen auf eine Weise beseitigt haben, die die Armen nicht dazu bringt, die Struktur der Gesellschaft umzust\u00fcrzen und Chaos und Hass zu sch\u00fcren.\"<\/h1><h4>Beitr\u00e4ge des Orientalisten Hussein Ruf<\/h4><h1>Der englische muslimische Orientalist Hussein Ruf war einer der bedeutendsten europ\u00e4ischen Sozialforscher, der sich eingehend mit Religionen und sozialen Lehren besch\u00e4ftigte. Er war beeindruckt von der Gr\u00f6\u00dfe des Islam, der Erhabenheit seiner Ziele und Prinzipien, seiner \u00fcberlegenen F\u00e4higkeit, die Probleme und Schwierigkeiten zu l\u00f6sen, unter denen Individuen und menschliche Gesellschaften leiden, und seiner wundersamen Eignung f\u00fcr verschiedene Umgebungen und Zivilisationen, ungeachtet ihrer Unterschiede und Disparit\u00e4ten.<\/h1><h1>Nach seinem Eintritt in den Islam war es f\u00fcr ihn selbstverst\u00e4ndlich, die Initiative zu ergreifen, um diese Religion, die sein Herz, seinen Verstand und seine Gef\u00fchle besa\u00df, zu predigen, seine Landsleute \u00fcber ihre toleranten Grunds\u00e4tze und erhabenen Ziele aufzukl\u00e4ren und gleichzeitig die Flut von L\u00fcgen zu widerlegen und das Geb\u00e4ude der Illusionen und Unwahrheiten zu zerst\u00f6ren, das die Gegner des Islams ihm anh\u00e4ngen.<\/h1><h1>Gott ist wahr, wenn Er sagt: {Wer hat eine bessere Rede als jemand, der zu Gott ruft, gute Taten vollbringt und sagt, dass ich zu den Muslimen geh\u00f6re} [Faslat: 33].<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63513\" class=\"elementor-tab-title\" data-tab=\"13\" role=\"button\" aria-controls=\"elementor-tab-content-63513\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Dr. Hamid Markus Deutscher Wissenschaftler und Journalist<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63513\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"13\" role=\"region\" aria-labelledby=\"elementor-tab-title-63513\"><h1>Die Geschichte von Dr. Hamed Markus, dem deutschen Wissenschaftler, der vom Koran fasziniert war Dr. Hamed Markus ist ein deutscher Wissenschaftler und Journalist, der nach seiner Konversion vom Stil des Korans und seinen Aussagen \u00fcber den Islam fasziniert war. Deutscher Wissenschaftler und Journalist<br \/>Von Kindheit an versp\u00fcrte ich in mir den Drang, den Islam so gut wie m\u00f6glich zu studieren, und ich sorgte daf\u00fcr, dass ich in der Bibliothek der Stadt, in der ich aufwuchs, eine \u00fcbersetzte Version des Korans las, aus der Goethe seine Informationen \u00fcber den Islam bezog.<\/h1><h1>Ich war beeindruckt von der wunderbaren intellektuellen Herangehensweise des Korans bei der Durchsetzung der islamischen Lehren, und ich war auch beeindruckt von dem gro\u00dfen Geist der Beharrlichkeit, den diese Lehren in den Herzen der fr\u00fchen Muslime weckten.<\/h1><h1>In Berlin hatte ich die Gelegenheit, mit Muslimen zu arbeiten und die enthusiastischen und spannenden Vortr\u00e4ge des Gr\u00fcnders des ersten islamischen Vereins in Berlin und des Gr\u00fcnders der Berliner Moschee \u00fcber den Heiligen Koran zu genie\u00dfen. Nach Jahren der praktischen Zusammenarbeit mit dieser herausragenden Pers\u00f6nlichkeit sah ich in ihm seine Selbstlosigkeit und seinen Geist, und ich glaubte an den Islam, da ich in seinen erhabenen Grunds\u00e4tzen, die als H\u00f6hepunkt in der Geschichte des menschlichen Denkens gelten, das sah, was meine pers\u00f6nlichen Ansichten erg\u00e4nzte.<\/h1><h1>Der Glaube an Gott ist eine grundlegende Lehre in der islamischen Religion, aber er verlangt keine Prinzipien oder Lehren, die mit der modernen Wissenschaft unvereinbar sind, so dass es keinen Widerspruch zwischen dem Glauben einerseits und der Wissenschaft andererseits gibt, und das ist zweifellos eine gro\u00dfe und einzigartige Eigenschaft in den Augen eines Mannes, der seine ganze Energie in die wissenschaftliche Forschung eingebracht hat.<\/h1><h1>Die islamische Religion ist nicht nur eine ohrenbet\u00e4ubende theoretische Lehre, die blind am Rande des Lebens verl\u00e4uft, sondern sie fordert ein angewandtes System, das das menschliche Leben f\u00e4rbt. Die Gesetze des Islams sind keine obligatorischen Lehren, die pers\u00f6nliche Freiheiten einsperren, sondern Richtlinien und Leitlinien, die zu einer organisierten individuellen Freiheit f\u00fchren.<\/h1><h1>Im Laufe der Jahre wurde ich immer mehr davon \u00fcberzeugt, dass der Islam der beste Weg ist, die Pers\u00f6nlichkeit des Einzelnen und die Pers\u00f6nlichkeit der Gruppe in Einklang zu bringen und sie durch ein starkes und solides Band miteinander zu verbinden.<\/h1><h1>Sie ist eine Religion der Rechtschaffenheit und der Toleranz, sie ruft stets zum Guten auf, ermahnt es und f\u00f6rdert es unter allen Umst\u00e4nden und bei allen Gelegenheiten.<\/h1><h5>Quelle: Buch (Die Reise des Glaubens mit M\u00e4nnern und Frauen, die Muslime wurden) von: Abdul Rahman Mahmoud.<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63514\" class=\"elementor-tab-title\" data-tab=\"14\" role=\"button\" aria-controls=\"elementor-tab-content-63514\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Die Geschichte der 3 ber\u00fchmtesten britischen Konvertiten zum Islam in der viktorianischen \u00c4ra<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63514\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"14\" role=\"region\" aria-labelledby=\"elementor-tab-title-63514\"><h1 class=\"selectionShareable\" dir=\"RTL\">Auf dem H\u00f6hepunkt des Zeitalters des Empire entschieden sich Briten, das Christentum zu verlassen und zum Islam zu konvertieren. Hier sind die Geschichten von drei dieser Pioniere, die die Normen der viktorianischen \u00c4ra herausforderten, zu einer Zeit, als das Christentum ein Eckpfeiler der britischen Identit\u00e4t war, wie die British Broadcasting Corporation (BBC) berichtet.<\/h1><h1 class=\"imgcontainer\"><img decoding=\"async\" title=\"William Henry Quilliam\" src=\"https:\/\/img.youm7.com\/ArticleImgs\/2019\/5\/21\/24912-%D9%88%D9%84%D9%8A%D8%A7%D9%85-%D9%87%D9%86%D8%B1%D9%8A-%D9%83%D9%88%D9%8A%D9%84%D9%8A%D8%A7%D9%85.jpg\" alt=\"William Henry Quilliam\" \/><span class=\"uplCaption\">William Henry Quilliam<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h4>Abdullah Quilliam<\/h4><h1 class=\"selectionShareable\" dir=\"RTL\">Das Interesse des Anwalts William Henry Quilliam am Islam begann, als er 1887 w\u00e4hrend einer Mittelmeerreise Marokkaner auf einer F\u00e4hre beten sah.<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Quilliam sagte: \"Sie lie\u00dfen sich von den starken Winden und dem Schaukeln des Schiffes \u00fcberhaupt nicht st\u00f6ren. Ich war tief bewegt, als ich ihre Gesichter und ihre Mimik sah, die v\u00f6lligen Glauben und Aufrichtigkeit zeigten.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Nachdem er sich w\u00e4hrend seiner Zeit in Tanger \u00fcber die Religion informiert hatte, konvertierte der damals 31-j\u00e4hrige Quilliam zum Islam und beschrieb seinen neuen Glauben als \"vern\u00fcnftig und logisch\", und er hatte das Gef\u00fchl, dass er auf pers\u00f6nlicher Ebene nicht im Widerspruch zu seinem Glauben stand.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Obwohl der Islam von Konvertiten nicht verlangt, ihren Namen zu \u00e4ndern, w\u00e4hlte Quilliam f\u00fcr sich den Namen \"Abdullah\".<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Nach seiner R\u00fcckkehr nach England im Jahr 1887 wurde er zum religi\u00f6sen Propagandisten, und es hei\u00dft, dass dank seiner Bem\u00fchungen etwa 600 Menschen in ganz Gro\u00dfbritannien zum Islam konvertierten.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"imgcontainer\"><img decoding=\"async\" title=\"1894 verlieh der osmanische Sultan Quilliam mit Zustimmung von K\u00f6nigin Victoria den Titel eines Scheichs des Islam auf den britischen Inseln.\" src=\"https:\/\/img.youm7.com\/ArticleImgs\/2019\/5\/21\/82664-%D8%A3%D9%86%D8%B9%D9%85-%D8%A7%D9%84%D8%B3%D9%84%D8%B7%D8%A7%D9%86-%D8%A7%D9%84%D8%B9%D8%AB%D9%85%D8%A7%D9%86%D9%8A-%D8%B9%D9%84%D9%89-%D9%83%D9%88%D9%8A%D9%84%D9%8A%D8%A7%D9%85-%D9%81%D9%8A-%D8%B9%D8%A7%D9%85-1894-%D9%84%D9%82%D8%A8-%D8%B4%D9%8A%D8%AE-%D8%A7%D9%84%D8%A5%D8%B3%D9%84%D8%A7%D9%85-%D9%81%D9%8A-%D8%A7%D9%84%D8%AC%D8%B2%D8%B1-%D8%A7%D9%84%D8%A8%D8%B1%D9%8A%D8%B7%D8%A7%D9%86%D9%8A%D8%A9-%D8%A8%D9%85%D9%88%D8%A7%D9%81%D9%82%D8%A9-%D9%85%D9%86-%D8%A7%D9%84%D9%85%D9%84%D9%83%D8%A9-%D9%81%D9%8A%D9%83%D8%AA%D9%88%D8%B1%D9%8A%D8%A7.jpg\" alt=\"1894 verlieh der osmanische Sultan Quilliam mit Zustimmung von K\u00f6nigin Victoria den Titel eines Scheichs des Islam auf den britischen Inseln.\" \/><span class=\"uplCaption\">1894 verlieh der osmanische Sultan Quilliam mit Zustimmung von K\u00f6nigin Victoria den Titel eines Scheichs des Islam auf den britischen Inseln.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Im selben Jahr gr\u00fcndete Quilliam auch die erste Moschee des Landes in Liverpool, das damals von vielen als die \"zweite Stadt des britischen Empire\" angesehen wurde.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">K\u00f6nigin Victoria, deren Land von mehr Muslimen regiert wurde als das Osmanische Reich, forderte unter anderem eine von Quilliam verfasste Brosch\u00fcre mit dem Titel \"The Religion of Islam\" an, in der er die Religion des Islam zusammenfasste. Die Brosch\u00fcre wurde in 13 Sprachen \u00fcbersetzt<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Berichten zufolge bestellte sie sechs weitere Exemplare f\u00fcr ihre Familie, doch ihr Wunsch nach mehr Wissen stie\u00df auf Ablehnung in der breiten \u00d6ffentlichkeit, die den Islam f\u00fcr eine Religion der Gewalt hielt.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">1894 verlieh der osmanische Sultan Quilliam mit Zustimmung von K\u00f6nigin Victoria den Titel \"Sheikh of Islam in the British Isles\" (Scheich des Islam auf den Britischen Inseln), ein Titel, der seine F\u00fchrungsrolle in der muslimischen Gemeinschaft widerspiegelte.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Viele Einwohner Liverpools, die zum Islam konvertiert sind, wurden wegen ihres Glaubens angefeindet und misshandelt, unter anderem mit Ziegelsteinen, M\u00fcll und D\u00fcnger, obwohl die Religion offiziell anerkannt ist.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Quilliam glaubte, dass die Angreifer eine \"Gehirnw\u00e4sche erhalten hatten, die sie glauben lie\u00df, wir seien b\u00f6se\".<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Bekannt f\u00fcr seine Arbeit mit benachteiligten Gruppen, sein Engagement f\u00fcr Gewerkschaften und die Reform des Scheidungsrechts, nahm Quilliams juristische Karriere eine negative Wendung, als er versuchte, einem Mandanten zu helfen, der sich scheiden lassen wollte<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"imgcontainer\"><img decoding=\"async\" title=\"Quilliam war am Bau der zweit\u00e4ltesten Moschee Gro\u00dfbritanniens in Woking beteiligt\" src=\"https:\/\/img.youm7.com\/ArticleImgs\/2019\/5\/21\/50472-%D8%B4%D8%A7%D8%B1%D9%83-%D9%83%D9%88%D9%8A%D9%84%D9%8A%D8%A7%D9%85-%D9%81%D9%8A-%D8%A5%D9%86%D8%B4%D8%A7%D8%A1-%D8%AB%D8%A7%D9%86%D9%8A-%D8%A3%D9%82%D8%AF%D9%85-%D9%85%D8%B3%D8%AC%D8%AF-%D8%A8%D8%B1%D9%8A%D8%B7%D8%A7%D9%86%D9%8A-%D9%81%D9%8A-%D8%A8%D9%84%D8%AF%D8%A9-%D9%88%D9%88%D9%83%D9%8A%D9%86%D8%BA.jpg\" alt=\"Quilliam war am Bau der zweit\u00e4ltesten Moschee Gro\u00dfbritanniens in Woking beteiligt\" \/><span class=\"uplCaption\">Quilliam war am Bau der zweit\u00e4ltesten Moschee Gro\u00dfbritanniens in Woking beteiligt<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Dem Ehemann wurde eine Falle gestellt, da er angeblich Ehebruch begangen hatte, was zu dieser Zeit \u00fcblich war, aber der Versuch war erfolglos und Quilliam wurde von seinem Posten suspendiert<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Er verlie\u00df Liverpool 1908, um die Auswirkungen des Skandals auf die Muslime in der Stadt so gering wie m\u00f6glich zu halten, und tauchte im S\u00fcden als Henri de Leon wieder auf, obwohl ihn viele kannten, so Ron Davies, der eine Biografie \u00fcber Quilliam geschrieben hat<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Obwohl sein Einfluss schwand, war er am Bau der zweit\u00e4ltesten Moschee des Landes in Woking beteiligt und wurde 1932 in Surrey beigesetzt.<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Die Liverpooler Moschee tr\u00e4gt immer noch seinen Namen<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"imgcontainer\"><img decoding=\"async\" title=\"Lady Evelyn\" src=\"https:\/\/img.youm7.com\/ArticleImgs\/2019\/5\/21\/27579-%D9%84%D9%8A%D8%AF%D9%8A-%D8%A5%D9%8A%D9%81%D9%8A%D9%84%D9%8A%D9%86.jpg\" alt=\"Lady Evelyn\" \/><span class=\"uplCaption\">Lady Evelyn<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h4>Die H\u00e4nde von Evelyn Cobbold<\/h4><h1 class=\"selectionShareable\" dir=\"RTL\">Es war keine \u00dcberraschung, dass ein Mitglied der Oberschicht vom Islam fasziniert war und sich von Reisen in muslimische L\u00e4nder inspirieren lie\u00df<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Lady Evelyn Murray wurde in einer aristokratischen Familie in Edinburgh geboren und verbrachte einen Gro\u00dfteil ihrer Kindheit zwischen Schottland und Nordafrika.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Sie schrieb: \"Ich habe dort Arabisch gelernt, ich war gl\u00fccklich, meinem Kinderm\u00e4dchen zu entkommen und mit algerischen Freunden Moscheen zu besuchen, ich war im Herzen eine unfreiwillige Muslimin<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Auf dem Anwesen ihrer Familie in Dunmore Park jagte Evelyn Rehe und angelte Lachse.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Ihr Vater, der 7. Earl of Dunmore, war ein begeisterter Entdecker und reiste unter anderem nach China und Kanada. Ihre Mutter, die sp\u00e4ter die Hofdame von K\u00f6nigin Victoria wurde, war ebenfalls eine begeisterte Reisende<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"imgcontainer\"><img decoding=\"async\" title=\"Lady Evelyn ist die erste britische Frau, die die Hadsch vollzieht\" src=\"https:\/\/img.youm7.com\/ArticleImgs\/2019\/5\/21\/66865-%D8%AA%D8%B9%D8%AF-%D9%84%D9%8A%D8%AF%D9%8A-%D8%A5%D9%8A%D9%81%D9%8A%D9%84%D9%8A%D9%86-%D8%A3%D9%88%D9%84-%D8%B3%D9%8A%D8%AF%D8%A9-%D8%A8%D8%B1%D9%8A%D8%B7%D8%A7%D9%86%D9%8A%D8%A7-%D8%AA%D8%A4%D8%AF%D9%8A-%D8%B4%D8%B9%D8%A7%D8%A6%D8%B1-%D8%A7%D9%84%D8%AD%D8%AC.jpg\" alt=\"Lady Evelyn ist die erste britische Frau, die die Hadsch vollzieht\" \/><span class=\"uplCaption\">Lady Evelyn ist die erste britische Frau, die die Hadsch vollzieht<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Lady Evelyn hatte von ihren Eltern die Liebe zum Reisen geerbt und lernte ihren Mann, den Gesch\u00e4ftsmann John Cobbold, in Kairo, \u00c4gypten, kennen.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Es ist nicht bekannt, wann Lady Evelyn zum Islam konvertiert ist. M\u00f6glicherweise wurde der Samen auf Reisen in der Kindheit gepflanzt, aber Lady Evelyns Glaube scheint nach einem Urlaub in Rom und einem Treffen mit dem Papst gefestigt worden zu sein<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Danach schrieb sie: \"Als Seine Heiligkeit mich pl\u00f6tzlich ansprach und mich fragte, ob ich Katholikin sei, war ich einen Moment lang \u00fcberrascht und antwortete dann: 'Ich bin Muslimin, und ich wei\u00df nicht, was in mich gefahren ist, denn ich hatte jahrelang nicht mehr \u00fcber den Islam nachgedacht. Die Reise begann und ich war entschlossen, Religion zu lesen und zu studieren.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Der Historiker William Vasey, der das Vorwort zu Lady Evelyns Tagebuch schrieb, sagte, dass der spirituelle Aspekt der Religion viele Konvertiten anzog.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"imgcontainer\"><img decoding=\"async\" title=\"Lady Evelyn, ihr Ehemann John Cobbold und ihre Tochter\" src=\"https:\/\/img.youm7.com\/ArticleImgs\/2019\/5\/21\/42857-%D8%B5%D9%88%D8%B1%D8%A9-%D8%AA%D8%AC%D9%85%D8%B9-%D9%84%D9%8A%D8%AF%D9%8A-%D8%A5%D9%8A%D9%81%D9%8A%D9%84%D9%8A%D9%86-%D9%88%D8%B2%D9%88%D8%AC%D9%87%D8%A7-%D8%AC%D9%88%D9%86-%D9%83%D9%88%D8%A8%D9%88%D9%84%D8%AF-%D9%88%D8%B7%D9%81%D9%84%D8%AA%D9%87%D8%A7.jpg\" alt=\"Lady Evelyn, ihr Ehemann John Cobbold und ihre Tochter\" \/><span class=\"uplCaption\">Lady Evelyn, ihr Ehemann John Cobbold und ihre Tochter<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Er f\u00fcgte hinzu, dass sie \"dem Glauben folgen, dass alle gro\u00dfen Religionen eine transzendente Einheit teilen. Weg von den oberfl\u00e4chlichen lehrm\u00e4\u00dfigen Details, die sie trennen<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Lady Evelyns arabische Freunde im Nahen Osten nannten sie \"Lady Zainab\", sie hatte Zugang zu Frauenbereichen und schrieb \u00fcber den \"dominierenden Einfluss der Frauen\" in der islamischen Kultur<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Im Alter von 65 Jahren absolvierte sie die Hadsch und war die erste britische Frau, die die gesamte Pilgerfahrt absolvierte.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Dies verschaffte ihr \"unendliches Interesse und Bewunderung\", und ihre Geschichte wurde sp\u00e4ter in einem Buch mit dem Titel Pilgerfahrt nach Mekka ver\u00f6ffentlicht.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00dcber ihr Leben nach ihrer kurzen Reise nach Kenia ist wenig bekannt. Sie starb 1963 im Alter von 95 Jahren in einem Pflegeheim in Inverness. In ihrem Testament hatte sie verf\u00fcgt, dass bei ihrer Beerdigung Dudels\u00e4cke gespielt werden sollten und dass auf ihrem Grabstein ein Koranvers, \"Das Zeichen des Lichts\", eingraviert werden sollte<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Sie schrieb in ihr Tagebuch: \"Ich habe mich immer gefragt, wann und warum ich Muslima geworden bin.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Sie f\u00fcgte hinzu: \"Meine Antwort ist, dass ich den genauen Zeitpunkt nicht kenne, an dem mir die Wahrheit des Islam klar wurde.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\"Es scheint, dass ich schon immer ein Muslim war.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"imgcontainer\"><img decoding=\"async\" title=\"Robert Stanley konvertierte im Alter von 70 Jahren zum Islam\" src=\"https:\/\/img.youm7.com\/ArticleImgs\/2019\/5\/21\/37447-%D8%B1%D9%88%D8%A8%D8%B1%D8%AA-%D8%B3%D8%AA%D8%A7%D9%86%D9%84%D9%8A-%D8%AA%D8%AD%D9%88%D9%84-%D8%A7%D9%84%D9%89-%D8%A7%D9%84%D8%A7%D8%B3%D9%84%D8%A7%D9%85-%D9%81%D9%8A-%D8%A7%D9%84%D8%B3%D8%A8%D8%B9%D9%8A%D9%86-%D9%85%D9%86-%D8%B9%D9%85%D8%B1%D9%87.jpg\" alt=\"Robert Stanley konvertierte im Alter von 70 Jahren zum Islam\" \/><span class=\"uplCaption\">Robert Stanley konvertierte im Alter von 70 Jahren zum Islam<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h4>Robert Stanley<\/h4><h1 class=\"selectionShareable\" dir=\"RTL\">Geschichten \u00fcber die muslimische Geschichte im viktorianischen Zeitalter werden in der Regel von den Angeh\u00f6rigen der oberen Gesellschaftsschichten dominiert, deren Geschichten besser erhalten sind<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Doch Christina Longden, die herausfand, dass ihr Gro\u00dfvater Muslim war, nachdem ihr Vater den Stammbaum der Familie erforscht und schriftliche Dokumente und ein Tagebuch aufbewahrt hatte, sagte: \"Im Allgemeinen gibt es Anzeichen daf\u00fcr, dass es sich um eine Sache der Mittelschicht handelt: \"Im Allgemeinen gibt es Anzeichen daf\u00fcr, dass es sich um eine Sache der Mittelschicht handelt.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Robert Stanley stieg von einem Lebensmittelh\u00e4ndler der Arbeiterklasse zum konservativen B\u00fcrgermeister von Stalybridge, einer Stadt in der N\u00e4he von Manchester, in den 1870er Jahren auf.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Longden, der ein Buch \u00fcber ihn geschrieben hat, sagt, Stanley sei auch Richter gewesen und habe einen Fonds f\u00fcr Arbeiter eingerichtet, die entlassen wurden, weil sie nicht mit ihren Chefs abgestimmt hatten.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Ich fand auch heraus, dass er im Newsletter der Quilliam-Moschee in Liverpool regelm\u00e4\u00dfig \u00fcber den britischen Kolonialismus schrieb<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Ende der 1890er Jahre, nachdem er sich aus der Politik zur\u00fcckgezogen hatte, lernte er Stanley Quilliam kennen, und die beiden schlossen eine enge Freundschaft.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Longden sagt: \"Robert war 28 Jahre \u00e4lter als Quilliam, daher denke ich, dass es eine Art Vater-Sohn-Beziehung zwischen ihnen gab.<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Er konvertierte jedoch erst im Alter von 70 Jahren zum Islam und w\u00e4hlte f\u00fcr sich den Namen \"Rashid\".<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Nach ihren Recherchen glaubt Longden, dass es zu dieser Zeit \"keine anderen Muslime\" in Stourbridge gab. Stanley zog dann nach Manchester, wo er 1911 starb.<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Seine Konvertierung zum Islam wurde geheim gehalten, bis sie 1998 von der Familie Longden entdeckt wurde.<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Zuf\u00e4lligerweise konvertierte Longdens Bruder Stephen 1991 zum Islam, nachdem er im Rahmen seines Studiums in \u00c4gypten studiert hatte, sieben Jahre bevor Gro\u00dfvater Stanleys Islam entdeckt wurde.<span dir=\"LTR\">.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">Als er von der Bekehrung seines Gro\u00dfvaters erfuhr, bezeichnete er sie als eine \"unglaubliche \u00dcberraschung\".<span dir=\"LTR\">&#8220;.<\/span><\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\u00a0<\/h1><h1 class=\"selectionShareable\" dir=\"RTL\">\"Die Tatsache, dass es einen Mann gibt, der sich entschieden hat, Muslim zu sein, und das zu einer Zeit, in der man sich nicht vorstellen kann, dass jemand so etwas Unkonventionelles tut, wenn man sich hinsetzt und dar\u00fcber nachdenkt, ja, das ist Manchester\", sagte er und f\u00fcgte hinzu: \"Die Menschen haben keine Angst, aufzustehen und f\u00fcr das einzutreten, woran sie glauben, egal ob es sich um politische oder religi\u00f6se Dinge handelt.<span dir=\"LTR\">&#8220;.<\/span><\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63515\" class=\"elementor-tab-title\" data-tab=\"15\" role=\"button\" aria-controls=\"elementor-tab-content-63515\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Malcolm X, der Mann, der im Stehen starb<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63515\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"15\" role=\"region\" aria-labelledby=\"elementor-tab-title-63515\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-36230 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/87667986-225x300.jpg\" width=\"225\" height=\"300\" \/><br \/>Diese bedeutende Pers\u00f6nlichkeit hat sich - nach Allah - um die Verbreitung der islamischen Religion unter den schwarzen Amerikanern verdient gemacht, und zwar zu einer Zeit, als die Schwarzen in Amerika schwer unter der Rassendiskriminierung zwischen ihnen und den Wei\u00dfen litten, Erniedrigungen und Dem\u00fctigungen ausgesetzt waren und von ihnen gequ\u00e4lt und gehasst wurden.<br \/>In diesem turbulenten Klima der Unterdr\u00fcckung und Erniedrigung wurde Malcolm X als Sohn eines Kirchenpastors und einer Mutter aus Westindien geboren. Als er sechs Jahre alt war, wurde sein Vater von den Wei\u00dfen get\u00f6tet, nachdem sie ihm den Kopf eingeschlagen und ihn in die Spur eines elektrischen Busses gebracht hatten, der ihn \u00fcberfuhr, bis er starb. Die Familie von Malcolm X begann sich schnell zu verschlechtern. Finanziell und seelisch. Sie lebten von Almosen und sozialer Unterst\u00fctzung durch die Wei\u00dfen, die sie nur widerwillig gew\u00e4hren wollten. Unter diesen harten Bedingungen erlitt die Mutter von Malcolm X ein psychologisches Trauma, das sich so weit entwickelte, dass sie in eine psychiatrische Klinik eingewiesen wurde, wo sie den Rest ihres Lebens verbrachte. Malcolm X und seine acht Schwestern litten unter der Bitterkeit, sowohl Vater als auch Mutter verloren zu haben, und wurden als Kinder unter die Obhut des Staates gestellt, der sie auf verschiedene Heime verteilte...<\/h1><h1>In der Zwischenzeit besuchte Malcolm X eine nahe gelegene Schule, wo er der einzige schwarze Sch\u00fcler war. Er war klug und intelligent und \u00fcbertraf alle seine Mitsch\u00fcler, so dass seine Lehrer Angst vor ihm hatten, was sie dazu veranlasste, ihn psychologisch und moralisch zu zerst\u00f6ren und ihn l\u00e4cherlich zu machen, vor allem, als er sein Studium im Bereich der Rechtswissenschaften fortsetzen wollte... Dies war der Wendepunkt in seinem Leben. Er brach die Schule ab und wechselte zwischen verschiedenen entw\u00fcrdigenden Jobs, die einem Neger angemessen waren. Vom Kellner in einem Restaurant einem Bahnarbeiter bis hin zu einem Schuhputzer in einer Diskothek. Bis er ein bekannter T\u00e4nzer wurde, wurde er von einem Leben des Leichtsinns und des Verlusts verf\u00fchrt und begann, Alkohol zu trinken und Zigaretten zu rauchen, und fand das Gl\u00fccksspiel als Hauptquelle f\u00fcr seine Ersparnisse. Bis er schlie\u00dflich Drogen nahm und sogar damit handelte und schlie\u00dflich H\u00e4user und Autos stahl. All das, als er noch nicht einundzwanzig Jahre alt war. Bis er und seine Kumpels von der Polizei erwischt wurden. Sie verurteilten ihn zu einer \u00fcberzogenen Strafe von zehn Jahren Gef\u00e4ngnis, w\u00e4hrend f\u00fcr Wei\u00dfe eine Gef\u00e4ngnisstrafe von nicht mehr als f\u00fcnf Jahren vorgesehen war.<\/h1><h1>Im Gef\u00e4ngnis verzichtete Malcolm X auf das Rauchen und den Verzehr von Schweinefleisch und verschlang Tausende von B\u00fcchern aus verschiedenen Wissensgebieten, wodurch er sich eine hohe Kultur aneignete, die es ihm erm\u00f6glichte, die Defizite in seiner Pers\u00f6nlichkeit auszugleichen.<\/h1><h1>W\u00e4hrend dieser Zeit wurden alle Br\u00fcder von Malcolm X von einem Mann namens Mohammed Elijah zum Islam bekehrt. Alle Br\u00fcder von Malcolm X wurden von einem Mann namens Mohammed Elijah zum Islam bekehrt, der behauptete, ein Prophet Gottes zu sein, der nur zu den Schwarzen gesandt wurde. Sie versuchten, Malcolm X mit verschiedenen Mitteln zum \u00dcbertritt zum Islam zu bewegen, bis er Muslim wurde. Seine Moral und sein Charakter verbesserten sich, und er begann, an Reden und Debatten innerhalb des Gef\u00e4ngnisses teilzunehmen, um den Islam zu predigen. Bis er begnadigt und entlassen wurde, damit er im Gef\u00e4ngnis nicht weiter den Islam predigen konnte.<\/h1><h1>Malcolm X geh\u00f6rte der Bewegung Nation of Islam an, die falsche Vorstellungen und rassistische Grundlagen hatte, die mit dem Islam unvereinbar waren, obwohl sie den Islam als gl\u00e4nzenden Slogan benutzten.<\/h1><h1>Malcolm X setzte seine Arbeit in den Reihen der Nation of Islam fort, indem er mit seinen wortgewandten Reden und seiner starken Pers\u00f6nlichkeit die Menschen zum Beitritt einlud. Er war ein unerm\u00fcdlicher Helfer und ein unerm\u00fcdlicher Arm der Kraft, der St\u00e4rke und der Aggression ... bis es ihm gelang, viele Menschen f\u00fcr diese Bewegung zu gewinnen.<\/h1><h1>Malcolm X wollte die Hadsch vollziehen, und auf seiner Reise sah er den wahren Islam aus n\u00e4chster N\u00e4he und erkannte den Irrtum der rassistischen Doktrin, die er vertrat und f\u00fcr die er eintrat. Er nahm die wahre islamische Religion an und nannte sich Hajj Malik Shabazz.<\/h1><h1>Nach seiner R\u00fcckkehr widmete er sich der Verk\u00fcndigung des wahren Islam und versuchte, die fehlgeleiteten Konzepte der Nation of Islam zu korrigieren. Allerdings wurde er von ihnen angefeindet und gehasst, und sie begannen, ihn zu bel\u00e4stigen und zu bedrohen, aber das war ihm egal, und er fuhr fort, in klaren und festen Fu\u00dfstapfen zu gehen und den wahren Islam zu fordern, der alle Formen des Rassismus beseitigt.<\/h1><h1>In einer seiner wortgewaltigen Predigten, in denen er den Ruf zu Gott verk\u00fcndete, weigerten sich die Tyrannen, die Stimme der Wahrheit zum Schweigen zu bringen. Sie ermordeten ihn, w\u00e4hrend er auf dem Podium stand und zum Volk predigte, als sechzehn verr\u00e4terische Kugeln auf seinen langen, schlanken K\u00f6rper abgefeuert wurden. Und das war das Ende. Wir beten, dass Allah ihn in seiner letzten Ruhest\u00e4tte annimmt. Wir bitten Gott, ihn am Tag des J\u00fcngsten Gerichts unter die M\u00e4rtyrer aufzunehmen.<br \/>.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63516\" class=\"elementor-tab-title\" data-tab=\"16\" role=\"button\" aria-controls=\"elementor-tab-content-63516\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Muhammad Ali Lehm<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63516\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"16\" role=\"region\" aria-labelledby=\"elementor-tab-title-63516\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-35081 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/4015_700x-209x300.webp\" width=\"209\" height=\"300\" \/>Muhammad Ali Clay, geboren als Cassius Marcellus Marcellus Clay Jr. am 17. Januar 1942, ist ein ehemaliger amerikanischer Profiboxer, der trotz seiner Kritik als kulturelle Ikone und beliebte Pers\u00f6nlichkeit gilt.<\/h1><h4>Sein Islam<\/h4><h1>Er \u00e4nderte seinen Namen, unter dem er als \"Cassius\" bekannt war, in \"Muhammad Ali\", nur ohne den Spitznamen \"Clay\", der auf Englisch \"Schlamm\" bedeutet, nachdem er 1964 zum Islam konvertierte und sich nicht darum k\u00fcmmerte, was in Bezug auf die Beeintr\u00e4chtigung seiner Popularit\u00e4t geschehen w\u00fcrde, die zunahm und die Liebe der Menschen zu ihm \u00fcber den Horizont hinausging, und die islamische Religion war ein wichtiger Grund f\u00fcr seinen Erfolg. 1966 \u00fcberraschte er die Welt erneut, als Muhammad Ali seine Weigerung bekannt gab, der US-Armee im Vietnamkrieg beizutreten und sagte: Die islamische Religion verbietet Kriege, die nicht um Allahs und Seines Gesandten willen und um das Banner des Islam hochzuhalten, wie er erkl\u00e4rte: \"Ich werde nicht gegen sie k\u00e4mpfen ... weil sie mich nicht Nigger genannt haben ...Es war ihm egal, dass seine Popularit\u00e4t bei den Amerikanern mit dieser Aussage sank, und er wurde verhaftet und wegen Wehrdienstverweigerung verurteilt, ihm wurde sein Box-Titel aberkannt, seine Lizenz wurde ausgesetzt, und er k\u00e4mpfte vier Jahre lang nicht, nachdem er beim Obersten Gerichtshof der Vereinigten Staaten von Amerika Berufung gegen seine Verurteilung eingelegt und diesen Fall schlie\u00dflich gewonnen hatte, um wieder in den Boxring zur\u00fcckzukehren.<\/h1><h4>Boxen<\/h4><h1>Er gewann dreimal den Weltmeistertitel im Schwergewicht und Ali nahm an mehreren historischen K\u00e4mpfen teil, von denen vielleicht die drei bekanntesten waren, der erste mit dem st\u00e4rksten Konkurrenten \"Joe Frazier\" und ein weiterer mit \"George Foreman\", wo er seinen Titel zur\u00fcckeroberte, der ihm sieben Jahre lang entzogen worden war. Ali zeichnete sich durch seinen unkonventionellen Kampfstil aus, er wich aus wie ein Schmetterling und griff an wie eine Biene, er hatte die F\u00e4higkeit und den Mut, Schl\u00e4ge auszuhalten, bis er zum ber\u00fchmtesten Boxer der Welt wurde, da er den schnellsten Schlag der Welt mit einer Geschwindigkeit von 900 Stundenkilometern beherrschte, und er war auch f\u00fcr seine Reden vor seinen K\u00e4mpfen bekannt, da er sich stark auf die Aussagen der Medien st\u00fctzte<\/h1><h4>Seine Krankheit<\/h4><h1>Muhammad Ali litt an der Parkinson-Krankheit, ist aber bis heute eine geliebte Sportikone. W\u00e4hrend seiner Krankheit war er \u00e4u\u00dferst geduldig, denn er sagte immer, Gott habe ihn geplagt, um ihm zu sagen, dass nicht er der Gr\u00f6\u00dfte sei, sondern Gott der Gr\u00f6\u00dfte.<\/h1><h4>Geehrt<\/h4><h1>In Hollywood gibt es eine sehr ber\u00fchmte Stra\u00dfe, die \"Celebrity Street\" genannt wird, weil man dort einen Stern im Namen aller ber\u00fchmten Pers\u00f6nlichkeiten auf die Stra\u00dfe malt.<br \/>Als man dem muslimischen Boxer Muhammad Ali Clay anbot, einen Stern in seinem Namen auf die Stra\u00dfe zu malen, lehnte er ab, und als man ihn fragte, warum er sich weigere, seinen Namen mit einem Stern auf der Stra\u00dfe zu verewigen?<br \/>Er sagte ihnen: \"Ich bin nach dem Propheten benannt, an den ich glaube, Muhammad (Friede sei mit ihm), und ich weigere mich absolut, den Namen 'Muhammad' auf den Boden zu malen.\"<br \/>Doch zu Ehren seiner Popularit\u00e4t und seines Erfolges w\u00e4hrend seiner Karriere beschloss Hollywood, den Stern \"Muhammad Ali\" auf eine Stra\u00dfenwand zu malen und nicht wie bei anderen Ber\u00fchmtheiten auf den Boden.<br \/>Bis heute gibt es keinen anderen Prominenten als Muhammad Ali, dessen Name an der Wand steht. Die \u00fcbrigen Prominenten haben ihre Namen auf dem Boden.<\/h1><h4>Seine wohlt\u00e4tigen Werke<\/h4><h1>Im Jahr 2005 gr\u00fcndete Muhammad Ali Clay in seiner Heimatstadt Louisville ein Zentrum, das Muhammad Ali Centre, in dem er derzeit Erinnerungsst\u00fccke ausstellt und als gemeinn\u00fctzige Organisation arbeitet, um die Ideen des Friedens, des sozialen Wohlstands, der Hilfe f\u00fcr Bed\u00fcrftige und der edlen Werte zu verbreiten, an die Muhammad Ali Clay glaubte.\u00a0<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63517\" class=\"elementor-tab-title\" data-tab=\"17\" role=\"button\" aria-controls=\"elementor-tab-content-63517\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\"> Abdullah Al-Tarjman<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63517\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"17\" role=\"region\" aria-labelledby=\"elementor-tab-title-63517\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34985 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Torjman-Anslem-300x240.jpg\" width=\"300\" height=\"240\" \/>Abdullah al-Mayurki, oder Abdullah al-Mayurki, bekannt als Abdullah al-Tarjaman, war ein spanischer Christ auf der Insel Mallorca und ein hoch angesehener Priester. Er war auch einer der gr\u00f6\u00dften christlichen Gelehrten im achten Jahrhundert AH, und sein Name vor seiner Bekehrung (Anselm Tormida), aber als Gott ihm den Islam erkl\u00e4rte, nannte er sich al-Tarjaman Er schrieb 823 AH das Buch \"Tahfat al-Areeb in Reply to the People of the Cross\" auf Arabisch, das dann ins Franz\u00f6sische \u00fcbersetzt und 1885 im Journal of the History of Religions in Paris ver\u00f6ffentlicht wurde.<\/h1><h4>Die Geschichte des Islam von Abdullah Al-Tarjman<\/h4><p>Abdullah al-Tarjuman erz\u00e4hlte die Geschichte seines Islams in seinem Buch Tahfat al-Areeb: Als ich sechs Jahre alt war, wurde ich einem priesterlichen Lehrer \u00fcbergeben, und ich las die Bibel, bis ich mehr als die H\u00e4lfte davon in zwei Jahren auswendig konnte, dann begann ich, die Sprache der Bibel und die Wissenschaft der Logik zu lernen. Dann reiste ich von Mallorca in die Stadt Llarda in Katalonien, die unter den Christen in diesem Land die Stadt des Wissens ist, und in dieser Stadt versammeln sich die christlichen Studenten des Wissens, und so las ich sechs Jahre lang Naturwissenschaften und Sterne, und dann las ich die Bibel und lehrte sie vier Jahre lang.<\/p><h1>Dann ging ich in die Stadt Baluniya und lebte dort, die eine Stadt des Wissens ist und eine Kirche f\u00fcr einen Priester von gro\u00dfem Alter und Schicksal namens Naghlomartil hat, und sein Status im Wissen, in der Religion und in der Askese war sehr hoch, so dass Fragen \u00fcber die Religion des Christentums und Geschenke von K\u00f6nigen und anderen zu ihm kamen, und sie wollten sogar von ihm gesegnet werden und ihre Geschenke annehmen und f\u00fchlten sich dadurch geehrt, so las ich diesem Priester die Grundlagen der Religion des Christentums und ihre Regeln vor und ich kam ihm immer n\u00e4her, indem ich ihm diente und viele seiner Aufgaben \u00fcbernahm, bis er mich zu einem seiner besten Spezialisten machte und mir die Schl\u00fcssel zu seiner Residenz und die Schatullen seiner Speisen und Getr\u00e4nke bezahlte. Eines Tages erkrankte er und konnte nicht an seiner Lesung teilnehmen, und die Leute des Rates warteten auf ihn und diskutierten \u00fcber Wissensfragen, bis sie zu den Worten des Propheten Jesus, Friede sei mit ihm, kamen: \"Nach mir wird ein Prophet kommen, der Baraklit hei\u00dft.\" Sie diskutierten \u00fcber die Ernennung dieses Propheten und dar\u00fcber, wer er ist, und jeder von ihnen sagte das, was er wusste und verstand, so dass sie einen gro\u00dfen Streit hatten und dann gingen, ohne in dieser Angelegenheit irgendeinen Nutzen zu erlangen.<\/h1><h1>Ich erz\u00e4hlte ihm von den Unterschieden zwischen den Leuten in Bezug auf den Namen des Parakleten, und dass so und so geantwortet hatten, und so und so geantwortet hatten, und ich z\u00e4hlte ihre Antworten auf. Er sagte zu mir: \"Was hast du geantwortet?\" Ich sagte: \"Die Antwort des Richters so und so in der Interpretation des Evangeliums.\" Er sagte zu mir: \"Du bist nah dran und nah dran, und so und so war falsch, und so und so kam fast nah dran, aber die Wahrheit ist das Gegenteil von all dem, denn die Interpretation dieses verehrten Namens kann nur von Gelehrten erkannt werden, die im Wissen gut etabliert sind, und du hast wenig Wissen dar\u00fcber.<\/h1><h1>Ich eilte zu seinen F\u00fc\u00dfen, k\u00fcsste sie und sagte zu ihm: \"Herr, Ihr wisst, dass ich aus einem fernen Land zu Euch gereist bin und seit zehn Jahren in Euren Diensten stehe. In dieser Zeit habe ich von Euch so viele Wissenschaften erlangt, dass ich sie nicht z\u00e4hlen kann; vielleicht w\u00e4re es also eine gro\u00dfe Gunst f\u00fcr Euch, mir die Kenntnis dieses edlen Namens zu gew\u00e4hren. Der Scheich weinte und sagte: \"Mein Sohn, bei Gott, du bist mir sehr teuer f\u00fcr deinen Dienst an mir und deine Hingabe an mich, und die Kenntnis dieses heiligen Namens ist von gro\u00dfem Nutzen, aber ich f\u00fcrchte, dass die Christen dich sofort t\u00f6ten werden, wenn du ihn zeigst\", und er sagte: \"O mein Herr, du wei\u00dft, dass ich aus einem fernen Land zu dir gereist bin.<\/h1><h1>Da sagte ich zu ihm: \"O Herr, bei Allah und bei der Wahrheit des Evangeliums und derer, die mit ihm gekommen sind, ich werde nichts von dem sagen, was du mir sagst, es sei denn auf deinen Befehl hin. Er sagte zu mir: \"Mein Sohn, als du das erste Mal zu mir kamst, fragte ich dich nach deinem Land und ob es den Muslimen nahe steht und ob sie dich guthei\u00dfen oder du sie guthei\u00dft, um deine Abneigung gegen den Islam zu pr\u00fcfen. Wisse, mein Sohn, dass der Baraklit einer der Namen ihres Propheten Muhammad ist, und auf ihn wurde das vierte Buch, das in der Zunge Daniels, Friede sei mit ihm, erw\u00e4hnt wird, herabgesandt, und er sagte, dass dieses Buch auf ihn herabgesandt werden w\u00fcrde, und dass seine Religion die Religion der Wahrheit ist und seine Schule die wei\u00dfe Schule ist, die in der Injil erw\u00e4hnt wird.<\/h1><h1>Er sagte: \"Mein Sohn, wenn die Christen in der Religion des ersten Jesus geblieben w\u00e4ren, dann w\u00e4ren sie in der Religion Gottes gewesen, denn Jesus und alle Propheten sind in der Religion Gottes. Ich sagte: \"Herr, wie kann ich aus dieser Sache herauskommen?\" Er sagte: \"Mein Sohn, indem du der Religion des Islam beitrittst. Ich fragte ihn: \"Wird derjenige, der dem Islam beitritt, gerettet werden?\" Er sagte: \"Ja, er wird in dieser Welt und im Jenseits gerettet werden.<\/h1><h1>Ich sagte zu ihm: \"Mein Herr, ein weiser Mann w\u00e4hlt f\u00fcr sich nur das Beste von dem, was er kennt; wenn du also die Tugenden der islamischen Religion kennst, was h\u00e4lt dich davon ab?\" Er sagte zu mir: \"Mein Sohn, Allah hat mir die Wahrheit dessen, was ich dir \u00fcber die Tugend und die Ehre der Religion des Islam gesagt habe, erst in meinem hohen Alter und nach der Schw\u00e4chung meiner Knochen offenbart. Es gibt keine Entschuldigung f\u00fcr uns, aber Allahs Argument gegen uns steht, und wenn Allah mich in deinem Alter dazu gef\u00fchrt h\u00e4tte, h\u00e4tte ich alles aufgegeben und w\u00e4re in die Wahrheit eingetreten, und die Liebe zur Welt ist das Haupt jeder S\u00fcnde, und du siehst, was ich f\u00fcr die Christen in Bezug auf hohen Status, Ruhm, Ehre und viele Angebote der Welt bin, und wenn ich irgendeine Neigung zur Religion des Islam zeigen w\u00fcrde, w\u00fcrde die \u00d6ffentlichkeit mich so schnell wie m\u00f6glich t\u00f6ten.<\/h1><h1>Wenn ich vor ihnen geflohen w\u00e4re und zu den Muslimen gekommen w\u00e4re und ihnen gesagt h\u00e4tte, dass ich als Muslim zu euch gekommen bin, w\u00fcrden sie zu mir sagen: \"Du hast dir selbst einen Vorteil verschafft, indem du in die Religion der Wahrheit eingetreten bist, also gew\u00e4hre uns keine Religion, mit der du dich vor der Strafe Gottes gerettet hast\", und ich w\u00fcrde als armer alter Mann von neunzig Jahren unter ihnen bleiben, ohne ihre Sprache zu kennen und ohne mein Recht zu kennen, und ich w\u00fcrde unter ihnen verhungern.<\/h1><h1>Ich geh\u00f6re, Gott sei Dank, der Religion Jesu an und dem, was er mitgebracht hat, und Gott wei\u00df das \u00fcber mich. Also sagte ich zu ihm: \"Herr, gibst du mir die Erlaubnis, in das Land der Muslime zu gehen und in ihre Religion einzutreten?\" Er sagte zu mir: \"Wenn du zurechnungsf\u00e4hig bist und \u00fcberleben willst, solltest du das tun, damit du die Welt und das Jenseits bekommst, aber mein Sohn, das ist etwas, was jetzt niemand bei uns ist, also halte es so gut wie m\u00f6glich geheim, und wenn irgendetwas davon bei dir auftaucht, wird die \u00d6ffentlichkeit dich f\u00fcr deine Zeit t\u00f6ten, und ich kann dir nicht helfen, und es wird dir nichts n\u00fctzen, es von mir zu berichten, denn ich leugne es, mein Wort wird von dir geglaubt und dein Wort wird von mir nicht geglaubt, und ich bin unschuldig an deinem Blut, wenn irgendetwas davon f\u00fcr dich verloren geht.<\/h1><h1>Dann nahm ich die Gr\u00fcnde f\u00fcr die Reise und verabschiedete mich von ihm. Er betete f\u00fcr mich und versorgte mich mit f\u00fcnfzig Golddinaren. Ich ging an Bord des Schiffes und fuhr nach Mallorca, wo ich sechs Monate blieb, dann reiste ich nach Sizilien, wo ich f\u00fcnf Monate blieb und auf ein Schiff wartete, um in das Land der Muslime zu fahren. Es kam ein Schiff nach Tunis, und so reiste ich von Sizilien aus mit ihm.<\/h1><h1>Danach fragte ich sie, ob es im Sultanatshaus jemanden g\u00e4be, der die Sprache der Christen beherrsche, und der damalige Sultan war Mawlana Abu al-Abbas Ahmad, m\u00f6ge Allah ihm gn\u00e4dig sein, und die Christen erz\u00e4hlten mir davon: Ich war sehr gl\u00fccklich dar\u00fcber und fragte nach dem Wohnsitz dieses Arztes, der mir gezeigt wurde, und ich traf mich mit ihm und erkl\u00e4rte ihm meine Situation und den Grund meines \u00dcbertritts zum Islam, und er war sehr erfreut, dass diese gute Tat durch seine H\u00e4nde vollbracht werden w\u00fcrde.<\/h1><h1>Dann bestieg er sein Pferd und nahm mich mit zum Haus des Sultans. Er trat ein und erz\u00e4hlte ihm von meiner Unterhaltung und bat ihn um Erlaubnis, mich vor ihm erscheinen zu lassen. Als erstes fragte er mich nach meinem Alter, und ich sagte ihm f\u00fcnfunddrei\u00dfig Jahre, und dann fragte er mich, was ich in den Wissenschaften gelesen h\u00e4tte: Ich sagte zu dem Dolmetscher, der der besagte Arzt ist: \"Sagen Sie unserem Sultan, dass er nicht ausgeht: Sagen Sie unserem Sultan, dass niemand aus seiner Religion austritt, ohne dass seine Leute ihn verleumden, also m\u00f6chte ich, dass Sie zu den christlichen Kaufleuten und guten Menschen in Ihrer Gegenwart schicken und sie \u00fcber mich befragen und h\u00f6ren, was sie \u00fcber mich sagen, und dann werde ich Muslim werden, so Gott will, so sagte er zu mir durch den Dolmetscher: Du hast gefragt, wie Abdullah Ibn Salam gefragt hat: Du hast gefragt, wie Abdullah Ibn Salam den Propheten (Friede sei mit ihm) gefragt hat, und dann ist er Muslim geworden.<\/h1><h1>Er schickte nach den ausgew\u00e4hlten Christen und einigen ihrer Kaufleute und brachte mich in einem Haus in der N\u00e4he seines Rates unter, und als die Christen eintraten, sagte er zu ihnen: \"Was sagt ihr \u00fcber diesen neuen Priester, der mit diesem Boot gekommen ist? Als die Christen eintraten, sagte er zu ihnen: \"Was sagt ihr \u00fcber diesen neuen Priester, der in diesem Boot gekommen ist?\" Sie sagten: \"O unser Herr, dies ist ein gro\u00dfer Gelehrter in unserer Religion, und wir haben nie einen h\u00f6heren Grad an Wissen und Religion gesehen als ihn.\" Er sagte: \"Was sagt ihr \u00fcber ihn, wenn er Moslem wird?\" Sie sagten: \"Das verbieten wir Gott, das w\u00fcrde er nie tun.\" Als er h\u00f6rte, was die Christen zu sagen hatten, schickte er nach mir, und ich trat vor ihn und bezeugte die Wahrheit vor den Christen, und sie fielen auf ihr Gesicht und sagten: \"Er hat ihn nur aus Liebe zur Ehe dazu gebracht, denn unsere Priester heiraten nicht.<\/h1><h1>Als ich entschlossen war, zu heiraten, gab er mir hundert Golddinar und einen guten, vollen Anzug, und so nahm ich meine Frau, und mir wurde ein Sohn geboren, den ich Muhammad nannte, zu Ehren unseres Propheten Muhammad, m\u00f6ge Allah ihn segnen und ihm Frieden geben[1].<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63518\" class=\"elementor-tab-title\" data-tab=\"18\" role=\"button\" aria-controls=\"elementor-tab-content-63518\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Fatima Herin<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63518\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"18\" role=\"region\" aria-labelledby=\"elementor-tab-title-63518\"><h1>Die wahre Bedeutung des Islams besteht darin, dass die Gl\u00e4ubigen ihr ganzes Wesen Allah, dem Allm\u00e4chtigen, \u00fcberlassen, sowohl in ihrem eigenen Leben als auch in den kleinen und gro\u00dfen Angelegenheiten.<\/h1><h1>Sie sollen sich der Hand hingeben, die sie f\u00fchrt, im Vertrauen darauf, dass sie Gutes, Rat und F\u00fchrung f\u00fcr sie will, und dass sie des Weges und der Bestimmung im Diesseits und im Jenseits gewiss sind; gem\u00e4\u00df den Worten des allm\u00e4chtigen Gottes: {Sag, dass mein Gebet, meine Rituale, mein Leben und mein Sterben Gott, dem Herrn der Welten, gelten * Es gibt keinen Partner f\u00fcr Ihn, und so habe ich befohlen, und ich bin der erste der Muslime} [Al-Anam: 162, 163].<\/h1><h1>Das war die Frage, die Fatima Heeren besch\u00e4ftigte, ein deutsches M\u00e4dchen, das zum Islam konvertierte, nachdem sie mit dem Nationalsozialismus aufgewachsen war, in dem die Rolle Gottes in allen Angelegenheiten der Sch\u00f6pfung und im t\u00e4glichen Leben nicht vorkommt.<\/h1><h4>Nationalistische Slogans<\/h4><p>Fatima Herrin wurde 1934 in Deutschland als Tochter eines Vaters geboren, der in der deutschen Armee t\u00e4tig war und die nationalsozialistischen Werte hochhielt.<\/p><h1>Als der Zweite Weltkrieg 1945 zu Ende ging, war Fatima eine elfj\u00e4hrige Sch\u00fclerin. Die Tr\u00e4ume der deutschen Nation waren zerschlagen, und alle Ideale, f\u00fcr die Leben geopfert worden waren, waren zerschlagen.<\/h1><h1>In den Jahren vor und w\u00e4hrend des Krieges war der Nationalismus ein hervorragendes Mittel, um die Deutschen an ihre Grenzen zu treiben, wobei es nur darum ging, alles f\u00fcr das Vaterland zu tun.<\/h1><h1>Dieser Nationalismus wirkte sich auf die Vorstellung von der Existenz Gottes aus: F\u00fcr die deutsche Gesellschaft war Gott die Macht, die vor Millionen von Jahren die Naturgesetze geschaffen hatte, die wiederum den Menschen - wahrscheinlich durch Zufall - hervorgebracht hatten.<\/h1><h1>Fatima Hirin sagt \u00fcber die damalige Geisteshaltung ihrer Gemeinschaft: \"Das Christentum war der einzige Glaube, mit dem wir wirklich konfrontiert wurden, und er wurde uns als 'Opium der V\u00f6lker' pr\u00e4sentiert, als der Glaube der Sch\u00e4fchen, die sich nur aus Angst vor dem Tod bewegen.<\/h1><h1>Wir haben verstanden, dass jeder Mensch f\u00fcr sich selbst verantwortlich ist und tun kann, was er will, solange es anderen nicht schadet, und wir haben uns vorgestellt, dass das Gewissen die einzige Richtschnur ist.<\/h1><h1>Viele Leute wie ich waren unzufrieden mit der Art und Weise, wie die moderne Gesellschaft funktioniert, aber sie behaupteten trotzdem, gl\u00fccklich zu sein, und wenn sie nach einer durchtanzten und durchzechten Nacht aufwachten, sp\u00fcrten sie eine Leere in ihrer Brust, die sich auch durch weiteres Tanzen, Trinken oder Flirten an den folgenden Abenden nicht beheben lie\u00df.<\/h1><h1>Als der Zweite Weltkrieg zu Ende ging, sagte Fatima: \"Der Krieg hat nicht nur unser Land (Deutschland) zerrissen, sondern auch die Gr\u00f6\u00dfe unserer Nation und all die Ideale, f\u00fcr die wir unser Leben gelassen haben, zerst\u00f6rt.<\/h1><h1>Ich erkannte, dass das individuelle Gewissen und die von der Gesellschaft akzeptierten humanit\u00e4ren Ideale allein nicht ausreichen, um als Leitfaden in meinem Leben zu dienen. Ich f\u00fchlte mich nicht wirklich gl\u00fccklich, weil ich die Gl\u00fcckseligkeit genoss, die mir zur Verf\u00fcgung stand, ohne jemandem f\u00fcr all das Gute zu danken, das mir zuteil wurde. Ich f\u00fchrte ein t\u00e4gliches Tagebuch und ertappte mich einmal dabei, wie ich den folgenden Satz aufschrieb: \"Es war ein freudiger Tag; vielen Dank, oh Herr!<\/h1><h1>Zuerst sch\u00e4mte ich mich, aber dann wurde mir klar, dass es nicht ausreichte, nur an einen Gott zu glauben... Ich wusste, dass es meine Pflicht war, ihn zu suchen, einen Weg zu finden, ihm zu danken und ihn anzubeten.\"<\/h1><h4>Die Ung\u00fcltigkeit des Christentums<\/h4><p>Nachdem das nationalistische Projekt ihres Landes in Bezug auf Kultur und Glauben gescheitert war, wandte sich Fatima Herin dem Christentum zu, um den Weg zu Gott zu finden: Ein Priester riet mir, zum Christentum zu konvertieren und zum Abendmahl zu gehen, und sagte: \"Wenn du die christliche Religion praktizierst, wirst du sicher einen Weg zu Gott finden.\" Ich folgte seinem Rat, aber ich erf\u00fcllte das Versprechen des Abendmahls nicht. Ich befolgte seinen Rat, aber es gelang mir nicht, wahren Seelenfrieden zu erlangen.\"<\/p><h1>Fatima Hirin erkl\u00e4rte den Grund f\u00fcr ihre Entt\u00e4uschung \u00fcber das Christentum: \"Wir Christen m\u00fcssen in unserem Glauben Kompromisse eingehen, um in unserer Gesellschaft leben zu k\u00f6nnen; die Kirche ist immer bereit, Kompromisse einzugehen, um ihre Macht in unserer Gesellschaft zu erhalten, um ein Beispiel zu nennen: Die Kirche sagt: Sexuelle Beziehungen sollten erst nach der Ehe im Namen Gottes beginnen, aber fast kein Mann und keine Frau im Westen \"kauft die Katze im Sack\", was ein g\u00e4ngiges Sprichwort ist, das bedeutet, dass man eine Ehe eingeht, ohne vorher die sexuelle Kompatibilit\u00e4t der beiden Partner miteinander zu testen.<\/h1><h1>Der Priester ist immer bereit, jedem, der diese S\u00fcnde bekennt, mit ein oder zwei Gebeten die Absolution zu erteilen.\"<\/h1><h1>Im Gegensatz dazu fordert der Islam seine Anh\u00e4nger auf, im Namen des Glaubens ihr ganzes Wesen Allah, dem Allm\u00e4chtigen, zu \u00fcbergeben, ohne zu z\u00f6gern und ohne sich abzuwenden; eine \u00dcbergabe, nach der kein rebellischer Rest von Wahrnehmung oder Gef\u00fchl, Absicht oder Handlung, Wunsch oder Furcht zur\u00fcckbleiben wird, der sich nicht Allah unterwirft und seine Herrschaft und sein Urteil akzeptiert, wie der Allm\u00e4chtige sagt {O ihr, die ihr glaubt, kommt in Frieden als Ganzes und folgt nicht den Fu\u00dfstapfen des Satans, denn er ist ein klarer Feind f\u00fcr euch [Al-Baqarah: 208].<\/h1><h1>Fatima Hirin und der Weg zum Islam<br \/>Fatima Hirin war auf der Suche nach einem perfekten Prinzip, an dem sie sich festhalten konnte, nach einem geraden Weg, auf den sie ihr ganzes Leben ausrichten konnte, so dass sie Gott nicht einmal dann nahe kommen konnte, wenn sie in der Kirche kniete.<\/h1><h1>1957 traf Fatima Herren zum ersten Mal den Mann, der zwei Jahre sp\u00e4ter ihr Ehemann werden sollte, einen deutschen Muslim mit einem Doktortitel in Philosophie.<\/h1><h1>Aber als er mir erz\u00e4hlte, dass er vor sieben Jahren zum Islam konvertiert war, war ich so \u00fcberrascht, dass ich wissen wollte, warum ein gebildeter Mann wie er diesen Weg gew\u00e4hlt hatte.<\/h1><h1>Mein Mann erkl\u00e4rte mir die Bedeutung des Islam: Allah ist nicht nur der Herr der Muslime, sondern dieses Wort \"Allah\" ist f\u00fcr uns gleichbedeutend mit \"G\u00f6ttlichkeit\", und dass die Muslime an die absolute Einheit des Sch\u00f6pfers glauben, und dass sie ihren Propheten Mohammed, Friede sei mit ihm, nicht so verehren wie die Christen Jesus Christus, und dass das Wort \"Islam\" v\u00f6llige Unterwerfung unter den einen und einzigen Gott bedeutet.<\/h1><h1>Er sagte mir, dass aus islamischer Sicht alle Lebewesen und alles notwendigerweise als selbstverst\u00e4ndlich angesehen werden, d. h. sie m\u00fcssen sich den Gesetzen Gottes unterwerfen und hingeben, und wenn sie das nicht tun, droht ihnen die Vernichtung.<\/h1><h1>Er f\u00fcgte hinzu: Der Mensch allein - unabh\u00e4ngig davon, ob sein K\u00f6rper freiwillig oder unfreiwillig muslimisch ist - ist von Gott mit der Freiheit des Willens und der Wahl ausgestattet, zu entscheiden, ob er sowohl in seinem geistigen als auch in seinem k\u00f6rperlichen Leben Muslim sein will. Wenn er dies tut und gem\u00e4\u00df dieser Entscheidung lebt, wird er sich mit Gott verbinden und Harmonie und seelischen Frieden mit den anderen Gesch\u00f6pfen in diesem irdischen Leben finden und im Jenseits Gl\u00fcck finden.<\/h1><h1>Aber wenn er sich gegen die Gesetze Gottes auflehnt, die uns im Heiligen Koran klar und deutlich offenbart werden, ist er ein Verlierer in diesem und im n\u00e4chsten Leben.\"<\/h1><h1>Fatima f\u00fcgt hinzu, was sie \u00fcber den Islam entdeckt hat: \"Von meinem Mann habe ich auch gelernt, dass der Islam keine neue Religion ist, sondern dass der Koran das einzige Buch ist, das frei von Abweichungen und Fehlern ist, und dass er das letzte himmlische Buch in einer langen Reihe von B\u00fcchern ist, vor allem die Offenbarungen der Thora und des Evangeliums.<\/h1><h1>Unter der Anleitung meines Mannes begann ich, die wenigen B\u00fccher zu lesen, die es \u00fcber den Islam in deutscher Sprache gab, und ich meine die wenigen B\u00fccher, die aus islamischer Sicht verf\u00fcgbar waren, von denen das wichtigste Muhammad Asads Der Weg nach Mekka war, das mich sehr inspiriert hat.<\/h1><h1>Einige Monate nach unserer Heirat lernte ich, wie man auf Arabisch betet, wie man fastet und studierte den Heiligen Koran, bevor ich 1960 zum Islam konvertierte.<\/h1><h1>Die Weisheit des Korans erf\u00fcllte meine Seele mit Liebe und Bewunderung, aber mein Augapfel war das Gebet; ich f\u00fchlte ein starkes Gef\u00fchl, dass Gott mit mir war, als ich dem\u00fctig in seinen H\u00e4nden stand und den Koran rezitierte und betete.\"<\/h1><h4>Der Islam als Lebensform<\/h4><p>Fatima Hirin wollte nicht zulassen, dass die Religion nur ein kleiner Teil ihres Lebens bleibt, so wie sie es einst war, oder vielleicht sogar gar kein Teil ist.<\/p><h1>Fatima beschloss, ihr ganzes Leben nach dem Islam auszurichten und ihn zu einer vollst\u00e4ndigen Lebenseinstellung zu machen, auch wenn sie daf\u00fcr auswandern musste.<\/h1><h1>Fatima Hirin sagte: \"Ich begann, die f\u00fcnf t\u00e4glichen Gebete regelm\u00e4\u00dfig zu verrichten und lernte, dass das Gebet nicht etwas ist, das man einfach so verrichtet, sondern dass es ein System ist, nach dem der ganze Tag gestaltet werden muss.<\/h1><h1>Ich habe gelernt, mich mit der Situation abzufinden, dass mein Mann mit seinen Glaubensbr\u00fcdern zusammensitzt und sich mit ihnen unterh\u00e4lt, w\u00e4hrend ich Tee zubereite und ihn an der T\u00fcr serviere, ohne zu wissen, f\u00fcr wen ich ihn zubereitet habe, und dass ich, anstatt auf den Markt zu gehen, zu Hause geblieben bin, um islamische B\u00fccher auf Englisch zu lesen.<\/h1><h1>Ich begann auch zu fasten und bereitete die Mahlzeiten zu, ohne sie zu probieren, obwohl ich manchmal gro\u00dfen Hunger und Durst versp\u00fcrte.<\/h1><h1>Durch die Lekt\u00fcre der Hadith-B\u00fccher des Propheten lernte ich unseren Propheten Muhammad und seine Gef\u00e4hrten lieben; sie wurden f\u00fcr mich zu lebendigen menschlichen Gestalten, nicht nur zu erstaunlichen historischen Modellen.<\/h1><h1>Die Beispiele f\u00fcr Freundlichkeit, Mut, Hingabe und G\u00fcte, die diese ersten Menschen gaben, wurden f\u00fcr mich zu Leitsternen, und mir wurde klar, wie ich mein Leben so gestalten sollte, dass ich in diesem Leben ein guter und zufriedener Mensch sein w\u00fcrde, ein Weg, dessen Verhalten die Art der Belohnung bestimmt, die wir im n\u00e4chsten Leben erhalten werden.\"<\/h1><h1>In ihrem Bem\u00fchen, nach dem Islam zu leben und ihn in allen Aspekten ihres Lebens anzuwenden, sagte Fatima Hirin: \"Mein Mann und ich waren uns einig, dass unser islamisches Leben in einem westlichen Land von uns viele Kompromisse verlangen w\u00fcrde. Der Islam ist nicht nur eine Religion im herk\u00f6mmlichen Sinne, sondern eine vollst\u00e4ndige Lebensweise, die nur in einer muslimischen Gesellschaft in ihrer reinsten Form angewendet werden kann. Da wir beide diese Religion aus freien St\u00fccken gew\u00e4hlt haben, wollten wir keinen lauwarmen, schwachen Islam.<\/h1><h1>So hatten wir nach langem Warten 1962 die M\u00f6glichkeit, nach Pakistan auszuwandern, nachdem wir genug Geld gespart hatten, um die Kosten f\u00fcr die Reise zu decken.<\/h1><h4>Fatima Hirin und die Verteidigung des Islam<\/h4><p>Fatima verteidigte den Islam und erl\u00e4uterte die Gr\u00f6\u00dfe und Reinheit des islamischen Rechts, w\u00e4hrend sie die Falschheit und Irref\u00fchrung anderer Glaubensrichtungen entlarvte, indem sie sagte: \"Wenn diejenigen, die dem Islam gegen\u00fcber voreingenommen sind, sagen, dass es barbarisch ist, wenn ein Mann sich mehrere Frauen nimmt, k\u00f6nnen sie mir dann zeigen, was an ihrem Verhalten gut ist, wenn ein Mann sich neben seiner Frau noch andere Frauen nimmt? Dies ist im Westen weiter verbreitet als die Polygamie in muslimischen L\u00e4ndern.<\/p><h1>Wenn sie behaupten, dass ihr Alkoholkonsum nicht sch\u00e4dlich ist, k\u00f6nnen sie dann erkl\u00e4ren, warum diese Gewohnheit im Westen so viel Elend verursacht?<\/h1><h1>Wer behauptet, dass das Fasten die Arbeitskraft und die Gesundheit der Nation schw\u00e4cht, sollte einen Blick auf die gro\u00dfen Leistungen der Gl\u00e4ubigen w\u00e4hrend des gesegneten Monats Ramadan werfen und die wichtigen Berichte lesen, die muslimische \u00c4rzte k\u00fcrzlich \u00fcber ihre nat\u00fcrlichen Erfahrungen mit fastenden Patienten gemacht haben.<\/h1><h1>Wenn sie sagen, dass die Trennung der Geschlechter zu sp\u00e4t ist, dann sollen sie die Jugend in einem muslimischen Land mit der Jugend in einer westlichen Nation vergleichen, denn der sittliche Versto\u00df zwischen einem Jungen und einem M\u00e4dchen gilt bei den Muslimen als Ausnahme, w\u00e4hrend es bei den Westlern nur sehr selten eine einzige Ehe zwischen einem keuschen Jungen und einem keuschen M\u00e4dchen gibt.<\/h1><h1>Wenn diejenigen, die dem Islam gegen\u00fcber Vorurteile haben, behaupten, dass das Verrichten von f\u00fcnf Gebeten jeden Tag und jede Nacht - in einer Sprache, die vielen Gl\u00e4ubigen unbekannt ist - eine Zeitverschwendung und eine nutzlose Anstrengung ist, dann sollen sie uns ein System im Westen zeigen, das die Menschen auf eine st\u00e4rkere und sicherere Weise f\u00fcr K\u00f6rper und Seele vereint als die muslimischen Andachtsrituale. Sie sollen beweisen, dass der Westler in seiner Freizeit mehr N\u00fctzliches leistet als ein Muslim, der jeden Tag eine Stunde dem Gebet widmet.<\/h1><h1>Der Islam ist seit mehr als vierzehn Jahrhunderten g\u00fcltig und bleibt es auch in unserer Zeit, wenn wir ihn ohne verzerrte Kompromisse weiterf\u00fchren.<\/h1><h1>Viele Menschen haben diese Tatsache in unseren Tagen erkannt, und sie werden, so Gott will, zusammenarbeiten, um es der kranken, gequ\u00e4lten und elenden Welt, die zu ihnen aufschaut, zu zeigen.\"<\/h1><h1>So hat sich Fatima Hirin ver\u00e4ndert, nachdem sie zum Islam konvertiert ist. Sie glaubte, dass es im Islam nicht nur um Rituale und Anbetung geht, sondern um ein komplettes Leben und eine Herangehensweise, um in dieser Welt gl\u00fccklich zu leben und einen Muslim ins Paradies im Jenseits zu f\u00fchren.<\/h1><h1>Fatima Hirin's Beitr\u00e4ge<br \/>Sie hat mehrere B\u00fccher \u00fcber den Islam geschrieben, darunter: (Fasten - Das Fasten) 1982, (Zakat - Zakat) 1978 und (Muhammad - Muhammad) 1983.<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63519\" class=\"elementor-tab-title\" data-tab=\"19\" role=\"button\" aria-controls=\"elementor-tab-content-63519\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Luis Garde<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63519\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"19\" role=\"region\" aria-labelledby=\"elementor-tab-title-63519\"><h1>Louis Gardi gilt als einer der bedeutendsten europ\u00e4ischen Philosophen, die sich eingehend mit dem islamischen Denken und der islamischen Zivilisation befasst haben. Schon in jungen Jahren war Louis Gardi leidenschaftlich bem\u00fcht, die Grunds\u00e4tze der Offenbarungsreligionen zu erforschen. Obwohl er in einer konservativen katholischen Familie aufwuchs, wurde er von einer psychologischen Besessenheit von den Mysterien und Geheimnissen, die er in seiner eigenen Religion sah, heimgesucht, die ihn dazu brachte, nach den Urspr\u00fcngen \u00f6stlicher Religionen wie dem Buddhismus, dem Hinduismus und anderen zu suchen, um die Wahrheit zu finden.<\/h1><h4>Die Geschichte des Islam von Louis Garde<\/h4><h1>Louis Gardet las eine \u00dcbersetzung der Bedeutung des Korans und fand darin viele Dinge, die sein Herz beruhigten, so dass er sich zum Islam hingezogen f\u00fchlte und langsam begann, sich tiefer in den Islam zu vertiefen, Arabisch lernte, den Koran auf Arabisch las und sich dann dem Studium der islamischen Zivilisation zuwandte und feststellte, dass der Islam sein Wunschziel war, und er glaubte an ihn als wahre g\u00f6ttliche Lehre (in seinem Herzen). Er glaubte an den Islam als wahren g\u00f6ttlichen Glauben (mit seinem Herzen); weil er sich sicher war, dass diejenigen, die den Islam annahmen und ihn in Europa verbreiteten, mit vielen Hindernissen konfrontiert wurden, verbarg Garde seinen Glauben in seinem Herzen und beschr\u00e4nkte seine Bem\u00fchungen, seine Arbeit, sein Geld und seine Gedanken auf den Sieg dieser Religion.<\/h1><h1>Louis Garde stellte fest, dass der Zionismus einen Angriffskrieg gegen alles Islamische in Europa f\u00fchrt, in dem alle aggressiven Mittel eingesetzt werden, angefangen von Versuchen, einige Verse des Heiligen Koran zu entstellen, den Heiligen Koran in viele afrikanische Regionen zu exportieren, nachdem er entstellt wurde, Unterw\u00e4sche und Schuhe mit islamischen Inschriften und Symbolen zu entwerfen, die im Gewissen eines jeden Muslims heilig sind und respektiert werden, und dazu beizutragen, fanatische Forscher zu ermutigen, ihre B\u00fccher und Studien zu ver\u00f6ffentlichen, die das Bild des Islam entstellen und den Muslimen und ihrem Propheten Laster und Untugenden anh\u00e4ngen.<\/h1><h4>Beitr\u00e4ge von Louis Garde<\/h4><h1>Louis Gardet verteidigte den Islam und ver\u00f6ffentlichte das Buch \"Die Muslime und die Konfrontation mit den zionistischen Angriffen\"; au\u00dferdem widmete er sich f\u00fcnfzehn Jahre lang (1957-1972) dem Studium der islamischen Philosophie am Internationalen Institut f\u00fcr Philosophie in Toulouse.<\/h1><h1>Er hat auch eine Reihe wichtiger islamischer Werke verfasst, wie z. B.: Die islamische Gesellschaft, Islam f\u00fcr alle Zeitalter und Religion und Gesellschaft. Er betreut die Ver\u00f6ffentlichung einer Reihe islamischer Studien und ist an der Entwicklung einer islamischen Enzyklop\u00e4die in franz\u00f6sischer Sprache beteiligt.<\/h1><h1>In diesem Buch erkl\u00e4rt er, wie islamische Werte und Prinzipien die Zeitalter und Generationen \u00fcberdauert haben und in jedem Zeitalter frisch, erneuert, begehrt und einflussreich bleiben.<\/h1><h1>In diesem Buch weist Jardet die Behauptung einiger philosophischer Theoretiker zur\u00fcck, dass der Islam eine W\u00fcstenreligion sei und sich nicht f\u00fcr andere Gesellschaften eigne; er antwortet diesen Materialisten mit den Worten: \"Die W\u00fcste war nur der Ort und der Ausgangspunkt f\u00fcr diese neue Religion, als sie kam, wo ihre Fundamente vollendet wurden und wo ihre Merkmale deutlich wurden, um eine globale Religion zu werden, und die W\u00fcste war keineswegs eine Siedlung f\u00fcr die islamischen V\u00f6lker, wie die Tatsache beweist, dass die islamische Welt heute mehr als eine Milliarde Muslime umfasst und sich von Dakar im Senegal bis zu den philippinischen Inseln im Indischen Ozean erstreckt.\"<\/h1><h4>Louis Gardet und die Verteidigung des Islam<\/h4><h1>Jardet entgegnet den F\u00e4lschungen, die im Westen \u00fcber den Islam und die Muslime gemacht, verbreitet und wiederholt werden, einschlie\u00dflich des Vorwurfs, die Muslime seien fatalistisch und faul. Jardet antwortet darauf mit Dutzenden von Koranversen und Hadithen, die die Muslime dazu auffordern, zu arbeiten und ihre Arbeit zu meistern, und dass sie die volle Verantwortung tragen. Dann entgegnet er dem Vorwurf, der Islam sei eine Religion der \u00e4u\u00dferen Rituale und Zeremonien, die unabh\u00e4ngig vom Lebenswandel zu befolgen seien:<\/h1><h1>\"Solche Dinge sind in den Zeitaltern der Dekadenz aufgetaucht, und die Wahrheit ist, dass die Anbetung nur dann akzeptiert werden kann, wenn sie aufrichtig ist und von aufrichtigen Absichten begleitet wird.\"<\/h1><h1>Er antwortet auch auf das Ger\u00fccht der Westler, der Islam sei eine Religion der Angst, indem er sagt, dass Gott im Islam \"der Barmherzigste, der Mitf\u00fchlendste\" ist und dass von den neunundneunzig g\u00f6ttlichen Namen, die Muslime singen, nur zwei Namen das g\u00f6ttliche Selbst als m\u00e4chtig, schrecklich und strafend beschreiben, und diese beiden Attribute werden nur f\u00fcr ungehorsame und ungl\u00e4ubige Menschen verwendet.<\/h1><h1>Hier k\u00f6nnen wir sehen, wie sehr sich das Leben von Louis Jardet nach seiner Konversion zum Islam ver\u00e4ndert hat, denn dieser Mann, der noch vor wenigen Jahren ein Nicht-Muslim war, wurde mit aller Kraft zum Verteidiger des Islam. Gepriesen sei Allah, der ihn zum Islam gef\u00fchrt hat!<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63520\" class=\"elementor-tab-title\" data-tab=\"20\" role=\"button\" aria-controls=\"elementor-tab-content-63520\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mohammed Fouad Al Hashimi<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63520\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"20\" role=\"region\" aria-labelledby=\"elementor-tab-title-63520\"><h1>Er wurde als Sohn christlicher Eltern in \u00c4gypten geboren, und sie fl\u00f6\u00dften ihm die Liebe zum Christentum ein, so dass er sich anderen Christen anschloss, aber er begann nachzudenken und zu diskutieren, und er hatte einige Zweifel, die das Feuer der Unruhe in ihm entfachten, was ihn dazu veranlasste, nach der Wahrheit und einer gesunden Religion zu suchen.<\/h1><h1>Als sein Verstand wuchs, begann er nach der Wahrheit zu suchen, sagt er:<br \/>\"Das Studium hat mich dazu gebracht, mehrere Rufe zu h\u00f6ren, die meine Ohren erreichten, als Folge der L\u00fccken, die durch Zweifel und Skepsis in dem entstanden waren, was der Verstand nicht akzeptieren konnte, und das Gewissen war nicht beruhigt durch den Moment der gewissenhaften Reinheit, in dem ich studierte oder mich darauf vorbereitete, Aufgaben zu \u00fcbernehmen, so dass diese Rufe das Privileg hatten, geh\u00f6rt zu werden, gefolgt von der Reflexion \u00fcber die Religionen vor der meinen.<\/h1><h4>Die Geschichte von Mohammed Fouad Al Hashimi<\/h4><p>Al-Hashimi begann, vorchristliche Religionen und positive Religionen zu erforschen, in der Hoffnung, das zu finden, wonach er suchte. Danach begann er, die islamische Religion zu erforschen, aber er war w\u00fctend und hasste sie, er wollte sie nicht betreten, sondern wollte Fehler finden, Irrt\u00fcmer suchen und nach Widerspr\u00fcchen suchen, um sie zu zerst\u00f6ren und die Menschen vor ihr zu retten, aber herrlich ist der, der die Verh\u00e4ltnisse \u00e4ndert! Dieser Mann fand im Islam den Weg der Rechtleitung und das Licht, nach dem er sein ganzes Leben lang gesucht hatte.<\/p><h1>Bei der Beschreibung dessen, was er im Islam sah, sagte er: \"Ich fand auf jede Frage eine befriedigende Antwort, die keine fr\u00fchere Religion, sei sie positivistisch oder von g\u00f6ttlichen Religionen oder einem philosophischen Prinzip abgeleitet (und ich sage abgeleitet aufgrund des Niedergangs der Religionen durch die H\u00e4nde von Klerikern, die sie von dem abbrachten, wof\u00fcr sie gedacht waren): Ich fand heraus, dass das, was sie als M\u00e4ngel im Islam bezeichneten, Vorteile waren, dass das, was sie f\u00fcr Widerspr\u00fcche hielten, Weisheiten oder Urteile und Gesetze waren, die f\u00fcr die Kl\u00fcgsten detailliert beschrieben wurden, und dass das, was sie dem Islam vorwarfen, ein Heilmittel f\u00fcr die Menschheit war, die lange in der Finsternis umhergeirrt war, bis der Islam sie aus der Finsternis ins Licht brachte und die Menschen mit der Erlaubnis ihres Herrn auf einen geraden Weg f\u00fchrte.\"<\/h1><h1>Mohammed Fouad Al Hashimi erkl\u00e4rte daraufhin seinen Islam.<\/h1><h4>Beitr\u00e4ge von Mohammed Fouad Al Hashimi<\/h4><p>Nachdem Muhammad Fouad al-Hashemi zum Islam konvertiert war, tat er vieles, um dem Islam zu dienen, unter anderem verglich und kontrastierte er die Religionen, und eine der Fr\u00fcchte dieser Vergleiche war das wunderbare Buch, das er den Muslimen vorlegte (Religionen im Gleichgewicht). Neben vielen anderen B\u00fcchern hat er auch das Wort Allahs verk\u00fcndet und seine Religion unterst\u00fctzt.<\/p><h1>{Und Gott wird denjenigen unterst\u00fctzen, der ihn unterst\u00fctzt, denn Gott ist stark und m\u00e4chtig} [Al-Hadsch: 40].<\/h1><h1>Er ist der Autor des Buches \"Das Geheimnis des Islam. Warum ich den Islam als meine Religion gew\u00e4hlt habe\", \"Der Prophet hat nicht gelogen\" und \"Dialog zwischen einem Christen und einem Muslim\".<\/h1><h5>Die Quelle: Das Buch von Dr. Ragheb al-Sarjani (Gro\u00dfe M\u00e4nner, die Muslime wurden).<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63521\" class=\"elementor-tab-title\" data-tab=\"21\" role=\"button\" aria-controls=\"elementor-tab-content-63521\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ahmed Nassim Sousa ... irakischer Jude<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"21\" role=\"region\" aria-labelledby=\"elementor-tab-title-63521\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34986 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/\u0623\u062d\u0645\u062f_\u0633\u0648\u0633\u0629-198x300.jpg\" width=\"198\" height=\"300\" srcset=\"\" sizes=\"(max-width: 198px) 100vw, 198px\" data-srcset=\"\" \/>Ahmed Nasim Sousa, der zum Islam konvertierte und die Wahrheit der von den Juden geschriebenen falschen Geschichte aufdeckte, stammte aus dem Stamm der Bani Sawasa, die in den Bezirken von Hadramawt im Jemen lebten. 1318 AH \/ 1900 n. Chr. wurde er als Sohn einer j\u00fcdischen Familie in Hilla, Irak, geboren und schloss 1924 n. Chr. sein Vorbereitungsstudium (High School) an der Amerikanischen Universit\u00e4t in Beirut ab. 1928 n. Chr. erwarb er einen Bachelor-Abschluss in Bauingenieurwesen am Colorado College in den Vereinigten Staaten.<\/h1><h1>Ahmed Nassim Sousa setzte seine Studien fort und promovierte 1930 mit Auszeichnung an der Johns Hopkins University. Er wurde zum Mitglied von Phi Beta Kappa, einer bekannten amerikanischen wissenschaftlichen Institution, gew\u00e4hlt. 1929 verlieh ihm die University of Washington den Weddell-Preis, der j\u00e4hrlich an den Autor des besten Artikels verliehen wird, der zur F\u00f6rderung des Friedens zwischen den L\u00e4ndern der Welt beitr\u00e4gt.<\/h1><h1>Dr. Ahmed Sousa ist einer der \u00e4ltesten irakischen Ingenieure, die ihren Abschluss an westlichen Universit\u00e4ten gemacht haben. Ahmed Sousa war Jude, konvertierte aber sp\u00e4ter zum Islam.<\/h1><h1>Nach seiner R\u00fcckkehr in den Irak wurde er 1930 als Ingenieur in die irakische Bew\u00e4sserungsbeh\u00f6rde berufen und bekleidete dann 18 Jahre lang verschiedene technische Positionen in dieser Beh\u00f6rde, bis er 1946 zum Assistenten des Leiters der Kommission ernannt wurde, die die gro\u00dfen Bew\u00e4sserungsprojekte des Irak untersuchen sollte. Im Jahr 1947 wurde er zum Generaldirektor des Vermessungsamtes ernannt, 1954 zum Generaldirektor des Landwirtschaftsministeriums und anschlie\u00dfend erneut zum Generaldirektor des Vermessungsamtes, das er bis 1957 leitete.<\/h1><h1>Nach der Gr\u00fcndung des Wiederaufbaurates im Jahr 1951 wurde er zus\u00e4tzlich zu seiner urspr\u00fcnglichen T\u00e4tigkeit zum pers\u00f6nlichen Assistenten des Vizepr\u00e4sidenten des Wiederaufbaurates in technischen Fragen ernannt. Er war eines der ersten Mitglieder der 1946 gegr\u00fcndeten Irakischen Wissenschaftlichen Gesellschaft und blieb bis zu seinem Tod ein aktives Mitglied.<\/h1><h1>In den Jahren 1939 und 1940 leitete er zwei Missionen, die von der irakischen Regierung nach Saudi-Arabien entsandt wurden, um Bew\u00e4sserungsprojekte in Al-Kharj zu untersuchen und deren Umsetzung zu \u00fcberwachen. 1938 war Dr. Ahmad Nasim Sousa einer der Gr\u00fcnder der Irakischen Gesellschaft der Ingenieure.<\/h1><h1>Zu seinen Ver\u00f6ffentlichungen z\u00e4hlen mehr als f\u00fcnfzig B\u00fccher, technische Berichte und Atlanten sowie mehr als 116 Artikel und Forschungsarbeiten, die in verschiedenen Zeitungen und wissenschaftlichen Zeitschriften erschienen sind. Seine Werke sind in den Bereichen Bew\u00e4sserung, Technik, Landwirtschaft, Geografie, Geschichte und Zivilisation verbreitet(1).<\/h1><h1>Ahmed Sousa studierte Philosophie und Geschichte, was einen gro\u00dfen Einfluss auf sein Wissen \u00fcber die falschen Glaubensvorstellungen der Juden und den Beginn des richtigen Weges hatte.<\/h1><h4>Die Geschichte von Ahmed Nassim Sousa<\/h4><h1>Ahmed Nassim Sousas Geschichte mit dem Islam begann, als er an der Amerikanischen Universit\u00e4t in Beirut studierte. Dies gab ihm die Gelegenheit, sich \u00fcber den Islam zu informieren und den Heiligen Koran zu lesen, in dem er fand, was er in der Thora und der Bibel nicht fand.<\/h1><h1>Dr. Ahmed Sousa spricht \u00fcber den Beginn seiner Schritte auf dem Weg des Glaubens:<br \/>\"Ich pflegte die Verse des Heiligen Koran zu rezitieren, und oft zog ich mich an meinen Zufluchtsort unter schattigen B\u00e4umen am Fu\u00dfe der libanesischen Berge zur\u00fcck und blieb dort stundenlang und rezitierte sie aus voller Kehle.\"<\/h1><h1>Erst als er Jahre in Amerika verbrachte, um die Philosophien der Religionen zu lesen, sich mit historischen und sozialen Fragen zu befassen und sein Wissen zu erweitern, um die Wahrheit \u00fcber die gef\u00e4lschte Geschichte zu erfahren, die von den Juden geschrieben wurde, um ihre religi\u00f6sen W\u00fcnsche zu erf\u00fcllen, zog er ernsthaft in Erw\u00e4gung, zum Islam zu konvertieren.<\/h1><h1>Er spricht auch \u00fcber das, was er im Koran gefunden hat und sagt:<br \/>\"Mir waren die von Gott geoffenbarten Verse nicht fremd, und mein Herz war beruhigt, als ich erkannte, dass die wissenschaftliche Argumentation meine angeborene Neigung unterst\u00fctzte.\"<\/h1><h1>Danach bekannte sich Dr. Ahmed Nassim Sousa mit voller \u00dcberzeugung zum Islam und widmete seine Bem\u00fchungen der Verteidigung des Islam.<\/h1><h4>Die Beitr\u00e4ge von Ahmed Nassim Sousa<\/h4><h1>Dieser Mann konvertierte vom Judentum zum Islam, um diese Religion mit aller Kraft zu verteidigen; er widmete seine Bem\u00fchungen der Darstellung der Tugenden der arabischen Zivilisation und schrieb mehrere B\u00fccher zu diesem Thema, von denen sein Buch (Araber und Juden in der Geschichte) das wichtigste ist.<\/h1><h1>Dr. Ahmed Nassim Sousa nutzte seine fr\u00fcheren Erfahrungen in der Kenntnis des Judentums, um die Behauptungen der zionistischen Bewegung aus historischer Sicht zu widerlegen, denn er kannte die falschen Texte in der Thora und k\u00fcmmerte sich darum, diese Verzerrung zu kl\u00e4ren, indem er erkl\u00e4rte, dass diese Texte das Werk der Rabbiner sind.<\/h1><h1>Zu seinen B\u00fcchern geh\u00f6ren: \"Geschichte der arabischen Halbinsel\" und \"Geschichte der Juden im Irak\".<\/h1><h1>Neben seinen zahlreichen Beitr\u00e4gen und historischen und intellektuellen Studien nach seiner Konversion zum Islam kl\u00e4rte Dr. Ahmed Sousa viele Aspekte der menschlichen Geschichte und trat den b\u00f6swilligen Versuchen entgegen, den Islam zu untergraben und sein Bild zu verf\u00e4lschen(4). Das Buch \"Auf meinem Weg zum Islam\" ist die Geschichte der Entwicklung einer wahrheitssuchenden Seele, die von der arabischen Umgebung beeinflusst wurde und dann die islamische F\u00fchrung erreichte, die Wahrheit als richtig ansah und gl\u00fccklich war, ihr zu folgen, und die Falschheit als falsch ansah und erkl\u00e4rte, sie zu meiden, und das Buch zeigt die Schw\u00e4chen der j\u00fcdischen Einheit und den Irrtum der Juden.<\/h1><h4>Der Tod von Ahmed Nassim Sousa<\/h4><h1>Dr. Ahmed Nassim Sousa verstarb im Jahr 1402 AH \/ 1982 AD.<\/h1><h5>Quelle: Dr. Ragheb al-Sarjani's Great Muslims.<\/h5><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63522\" class=\"elementor-tab-title\" data-tab=\"22\" role=\"button\" aria-controls=\"elementor-tab-content-63522\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Anne Sauv\u00e9<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63522\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"22\" role=\"region\" aria-labelledby=\"elementor-tab-title-63522\"><h1><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-36231 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/767575-286x300.jpeg\" width=\"286\" height=\"300\" \/>Wann immer ein Thema gegen Muslime in Schweden aufgeworfen wurde, machte sie sich daran, die Meinungen derer, die ihnen B\u00f6ses wollen, zu widerlegen, zu verteidigen und zu widerlegen, indem sie ihre ernsthaften Ansichten ver\u00f6ffentlichte und ihre n\u00fcchternen, auf Fakten basierenden und respektvollen Schriften verfasste, wobei sie versuchte, die schwedische Gesellschaft mit offenem Visier \u00fcber die Wahrheit \u00fcber den Islam und die Muslime aufzukl\u00e4ren, manchmal durch das Verfassen von Zeitungsartikeln, ein anderes Mal durch Fachb\u00fccher, die weite Verbreitung gefunden haben, und drittens durch direkte Treffen und Seminare.<\/h1><h1>Es war ein wahres... Ein wahres Sprachrohr f\u00fcr die Verteidigung dieser wahren Religion und ihrer Anh\u00e4nger.<\/h1><h4>Menschenrechtsaktivist<\/h4><h1>Sie ist Anne Sauve Rold, Religionshistorikerin und Dozentin f\u00fcr Islamologie, Gender- und Migrationsstudien an der Universit\u00e4t von S\u00fcdschweden in Malm\u00f6. Bevor sie vom Christentum zum Islam konvertierte, war Sauve eine der wichtigsten Forscherinnen im Bereich Islam und muslimische Fragen, da sie ihre Doktorarbeit \u00fcber die Muslimbruderschaft an der Universit\u00e4t Lund in S\u00fcdschweden vorlegte, sich dann auf islamische Geschichte spezialisierte, dann auf islamische Bewegungen und muslimische Minderheiten im Westen, um sich danach auf islamische Geschichte zu spezialisieren.<\/h1><h1>In ihrer Jugend war sie eine Menschenrechtsaktivistin, die sich f\u00fcr die Befreiung der Frauen in Norwegen einsetzte, was ihr Interesse an politischen Fragen verst\u00e4rkte. Da sie wusste, dass der Islam nicht zwischen Religion und Politik trennt, spezialisierte sie sich auf dieses Thema und verfasste mehrere B\u00fccher zu verschiedenen Themen \u00fcber den Islam in schwedischer und englischer Sprache, darunter: \"New Muslims in Europe\", \"Women in Islam\", \"Islam\", \"Experiences of Conversions to Islam in Scandinavia\" und \"Islam Belief and History\".<\/h1><h1>Die schwedische Zeitung Svenska Dag stellte fest, dass Sufis Schriften eine gro\u00dfe Rolle bei der Einf\u00fchrung in den Islam spielen, insbesondere f\u00fcr diejenigen, die sich f\u00fcr dessen Studium interessieren und deren Zahl in letzter Zeit in Europa zugenommen hat. Sie bereicherte auch die schwedische Bibliothek mit ihrem wichtigen Buch \"Muslime in Schweden\", das sie gemeinsam mit Pernilla Kois, einer weiteren zum Islam Konvertierten, verfasst hat.<\/h1><h4>Der Weg zum Glauben<\/h4><h1>Die \"Sufi\" durchlief viele komplexe Etappen der Forschung, der Erkundung und des Vergleichs, um herauszufinden, was sie bef\u00e4higt, die wahre Religion zu finden und was sie glauben soll, und weil der Mensch mit gesundem Menschenverstand immer das Richtige findet, hat sie mit ihrem Verstand erkannt, wie sie in einem ihrer Dialoge sagt: Der Mensch muss sich auf Gott zubewegen, denn Gott zwingt die Menschen nicht, an ihn zu glauben.<\/h1><h1>\u00dcber ihre religi\u00f6se Erziehung sagte sie: \"Ich lebte in \u00d6stlund, Norwegen: Ich lebte in \u00d6stlund, Norwegen, und der Glaube an Gott war in ihrer Familie weit verbreitet. Jeden Abend betete sie auf ihre eigene Weise als Christin, und sie war fest davon \u00fcberzeugt, dass Gott sie vor allem Unheil besch\u00fctzen w\u00fcrde.<\/h1><h1>Sie sagt auch: Als sie siebzehn Jahre alt war: Sie begann, das Christentum als Religion in Frage zu stellen und zu hinterfragen, warum sich die Christen untereinander bek\u00e4mpften, und sie kam zu einem gro\u00dfen Schluss: Einige Menschen benutzten Gott, um ihre Herrschaft und Autorit\u00e4t zu st\u00e4rken und Macht \u00fcber andere zu erlangen, wie es fr\u00fcher in Europa der Fall war, was sie dazu veranlasste, mehr Fragen \u00fcber Religionen zu stellen.<\/h1><h1>In den 1970er Jahren studierte sie vergleichende Religionswissenschaften und entdeckte durch ihre sorgf\u00e4ltige Forschung die Gr\u00f6\u00dfe und Objektivit\u00e4t des Islam: \"Ich fand in ihm alle Antworten auf alle Fragen und gelangte sogar zur Wahrheit \u00fcber den allm\u00e4chtigen Gott, der unser Leben auf die sch\u00f6nste und gerechteste Weise geplant hat.<\/h1><h4>Furcht (Phobie) vor dem Islam:<\/h4><h1>Sufi war entsetzt \u00fcber die weit verbreitete Islamophobie, oder, wie sie es nennen, \"Islamophobie\", und die Ernsthaftigkeit der Warnung durch die westlichen Medien, die begannen, sie zu verzerren und Muslime als Terroristen darzustellen, insbesondere nach den Ereignissen des 11. September und dem Angriff auf die Zwillingst\u00fcrme des World Trade Centers.<\/h1><h1>Das Ph\u00e4nomen der \"Islamophobie\" im Westen hat auch religi\u00f6se, kulturelle und rassistische Gr\u00fcnde, die sie in ihrem Buch erw\u00e4hnt: \"Die Muslima in Schweden\", in dem sie \u00fcber das Leben muslimischer Frauen und ihr Zusammenleben mit der schwedischen Gesellschaft berichtet, die wie andere westliche Gesellschaften anderen Werten und Konzepten folgt, und dar\u00fcber, wie Muslime in Schweden leben und die Rituale des Gebets, der Zakat, des Fastens, der Pilgerfahrt und der Transaktionen zwischen ihnen praktizieren: Sie lieferte auch einen guten Vergleich zwischen den Br\u00e4uchen der islamischen V\u00f6lker und den Auswirkungen auf die schwedischen Muslime. Sie wies auch auf seine negative und sogar misstrauische Haltung gegen\u00fcber Frauen mit Kopftuch hin.<\/h1><h1>In einer ihrer fundiertesten Studien \u00fcber Islam und Kultur betont Sufi, dass es keinen Unterschied zwischen dem Islam und der islamischen Kultur gibt: Sie argumentiert, dass es keinen Unterschied zwischen dem Islam und der islamischen Kultur gibt, wie viele zu glauben pflegten, und vertritt die Ansicht, dass sich die Regeln, auf denen der Islam beruht, mit den kulturellen Ausdrucksformen in einer ganzheitlichen Weise \u00fcberschneiden sollten; dies sei zum allgemeinen Nutzen der Menschheit.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63523\" class=\"elementor-tab-title\" data-tab=\"23\" role=\"button\" aria-controls=\"elementor-tab-content-63523\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Martin Lings<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63523\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"23\" role=\"region\" aria-labelledby=\"elementor-tab-title-63523\"><h4><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34991 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W-200x300.jpg\" width=\"200\" height=\"300\" srcset=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W-200x300.jpg 200w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W-683x1024.jpg 683w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W-768x1152.jpg 768w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W-1024x1536.jpg 1024w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W-1365x2048.jpg 1365w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W-8x12.jpg 8w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/Martin_LIngs_-_W.jpg 1568w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>Wer ist Martin Lings?<\/h4><h1>Martin Lings wurde im Januar 1909 in Lancashire, England, geboren und verbrachte seine fr\u00fche Kindheit in Amerika, wo sein Vater arbeitete. Er war Christ, ebenso wie seine Familie, die nichts \u00fcber Religion wusste, au\u00dfer dass sie erbliche Christen waren. So wuchs er ohne eine Doktrin auf, an die er wirklich glaubte.<\/h1><h1>Nach seiner R\u00fcckkehr in sein Heimatland schrieb er sich am Clinton College ein, wo er klare F\u00fchrungsqualit\u00e4ten zeigte, die ihn zum Pr\u00e4sidenten der Studenten machten. Von dort wechselte er nach Oxford, um englische Sprache und Literatur zu studieren, und die Merkmale seiner intellektuellen Reife begannen sich zu zeigen, nachdem er sein A-B-Diplom in englischer Literatur erhalten hatte; er begann, sich in Erbb\u00fcchern \u00fcber die Weltreligionen einzulesen, und die Religion des Islam zog ihn als ein Gesetz an, dessen Methodik mit Logik und Vernunft \u00fcbereinstimmt und dessen Moral f\u00fcr die Seele und das Gewissen angenehm ist.<\/h1><h1>Anschlie\u00dfend reiste er nach Litauen, um dort angels\u00e4chsisches und mittelalterliches Englisch zu unterrichten, wobei er sich auch f\u00fcr das alte Erbe des Landes in Form von Volksliedern und Gedichten interessierte.<\/h1><h1>1940 reiste er nach \u00c4gypten, um einen alten Freund an der Universit\u00e4t Kairo (damals Fouad I.) zu besuchen und Islam und Arabisch zu studieren, doch sein Freund kam bei einem Reitunfall ums Leben, und ihm wurde die Stelle angeboten, die er an der Universit\u00e4t innehatte.<\/h1><h4>Die Geschichte von Martin Lings<\/h4><h1>In \u00c4gypten konvertierte Lings zum Islam, nachdem er mehrere Sufis des Shadhiliya-Ordens kennengelernt hatte. Er wurde schnell religi\u00f6s und mystisch, \u00e4nderte seinen Namen in Abu Bakr Serageldin und wurde ein enger Freund des franz\u00f6sischen muslimischen Sufi-Schriftstellers Abdul Wahid Yahya (Ren\u00e9 Gino), da er von der Richtigkeit von dessen scharfer Kritik an der westlichen Zivilisation \u00fcberzeugt war.<\/h1><h1>Rene Gino hatte einen entscheidenden Einfluss auf Lings' Denken. Er sagt \u00fcber diesen:<\/h1><h1>\"Was mich beeinflusste und mein Interesse am Islam weckte, waren die B\u00fccher eines gro\u00dfen Autors, der wie ich zum Islam konvertierte und einer der f\u00fchrenden Sufis wurde, Scheich (Abdul Wahid Yahya). Seine B\u00fccher \u00fcber den Islam beeinflussten mich so sehr, dass ich nie zuvor so gro\u00dfartige B\u00fccher wie seine gelesen hatte; das veranlasste mich, die Person zu treffen, die der Grund f\u00fcr meinen Islam war, und so kam ich nach \u00c4gypten, wo er damals lebte.\"<\/h1><h1>Dann f\u00fcgt er hinzu: \"Ich habe viel von ihm profitiert, er war wirklich ein Gelehrter, der mit seinem Wissen arbeitete, und was ich am meisten von ihm gelernt habe, war die Askese in der Welt, was ihr 'Sufismus' nennt.\"<\/h1><h1>Wie er sagt: Der Prophet Muhammad (Friede sei mit ihm) fasste die ganze Bedeutung des Sufismus in seinem Hadith zusammen: \"Sei in der Welt, als w\u00e4rst du ein Fremder oder ein Wanderer\", oder was er in einem anderen Hadith sagte: \"... die Welt und ich sind wie ein Reisender, der unter einem Baum Schutz suchte und ihn dann verlie\u00df. Dies ist das Konzept des Sufismus, das ich von Sheikh Abdul Wahid Yahya gelernt habe.\"<\/h1><h1>Bemerkenswert ist, dass er von einem algerischen Scheich namens Scheich Ahmed Alaoui, den er in der Schweiz kennenlernte, wo er als Lehrer arbeitete, zum Islam konvertiert wurde und daraufhin seinen Namen von Martin Lings in Abu Bakr Serageldin \u00e4nderte.<\/h1><h1>Lings hatte das Gef\u00fchl, dass er mit dieser Religion, die der menschlichen Natur entspricht, zu sich selbst gefunden hatte, wie er es mit den Worten ausdr\u00fcckt: \"Ich fand im Islam das Selbst, das ich mein ganzes Leben lang vermisst hatte, und ich f\u00fchlte mich zum ersten Mal als Mensch, als eine Religion, die den Menschen zu seiner Natur zur\u00fcckf\u00fchrt, da sie mit der menschlichen Natur \u00fcbereinstimmt.\"<\/h1><h1>\"Gott wollte, dass ich Muslim werde, und wenn Gott es will, kann man ihn nicht aufhalten, und das ist der Grund, warum ich in erster Linie Muslim geworden bin\", sagte er mit einem L\u00e4cheln im Gesicht.<\/h1><h1>Das ist der britische muslimische Intellektuelle Dr. Abu Bakr Serageldin, der ein Nicht-Muslim war, dann von Gott zur toleranten Hanifiyyah gef\u00fchrt wurde; er nahm den Islam mit voller \u00dcberzeugung an, dann wurde sein Glaube erh\u00f6ht und er wurde zum Asketen in der Welt und zum Mystiker in Gesellschaften, die von Verf\u00fchrung und Versuchung der Vergn\u00fcgungen durchzogen sind, und er widmete sich dem Ruf zu Gott in seinem Land, angetrieben von der tiefen \u00dcberzeugung, dass die Zukunft dem Islam geh\u00f6rt, der die wahre Religion ist, die in alle Teile der Erde gesandt wurde.<\/h1><h1>In den 1940er Jahren lebte Lings in \u00c4gypten, wo er an der Philosophischen Fakult\u00e4t Shakespeares Gedankengut und Literatur unterrichtete.<\/h1><h1>1944 heiratete Lings Leslie Smalley, mit der er die n\u00e4chsten sechzig Jahre seine Ideen teilte. W\u00e4hrend seines Lebens in Kairo war ihr Landhaus in einem kleinen Dorf in der N\u00e4he der Pyramide ein sicherer Zufluchtsort f\u00fcr viele \u00c4gypter und Ausl\u00e4nder, die unter der Last des modernen Lebens litten.<\/h1><h1>Auf die Revolution von 1952 folgten anti-britische Demonstrationen, die sich gegen die fortgesetzte englische Besatzung \u00c4gyptens, die britische Einmischung in die inneren Angelegenheiten \u00c4gyptens, die Korruption in allen Lebensbereichen und die vielen Opfer richteten, die ohne Mitleid oder Erbarmen den Kugeln der Besatzer zum Opfer fielen. Drei von Lings' Kollegen an der Universit\u00e4t wurden bei diesen Demonstrationen get\u00f6tet, und englische Professoren wurden ohne Entsch\u00e4digung von der Universit\u00e4t entlassen.<\/h1><h1>Er kehrte 1952 nach London zur\u00fcck, wo Lings sein Studium der arabischen Sprache an der School of Oriental and African Studies in London fortsetzte. 1962 promovierte er \u00fcber \"Sheikh Ahmad Al-Alawi\" und ver\u00f6ffentlichte es in einem Buch mit dem Titel \"A Sufi Wali of the Twentieth Century\", eines seiner einflussreichsten B\u00fccher, das eine einzigartige Perspektive auf die islamische Spiritualit\u00e4t von innen heraus bietet und in der Folge in B\u00fcchern ver\u00f6ffentlicht wurde, die ins Franz\u00f6sische, Spanische und andere Sprachen \u00fcbersetzt wurden, und seither gilt Lings als einer der wichtigsten Historiker des Sufismus.<\/h1><h1>1955 arbeitete Lings am Britischen Museum, wo er zum Leiter des Kabinetts f\u00fcr orientalische Handschriften im Englischen Museum ernannt wurde und auch die Verantwortung f\u00fcr die Ehrenhandschriften des Korans \u00fcbernahm, was dazu f\u00fchrte, dass er sich der koranischen Kalligrafie zuwandte und sein Buch \"Qur'anic Art in Calligraphy and Gilding\" herauskristallisierte, dessen Ver\u00f6ffentlichung mit der Gr\u00fcndung der World Muslim Festival Foundation im Jahr 1976 zusammenfiel, zu der er eine enge Beziehung hatte.<\/h1><h1>Er erstellte auch zwei Kataloge dieser arabischen Manuskripte, die 1959 im British Museum und 1976 in der British Library ausgestellt wurden.<\/h1><h4>Martin Lings' Beitr\u00e4ge<\/h4><h1>Vor seiner Abreise aus \u00c4gypten im Jahr 1952 ver\u00f6ffentlichte Lings ein Buch mit dem Titel Das Buch der Gewissheit. Die Sufi-Lehre von Glaube, Offenbarung und Wissen. W\u00e4hrend seines Bachelor-Studiums der arabischen Sprache ver\u00f6ffentlichte er 1973 sein wortgewaltiges, auf den \u00e4ltesten Quellen basierendes Buch \"Muhammad, der Gesandte Gottes und sein Leben\", f\u00fcr das er den Preis des pakistanischen Pr\u00e4sidenten erhielt.<\/h1><h4>Martin Lings stirbt<\/h4><h1>Der Sufi-Historiker Abu Bakr Siraj al-Din (Martin Lings), bekannt als Autor der Biographie des Propheten, ist am Morgen des 12. Mai 2005 an seinem sechsundneunzigsten Geburtstag verstorben.<\/h1><h1>Trotz seines langen Lebens war die Nachricht von seinem Tod ein Schock f\u00fcr viele, die sich seit Jahren an ihn wandten, um spirituellen Rat zu erhalten, und sogar noch zehn Tage vor seinem Tod, als er im Wembley Conference Centre in London vor etwa dreitausend Zuh\u00f6rern \u00fcber den Jahrestag der Geburt des Propheten (Friede sei mit ihm) sprach, nachdem er von einer Tournee zur\u00fcckgekehrt war, die \u00c4gypten, Dubai, Pakistan und Malaysia umfasste.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63524\" class=\"elementor-tab-title\" data-tab=\"24\" role=\"button\" aria-controls=\"elementor-tab-content-63524\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Der franz\u00f6sische Maler und Denker Etienne Dennehy<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63524\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"24\" role=\"region\" aria-labelledby=\"elementor-tab-title-63524\"><h4><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34993 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/alarabi_article_image_2017_11_19299_500-190x300.jpg\" width=\"190\" height=\"300\" srcset=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/alarabi_article_image_2017_11_19299_500-190x300.jpg 190w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/alarabi_article_image_2017_11_19299_500-8x12.jpg 8w, https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/05\/alarabi_article_image_2017_11_19299_500.jpg 204w\" sizes=\"(max-width: 190px) 100vw, 190px\" \/>Wer ist Eytan Deneh?<\/h4><h1>Alphonse Etienne Denis, 1861 in Paris geboren und im Alter von siebzig Jahren gestorben, ist einer der weltweit f\u00fchrenden K\u00fcnstler und Maler, dessen Werke im Larousse-W\u00f6rterbuch verzeichnet sind und dessen kostbare Gem\u00e4lde die W\u00e4nde der Kunstgalerien in Frankreich schm\u00fccken, darunter sein ber\u00fchmtes Gem\u00e4lde (Ghada Ramadan), und er zeichnete sich durch seine W\u00fcstenmalerei aus.<\/h1><h4>Seine Geschichte \u00fcber den Islam<\/h4><h1>Dennehy beschreibt, wie er den Islam kennenlernte: \"Ich habe das Buch Allahs studiert und festgestellt, dass es ein Leitfaden f\u00fcr die gesamte Menschheit ist, und ich habe darin gefunden, was das geistige und materielle Wohlergehen des Menschen garantiert, also habe ich geglaubt, dass es die beste Religion f\u00fcr die Anbetung Allahs ist, und ich habe sie als meine Religion angenommen und sie offiziell in der \u00d6ffentlichkeit erkl\u00e4rt.\"<\/h1><h4>Seine Beitr\u00e4ge<\/h4><h1>Nach seiner Konvertierung zum Islam schrieb Eytan Deneh viele wertvolle B\u00fccher, darunter sein einzigartiges Buch \"Besondere Strahlen des Lichts des Islam\" sowie \"Fr\u00fchling der Herzen\", \"Der Osten aus der Sicht des Westens\" und \"Muhammad ist der Gesandte Gottes\". Die Pilgerfahrt von \"Nasir al-Din Dinah\" zum Heiligen Haus Allahs im Jahr 1928 n. Chr. beeinflusste ihn, das Buch (Pilgerfahrt zum Heiligen Haus Allahs) zu schreiben, das von Amir Shakib Arslan mit den Worten gelobt wurde: \"Er wurde Muslim, machte eine Pilgerreise und schrieb ein Buch \u00fcber seine Pilgerreise zum Heiligen Haus, eines der wunderbarsten B\u00fccher, die in diesem Zeitalter geschrieben wurden.\"<\/h1><h1>Das Buch besteht aus einer Einleitung, sieben Kapiteln und einem Anhang mit zwei Kapiteln, die alle mehr als zweihundert Seiten umfassen. Nasir al-Dins Buch ist mit acht handgefertigten Fotografien der Kaaba, des Haram al-Sharif, der Ansicht der Pilgerfahrt in Arafat, des Maghrib-Gebetes um die Kaaba und des Berges des Lichts illustriert, wo der Prophet die erste Offenbarung erhielt, als er zum ersten Mal hinabstieg.<\/h1><h1>Sein Buch behandelte die Reisen des Schweizer Reisenden Birkhard in seinem Buch (Journey to Arabia) im Jahr 1914, des englischen Reisenden Burton in seinem Buch (Pilgrimage to Mecca and Medina), des franz\u00f6sischen Reisenden Leon Roche, der im Auftrag des franz\u00f6sischen Generals (Bijou) eine Reise in den Hidschas unternahm und sein Buch (Ten Years in Islam) ver\u00f6ffentlichte Er ver\u00f6ffentlichte sein Buch (Ten Years in the Land of Islam), der franz\u00f6sische Reisende Lope Leco in seinem Buch (In the Land of Secrets: A Christian Pilgrimage to Mecca and Medina), Grove Cole Tilmon in seinem Buch (A Journey to Mecca) im Jahr 1896 und Belgrave in seinem Buch (A Year in Central Arabia).<\/h1><h1>Dieses Buch ist eine umfassende und faire \u00dcberpr\u00fcfung aller fr\u00fcheren B\u00fccher, in denen er die versteckten Ziele der Reisen der Orientalisten aufdeckt, w\u00e4hrend er gleichzeitig jenen Orientalisten gerecht wird, die in ihren Schriften wahrheitsgetreu und genau waren, und er behandelt Themen wie: Orientalisten und der Heilige Koran; Orientalisten und die arabische Sprache; Orientalismus und arabische Kalligraphie und die Forderung nach dem lateinischen Buchstaben; Orientalismus und arabische Poesie.<\/h1><h1>Seine B\u00fccher haben in Orientalistenkreisen hohe Wellen geschlagen.<\/h1><h1>Er verteidigte auch die arabische Schrift, indem er die S\u00fcnde derjenigen darstellte, die sie durch eine andere Schrift ersetzen wollten: \"Die arabische Schrift ist die sch\u00f6nste Kunstform, die die Menschheit kennt, und die sch\u00f6nste Schrift, in der man ohne \u00dcbertreibung sagen kann: Sie hat eine Seele, die der menschlichen Stimme entspricht, in \u00dcbereinstimmung mit musikalischen Melodien.\"<\/h1><h1>Er beschrieb auch die arabische Schrift als: \"Sie ist ein Schl\u00fcssel, der die Geheimnisse der subtilen Bewegungen des Herzens offenbart, als ob ihre Buchstaben der Kraft eines str\u00f6menden Geistes unterworfen sind, so dass man sie manchmal in sch\u00f6nen geometrischen Formen zusammenwinden sieht, w\u00e4hrend sie alle in ihnen gespeicherten Geheimnisse bewahren, und manchmal sieht man sie pl\u00f6tzlich beginnen und aufh\u00f6ren, als ob sie sich selbst bewundern, und manchmal sieht man sie rennen, sich umarmen und manchmal zerstreuen.\"<\/h1><h1>\"Wenn ich ihre attraktiven Formen betrachte, versetzen mich meine Gedanken in ferne Tr\u00e4ume, und ich muss kein Westler oder Magier sein, um mich an ihrer einmaligen Sch\u00f6nheit zu erfreuen, sondern jeder Mensch, in dem ein Kunstgeist steckt, wird von dieser Schrift in den Bann gezogen\", f\u00fcgt er hinzu.<\/h1><h1>Er betont, dass die arabische Kalligrafie dadurch gekennzeichnet ist, dass man von rechts nach links schreibt und dabei der nat\u00fcrlichen Bewegung der Hand folgt, so dass uns das Schreiben leichter und schneller f\u00e4llt als das Schreiben von links nach rechts; aus diesem Grund hat der gro\u00dfe K\u00fcnstler (Leonardo da Vinci) nach der Regel der arabischen Kalligrafie von rechts nach links gezeichnet und geschrieben.<\/h1><h4>Seine Spr\u00fcche<\/h4><h1>\"Der Islam hat von der ersten Stunde seines Entstehens an bekr\u00e4ftigt, dass er eine Religion ist, die f\u00fcr jede Zeit und jeden Ort g\u00fcltig ist, denn er ist die Religion des Instinkts, und der Instinkt unterscheidet sich nicht von dem eines anderen Menschen, so dass er f\u00fcr jede Stufe der Zivilisation g\u00fcltig ist.\"<\/h1><h1>Als begabter K\u00fcnstler f\u00fchlte sich Dennehy von den \u00e4sthetischen und geschmackvollen Aspekten des Lebens des Propheten angezogen: \"Der Prophet achtete sehr auf sich selbst und war bekannt daf\u00fcr, dass sein Kleidungsstil sehr einfach, aber sehr geschmackvoll und sch\u00f6n war.\"<\/h1><h1>\"Die regelm\u00e4\u00dfigen Gebetsbewegungen kommen K\u00f6rper und Seele zugute und sind von einer Einfachheit und Sanftheit, die in anderen Gebeten nicht zu finden ist\".<\/h1><h1>Er sagt \u00fcber Polygamie: \"Die Polygamie ist unter den Muslimen weniger verbreitet als unter den Westlern, die den Genuss der verbotenen Fr\u00fcchte finden, wenn sie vom Prinzip der Monogamie abweichen!<\/h1><h1>Ist es wahr, dass das Christentum die Polygamie verbietet? Kann man das sagen, ohne zu lachen?<\/h1><h1>Polygamie ist ein Naturgesetz und wird bestehen bleiben, solange es die Welt gibt. Die Monogamie-Theorie hat drei gef\u00e4hrliche Ergebnisse hervorgebracht: Jungfern, Prostituierte und uneheliche Kinder.\"<\/h1><h1 class=\"redbigtitle\">Sein Tod<\/h1><h1>Im Dezember 1929 starb Nasser al-Din Din\u00e9 in Paris, wurde in der Gro\u00dfen Moschee in Anwesenheit islamischer W\u00fcrdentr\u00e4ger und des Ministers f\u00fcr Wissen im Namen der franz\u00f6sischen Regierung beigesetzt und anschlie\u00dfend nach Algerien \u00fcberf\u00fchrt, wo er auf dem Friedhof beigesetzt wurde, den er gem\u00e4\u00df seinem Testament in der Stadt Boussaada angelegt hatte.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-63525\" class=\"elementor-tab-title\" data-tab=\"25\" role=\"button\" aria-controls=\"elementor-tab-content-63525\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus-circle\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Der franz\u00f6sische Philosoph Rene Gino<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-63525\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"25\" role=\"region\" aria-labelledby=\"elementor-tab-title-63525\"><h4><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36233 alignleft\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2025\/06\/7645644.jpg\" width=\"214\" height=\"235\" \/>Wer ist Rene Gino?<\/h4><h1>Der \u00dcbertritt von Rene Gino vom Christentum zum Islam, nachdem er die Freimaurerei und die Philosophien des alten Ostens studiert hatte, war keine Frage des Schwankens und der Unbest\u00e4ndigkeit oder der Liebe zum Wandel, sondern eine Suche nach der verlorenen Wahrheit, einer Wahrheit, die einst den Menschen mit dem weiten Universum in einem weisen Gleichgewicht verband und deren Faden dann unter dem Druck dieses materialistischen Zeitalters zerrissen wurde. Er ist Abdul Wahid Yahya, der zum Islam konvertierte und einen Plan zum Bau der Gro\u00dfen Moschee in Paris vor dem Ersten Weltkrieg und zur Gr\u00fcndung einer islamischen Universit\u00e4t in Frankreich entwickelte.<\/h1><h1>Ren\u00e9 Gineau wurde am 15. November 1886 in Blois, s\u00fcdwestlich von Paris, geboren und wuchs in einer konservativen katholischen Familie auf. Ren\u00e9 war von schwacher Statur, was ihn am Schulbesuch hinderte, und so brachte ihm seine Tante Doro in ihrem sch\u00f6nen Haus am Ufer der Loire das Lesen und Schreiben bei, bis er zw\u00f6lf Jahre alt war.<\/h1><h1>Im Alter von sechzehn Jahren schrieb er sich am Pariser Roland-Kolleg ein und begn\u00fcgte sich nicht mit einem Universit\u00e4tsstudium, sondern begann, in Paris zu lernen, wo es viele Lehrer und Mentoren aus Ost und West gibt.<\/h1><h1>1906 kam er in Kontakt mit der Freien Schule f\u00fcr okkulte Studien in Lapus und wechselte zu anderen Organisationen wie dem Martinismus und der Freimaurerei des Spanischen Nationalritus. 1908 trat er der Gro\u00dfen Freimaurerloge in Frankreich bei und schloss sich der gnostischen Kirche an, die das Gegenteil der etablierten Kirche ist, die an die Inkarnation Gottes (des Allm\u00e4chtigen) in menschlicher Gestalt usw. glaubt (der Allm\u00e4chtige steht \u00fcber dem, was sie sagen), und in dieser Zeit traf er viele Pers\u00f6nlichkeiten, die es ihm erm\u00f6glichten, seine Kenntnisse des chinesischen Taoismus und des Islam zu vertiefen.<\/h1><h1>Ende 1909 wurde Rene Gino zum gnostischen Bischof in der gnostischen Kirche von Alexandria ernannt. Er gr\u00fcndete das Journal of Gnosis und ver\u00f6ffentlichte eine Reihe von Artikeln in dieser Zeitschrift, aber seine Kritik an dieser Kirche war stark, da er der Meinung war, dass die modernen spirituellen Lehren nichts anderes als ein neuer Materialismus auf einer anderen Ebene sind und ihr einziges Anliegen darin besteht, die Methodik der positivistischen Wissenschaft auf die Seele anzuwenden.<\/h1><h4>Seine Geschichte \u00fcber den Islam<\/h4><h1>Seine Bekanntschaft mit dem schwedischen Intellektuellen und Maler \"Jean Gustav Agli\" - der 1897 zum Islam konvertierte und Abdul Hadi hie\u00df und der Mitherausgeber einer arabisch-italienischen Zeitschrift namens \"The Club\" war - hatte den gr\u00f6\u00dften Einfluss auf seinen Islam, zumal Gino viele Artikel \u00fcber den ber\u00fchmten arabischen Mystiker Muhyi al-Din ibn Arabi ver\u00f6ffentlichte.<\/h1><h1>Abdul Hadi begann 1910, flei\u00dfig und aktiv dazu beizutragen, indem er Forschungen ver\u00f6ffentlichte und zahlreiche Sufi-Texte ins Franz\u00f6sische \u00fcbersetzte. Abdul Hadi konnte durch den Austausch von Briefen und Meinungen eine starke und solide Beziehung zwischen Gino und Sheikh Alish - den er zum Islam konvertierte - herstellen, die dazu f\u00fchrte, dass Gino 1912 nach eingehendem Studium zum Islam konvertierte und den Namen Abdul Wahid Yahya annahm.<\/h1><h1>Imam Abdul Halim Mahmoud sagt \u00fcber den Grund f\u00fcr den Islam von Rene Gino: \"Der Grund f\u00fcr seinen Islam war einfach und logisch zugleich: \"Der Grund f\u00fcr seinen Islam war einfach und logisch zugleich: Er wollte zu einem heiligen Text Zuflucht nehmen, der keine Falschheit zwischen seinen H\u00e4nden oder hinter ihm empf\u00e4ngt. Nach seinem gr\u00fcndlichen Studium fand er nur den Koran, das einzige Buch, das nicht verf\u00e4lscht oder ver\u00e4ndert wurde, weil Gott seine Bewahrung garantiert hat; er nahm zu ihm Zuflucht und wandelte unter seinem Banner und wurde von psychologischer Sicherheit im Geist des Furqan \u00fcberw\u00e4ltigt.\"<\/h1><h1>Im Juli 1915 erwarb Gino den Bachelor of Arts in Philosophie an der ber\u00fchmten Universit\u00e4t Sorbonne und setzte dann sein Studium fort, wo er das Postgraduierten-Diplom DES erwarb. 1917 wurde er zum Philosophieprofessor in Algerien ernannt, wo er ein Jahr verbrachte, dann kehrte er in die franz\u00f6sische Stadt Blois zur\u00fcck, aber der Aufenthalt in seiner Stadt gefiel ihm nicht und er verlie\u00df sie in Richtung Paris, um seine Doktorarbeit \u00fcber \"Leibniz und die Differentialrechnung\" vorzubereiten, aber wegen seiner intellektuellen Unabh\u00e4ngigkeit und Offenheit f\u00fcr seine Ideen weigerte sich sein Doktorvater, ihm diesen Titel zu verleihen. Im Jahr 1918 begann Gino mit der Vorbereitung auf sein Philosophiestudium.<\/h1><h1>Dies hielt Scheich Abdul Wahid Yahya nicht davon ab, seine Arbeit fortzusetzen und sich seinen Forschungen zu widmen. Das Ergebnis dieser Hingabe war die Ver\u00f6ffentlichung von zwei B\u00fcchern im Jahr 1921, darunter \"Introduction to the Study of Indian Beliefs\".<\/h1><h1>1925 \u00f6ffnete ihm die Zeitschrift \"Maske der Isis\" ihre Pforten, in der er zu schreiben begann, und 1929 wurde er schlie\u00dflich ihr wichtigster Redakteur, obwohl er sich weigerte, Chefredakteur zu werden.<\/h1><h1>1925 hielt Scheich Abdul Wahid Yahya an der Universit\u00e4t Sorbonne eine der wichtigsten Vorlesungen mit dem Titel \"\u00d6stliche Metaphysik\", in der er den Unterschied zwischen dem Osten und dem Westen auf dem Gebiet des Okkulten erl\u00e4uterte und erkl\u00e4rte, dass die Metaphysik weder im Osten noch im Westen dieselbe ist, genau wie die reine Wahrheit, aber ihr Konzept oder ihr Ansatz unterscheidet sich Der von ihm gew\u00e4hlte Begriff \"orientalisch\" bezieht sich auf das Studium des Okkulten im Osten im Allgemeinen und nicht nur auf Indien; die \u00f6stlichen Zivilisationen haben dieselbe Kontinuit\u00e4t und werden immer noch als kompetente Vertreter angesehen, die man f\u00fcr wahre Informationen heranziehen kann, da den westlichen Zivilisationen diese langj\u00e4hrigen Urspr\u00fcnge fehlen.<\/h1><h1>Im Jahr 1927 ver\u00f6ffentlichte er sein Buch \"Der K\u00f6nig der Welt\" oder \"Der Pole\" und brachte sein Buch \"Die Krise der modernen Welt\" heraus, das ein gro\u00dfer Erfolg war und dutzende Male in luxuri\u00f6sen und popul\u00e4ren Ausgaben nachgedruckt wurde. Dieses Buch ist keine Einladung zur Introversion, sondern ein Aufruf zum richtigen Verst\u00e4ndnis und zur kritischen Betrachtung der westlichen Zivilisation als menschliches Werk, das Kritik vertr\u00e4gt und ihr nicht \u00fcberlegen ist.<\/h1><h1>Kairo Endlich<\/h1><h1>Der Pariser Verlag bot Scheich Abdul Wahid Yahya an, nach \u00c4gypten zu reisen, um mit der Sufi-Kultur in Kontakt zu treten, Texte zu transkribieren und einige davon zu \u00fcbersetzen. So zog er 1930 nach Kairo, wo er eigentlich nur einige Monate verbringen sollte, aber diese Arbeit nahm viel Zeit in Anspruch, und der Verlag \u00e4nderte sein Projekt, so dass Scheich Abdul Wahid Yahya weiterhin in Kairo im Al-Azhar-Viertel lebte, bescheiden und versteckt, ohne Kontakt zu Europ\u00e4ern, ohne \u00f6ffentliches Leben, sondern seine ganze Zeit mit seinen Studien verbringend.<\/h1><h1>Er kam allein nach Kairo und hatte viele Schwierigkeiten, auf sich allein gestellt zu sein. 1934 heiratete er Karima Sheikh Muhammad Ibrahim, mit der er vier Kinder hatte.<\/h1><h1>Scheich Abdul Wahid wollte die Sufi-Kultur in \u00c4gypten verbreiten und gr\u00fcndete daher in Zusammenarbeit mit Abdul Aziz al-Istanbuli die Zeitschrift \"Wissen\", und die Wahl dieses Namens mag einen Teil seines Denkens offenbaren: Wissen ist einer der Wege, die zu Gott f\u00fchren, der andere Weg ist die Liebe.<\/h1><h1>Das Programm der Zeitschrift war also ein ganzes Projekt, das darauf abzielte, das Wissen einer wahrhaft heiligen Wissenschaft kennen zu lernen. Scheich Abdul Wahid Yahya schrieb weiterhin B\u00fccher, Artikel und Briefe, eine st\u00e4ndige geistige und spirituelle Bewegung.<\/h1><h4>Seine Beitr\u00e4ge<\/h4><h1>Scheich Abdul Wahid Yahya hinterlie\u00df zahlreiche Werke, in denen er den Islam und sein Image im Westen verteidigte und sich gegen das von den Orientalisten verbreitete Bild wandte, der Islam sei durch das Schwert verbreitet worden und bringe keine tiefe Spiritualit\u00e4t hervor.<\/h1><h1>Mit seinen B\u00fcchern, von denen die wichtigsten sind, hat er dazu beigetragen, auf diese Anschuldigungen zu reagieren:<\/h1><h1>Der Irrtum des Spiritualismus, Ost und West, Dantes Esoterik, der Mensch und seine Zukunft nach dem Vedanta, die Krise der modernen Welt, der K\u00f6nig der Welt, der Heilige Bernhard, die Symbolik des Kreuzes, die geistige Macht und die weltliche Macht, die verschiedenen Existenzweisen, kritische Darlegungen, die Quanten\u00fcberlegenheit und die Zeichen der Zeit, die \u00f6stliche Metaphysik, Einblicke in die spirituelle Massage, die Dreifaltigkeit, die Prinzipien der Differentialrechnung, Einblicke in die christliche Esoterik und Anf\u00e4nge: Eine Studie \u00fcber Freimaurerei und Bruderschaften (zwei Teile), Traditionelle Bilder und kosmische Zyklen, Einblicke in den islamischen Sufismus und Taoismus und Verstreute Schriften.<\/h1><h4>Sein Tod<\/h4><h1>Er starb 1951 im Alter von vierundsechzig Jahren in Kairo, umgeben von seiner Frau, seinen drei S\u00f6hnen und einem sich noch entwickelnden F\u00f6tus, und das letzte Wort, das er sprach, war der Name \"Allah\" in der Einzahl.<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a11fe1 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"4a11fe1\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bad0908\" data-id=\"bad0908\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1eb8e1d elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1eb8e1d\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-f67163c e-flex e-con-boxed e-con e-parent\" data-id=\"f67163c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08ceee1 elementor-widget elementor-widget-heading\" data-id=\"08ceee1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum sie Muslime wurden Video<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-492058f e-flex e-con-boxed e-con e-parent\" data-id=\"492058f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8dbbefd e-con-full e-flex e-con e-child\" data-id=\"8dbbefd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9d628c7 e-con-full e-flex e-con e-child\" data-id=\"9d628c7\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3ffe345 e-con-full e-flex e-con e-child\" data-id=\"3ffe345\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97d1466 elementor-widget elementor-widget-video\" data-id=\"97d1466\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=r24WPPuoxSo&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-459dffd elementor-widget elementor-widget-heading\" data-id=\"459dffd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Christian kommt nach 20 Minuten zur\u00fcck, um sich vor der Menge zum Islam zu bekennen, und das Ticket von Nike treibt ihr die Tr\u00e4nen in die Augen\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcd4f81 e-con-full e-flex e-con e-child\" data-id=\"dcd4f81\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9dd706 elementor-widget elementor-widget-video\" data-id=\"a9dd706\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=CaLACDBc3BM&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b143bd elementor-widget elementor-widget-heading\" data-id=\"9b143bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eine Christin fragte nach Mohammed in der Bibel und konvertierte nach der Antwort zum Islam - Dr. Zakir Naik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0267d86 e-con-full e-flex e-con e-child\" data-id=\"0267d86\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d02b969 elementor-widget elementor-widget-video\" data-id=\"d02b969\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=qxAsMFiUrdc&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f14e5e4 elementor-widget elementor-widget-heading\" data-id=\"f14e5e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Japaner konvertieren bei Zakir Naiks Vortr\u00e4gen zum Islam\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0708b6 e-flex e-con-boxed e-con e-parent\" data-id=\"c0708b6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-35121e8 e-con-full e-flex e-con e-child\" data-id=\"35121e8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b95711 e-con-full e-flex e-con e-child\" data-id=\"7b95711\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-75d64a7 e-con-full e-flex e-con e-child\" data-id=\"75d64a7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ddc7c0 elementor-widget elementor-widget-video\" data-id=\"0ddc7c0\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=RU9pa4Xipwg&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b6e5ae elementor-widget elementor-widget-heading\" data-id=\"0b6e5ae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arzt fragt Dr. Zakir Naik und konvertiert zum Islam, nachdem er die Antwort erhalten hat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52f350a e-con-full e-flex e-con e-child\" data-id=\"52f350a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54508c1 elementor-widget elementor-widget-video\" data-id=\"54508c1\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=WzkjgPnyYMQ&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e062c1 elementor-widget elementor-widget-heading\" data-id=\"0e062c1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e4dchen sagt, wenn Sie meine letzte Frage beantworten, werde ich zum Islam konvertieren - Dr. Zakir Naik<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc17594 e-con-full e-flex e-con e-child\" data-id=\"fc17594\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de979a5 elementor-widget elementor-widget-video\" data-id=\"de979a5\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=RBr-dfc68_s&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0923be elementor-widget elementor-widget-heading\" data-id=\"d0923be\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Australisches M\u00e4dchen erz\u00e4hlt die Geschichte ihrer Konversion zum Islam\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4760741 e-flex e-con-boxed e-con e-parent\" data-id=\"4760741\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b77d5fa e-con-full e-flex e-con e-child\" data-id=\"b77d5fa\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bc9ad49 e-con-full e-flex e-con e-child\" data-id=\"bc9ad49\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e1e68bd e-con-full e-flex e-con e-child\" data-id=\"e1e68bd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7447505 elementor-widget elementor-widget-video\" data-id=\"7447505\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=gw9fKkNlhKA&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&amp;index=3&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14d58d0 elementor-widget elementor-widget-heading\" data-id=\"14d58d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Champion Wrestler wird nach einer bemerkenswerten Geschichte Muslim - US. Champion Wrestler wird Muslim\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d5fe65 e-con-full e-flex e-con e-child\" data-id=\"4d5fe65\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c738f8 elementor-widget elementor-widget-video\" data-id=\"9c738f8\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=NbwBW-_f1a0&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&amp;index=7&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-164a6b8 elementor-widget elementor-widget-heading\" data-id=\"164a6b8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ber\u00fchmte Konvertiten zum Islam - .\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46e7899 e-con-full e-flex e-con e-child\" data-id=\"46e7899\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d195ed0 elementor-widget elementor-widget-video\" data-id=\"d195ed0\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=dXqqtpoMZrA&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&amp;index=12&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f01918c elementor-widget elementor-widget-heading\" data-id=\"f01918c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Australischer Mann konvertiert auf wundersame Weise zum Islam\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8dd91b e-flex e-con-boxed e-con e-parent\" data-id=\"c8dd91b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9b0df6c e-con-full e-flex e-con e-child\" data-id=\"9b0df6c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c663bf2 e-con-full e-flex e-con e-child\" data-id=\"c663bf2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9906218 e-con-full e-flex e-con e-child\" data-id=\"9906218\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85234fb elementor-widget elementor-widget-video\" data-id=\"85234fb\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=pEFOTQf_QkA&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&amp;index=13&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25a5f27 elementor-widget elementor-widget-heading\" data-id=\"25a5f27\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Geschichte eines zum Islam konvertierten Engl\u00e4nders\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c909c5 e-con-full e-flex e-con e-child\" data-id=\"8c909c5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3e52e1 elementor-widget elementor-widget-video\" data-id=\"a3e52e1\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=0n7AQnN5fOw&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&amp;index=19&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c5452a elementor-widget elementor-widget-heading\" data-id=\"7c5452a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum sind sie Muslime geworden? Ein britischer Polizist erz\u00e4hlt von seinem \u00dcbertritt zum Islam und weint.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f6fa7c e-con-full e-flex e-con e-child\" data-id=\"3f6fa7c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a365eb elementor-widget elementor-widget-video\" data-id=\"1a365eb\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=skaCLhTs8_4&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&amp;index=20&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-605ca88 elementor-widget elementor-widget-heading\" data-id=\"605ca88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fitna Filmverleiher wurde Muslim wegen Surah #Durch den Koran wurde ich gef\u00fchrt2 H4 Fitna Filmverleiher wurde Muslim\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d7bf02 e-flex e-con-boxed e-con e-parent\" data-id=\"2d7bf02\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-29137d7 e-con-full e-flex e-con e-child\" data-id=\"29137d7\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c90d2f9 e-con-full e-flex e-con e-child\" data-id=\"c90d2f9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0bf587d e-con-full e-flex e-con e-child\" data-id=\"0bf587d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9d3f0d elementor-widget elementor-widget-video\" data-id=\"a9d3f0d\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=gyiP4DcaYww&amp;list=PLIGNg47JCTHimGGn6liv5kBYZiWXqFQkk&amp;index=21&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc064af elementor-widget elementor-widget-heading\" data-id=\"dc064af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">US-Rap-S\u00e4nger wird durch eine wundersame Vision zum Muslim - US-Rap-S\u00e4nger wird Muslim\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cba8a17 e-con-full e-flex e-con e-child\" data-id=\"cba8a17\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3124a04 elementor-widget elementor-widget-video\" data-id=\"3124a04\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=OeVT8JZfyno&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6127973 elementor-widget elementor-widget-heading\" data-id=\"6127973\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EP5 Gef\u00fchrt durch den Koran EP5 Gef\u00fchrt durch den Koran\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50699e0 e-con-full e-flex e-con e-child\" data-id=\"50699e0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96ca694 elementor-widget elementor-widget-video\" data-id=\"96ca694\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=-t_Wl6IQKXE&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef4b6e5 elementor-widget elementor-widget-heading\" data-id=\"ef4b6e5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vom hasserf\u00fcllten Hasser zum liebenden Gl\u00e4ubigen - Joram van Klaverens Reise des Glaubens\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-279740e e-flex e-con-boxed e-con e-parent\" data-id=\"279740e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-76399b5 e-con-full e-flex e-con e-child\" data-id=\"76399b5\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-efa1317 e-con-full e-flex e-con e-child\" data-id=\"efa1317\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c3e29eb e-con-full e-flex e-con e-child\" data-id=\"c3e29eb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22d9e61 elementor-widget elementor-widget-video\" data-id=\"22d9e61\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=GvEhbHrOTUA&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2161c6 elementor-widget elementor-widget-heading\" data-id=\"d2161c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niederl\u00e4ndischer junger Mann konvertiert zum Islam - versuchen Sie nicht zu weinen\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e8d6403 e-con-full e-flex e-con e-child\" data-id=\"e8d6403\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11329c5 elementor-widget elementor-widget-video\" data-id=\"11329c5\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Euy1-3MrPrw&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ece5c82 elementor-widget elementor-widget-heading\" data-id=\"ece5c82\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Yusuf Estes vom katholischen Priester zum islamischen Prediger<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7093cd1 e-con-full e-flex e-con e-child\" data-id=\"7093cd1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b152785 elementor-widget elementor-widget-video\" data-id=\"b152785\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Ykoc116Qqf0&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70a4ed6 elementor-widget elementor-widget-heading\" data-id=\"70a4ed6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Sarah Lauren Booth in Manchester<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e24b38 e-flex e-con-boxed e-con e-parent\" data-id=\"0e24b38\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8f160be e-con-full e-flex e-con e-child\" data-id=\"8f160be\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-370f116 e-con-full e-flex e-con e-child\" data-id=\"370f116\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-30f5ad1 e-con-full e-flex e-con e-child\" data-id=\"30f5ad1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-984d6b3 elementor-widget elementor-widget-video\" data-id=\"984d6b3\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=q4KHPzOhA0E&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b66552 elementor-widget elementor-widget-heading\" data-id=\"3b66552\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Japanische Frau konvertiert mit einem r\u00fchrenden Schluck Wasser zum Islam <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a77f960 e-con-full e-flex e-con e-child\" data-id=\"a77f960\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-441403b elementor-widget elementor-widget-video\" data-id=\"441403b\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=j0taoL5wA2A&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c675544 elementor-widget elementor-widget-heading\" data-id=\"c675544\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die Geschichte eines Russen, der aufgrund der Sura Al-Qara'ah zum Islam fand, ist ber\u00fchrend <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab673c5 e-con-full e-flex e-con e-child\" data-id=\"ab673c5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f287cd3 elementor-widget elementor-widget-video\" data-id=\"f287cd3\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Bh5I8yOVSGA&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f104355 elementor-widget elementor-widget-heading\" data-id=\"f104355\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bilal aus Belgien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec8b259 e-flex e-con-boxed e-con e-parent\" data-id=\"ec8b259\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2b0a18e e-con-full e-flex e-con e-child\" data-id=\"2b0a18e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-15f06ba e-con-full e-flex e-con e-child\" data-id=\"15f06ba\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fc1d1d8 e-con-full e-flex e-con e-child\" data-id=\"fc1d1d8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00c7dfd elementor-widget elementor-widget-video\" data-id=\"00c7dfd\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=zEYfkVLQSY8&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f725f elementor-widget elementor-widget-heading\" data-id=\"07f725f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schwedische Muslimin wegen ihres Hidschabs verpr\u00fcgelt <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c49369 e-con-full e-flex e-con e-child\" data-id=\"4c49369\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-935eedb elementor-widget elementor-widget-video\" data-id=\"935eedb\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=EO2kx0iYNEE&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce09f0 elementor-widget elementor-widget-heading\" data-id=\"5ce09f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die amerikanische NFL und die Geschichte seiner Bekehrung und seiner Niederwerfung auf dem Spielfeld<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0a39a98 e-con-full e-flex e-con e-child\" data-id=\"0a39a98\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de4e471 elementor-widget elementor-widget-video\" data-id=\"de4e471\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=udC_1N0vNhM&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23310fe elementor-widget elementor-widget-heading\" data-id=\"23310fe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Der brasilianische Polizist, der von den Werten der Gerechtigkeit im Islam beeinflusst wurde<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-407bbc1 e-flex e-con-boxed e-con e-parent\" data-id=\"407bbc1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a5ff72c e-con-full e-flex e-con e-child\" data-id=\"a5ff72c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5739096 e-con-full e-flex e-con e-child\" data-id=\"5739096\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-87f836e e-con-full e-flex e-con e-child\" data-id=\"87f836e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-215d94a elementor-widget elementor-widget-video\" data-id=\"215d94a\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=e05zYdgSfso&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82dc44a elementor-widget elementor-widget-heading\" data-id=\"82dc44a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0623\u062c\u0645\u0644 \u0644\u062d\u0638\u0627\u062a \u0646\u0637\u0642 \u0627\u0644\u0634\u0647\u0627\u062f\u0629\u261d\ufe0f\u0623\u0628\u0643\u062a \u0627\u0644\u0646\u0633\u0627\u0621\ud83d\ude22 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0648\u0623\u0645\u0631\u064a\u0643\u0627 \/ Women crying when converting to Islam\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34e5c92 e-con-full e-flex e-con e-child\" data-id=\"34e5c92\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68df53b elementor-widget elementor-widget-video\" data-id=\"68df53b\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=QhAa2quhIuM&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-538d761 elementor-widget elementor-widget-heading\" data-id=\"538d761\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0623\u062c\u0645\u0644 \u0644\u062d\u0638\u0627\u062a \u0646\u0637\u0642 \u0627\u0644\u0634\u0647\u0627\u062f\u0629\u261d\ufe0f\u0623\u0628\u0643\u062a \u0627\u0644\u0634\u0628\u0627\u0628 \u0648\u0631\u062c\u0627\u0644\ud83d\ude22 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0648\u0623\u0645\u0631\u064a\u0643\u0627 \/ Guys crying when converting to Islam\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-698496a e-con-full e-flex e-con e-child\" data-id=\"698496a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1123ea5 elementor-widget elementor-widget-video\" data-id=\"1123ea5\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_nLKj1LzQCA&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a98d6da elementor-widget elementor-widget-heading\" data-id=\"a98d6da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u0644\u0647 \u0623\u0643\u0628\u0631 : \u0637\u0648\u0641\u0627\u0646 \u0627\u0644\u0645\u0633\u0644\u0645\u064a\u0646 \u0627\u0644\u062c\u062f\u062f\u261d\ufe0f\u064a\u062c\u062a\u0627\u062d \u0627\u0654\u0648\u0631\u0648\u0628\u0627 \ud83c\uddfa\ud83c\uddf8 \u0648\u0623\u0645\u0631\u064a\u0643\u0627 Boys and girls converting to Islam\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dedab7 e-flex e-con-boxed e-con e-parent\" data-id=\"0dedab7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d2ad018 e-con-full e-flex e-con e-child\" data-id=\"d2ad018\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-59eeaf0 e-con-full e-flex e-con e-child\" data-id=\"59eeaf0\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-92f5703 e-con-full e-flex e-con e-child\" data-id=\"92f5703\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dba5402 elementor-widget elementor-widget-video\" data-id=\"dba5402\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=eOEh_QGWaVw&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49c37e0 elementor-widget elementor-widget-heading\" data-id=\"49c37e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0639\u0634\u0631\u0627\u062a \u0627\u0644\u0646\u0633\u0627\u0621 \u064a\u0639\u062a\u0646\u0642\u0646 \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0641\u064a \u0627\u0633\u062a\u0631\u0627\u0644\u064a\u0627\u261d\ufe0f\u0628\u0633\u0628\u0628 \u0635\u0645\u0648\u062f \u063a\u0632\u0629 sister Australian people become a Muslims\ud83c\udded\ud83c\uddf2\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd0f48b e-con-full e-flex e-con e-child\" data-id=\"cd0f48b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2cdf26 elementor-widget elementor-widget-video\" data-id=\"b2cdf26\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=nN7ZH_VqsD4&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae24c5a elementor-widget elementor-widget-heading\" data-id=\"ae24c5a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0623\u062c\u0645\u0644 \u0644\u062d\u0638\u0627\u062a \u0646\u0637\u0642 \u0627\u0644\u0634\u0647\u0627\u062f\u0629\u261d\ufe0f\u0623\u0628\u0643\u062a \u0627\u0644\u0646\u0633\u0627\u0621\ud83d\ude22 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0648\u0623\u0645\u0631\u064a\u0643\u0627 \/ Women crying when converting to Islam\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88c7432 e-con-full e-flex e-con e-child\" data-id=\"88c7432\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f70fb1a elementor-widget elementor-widget-video\" data-id=\"f70fb1a\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=35x-X8_k1N8&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e940712 elementor-widget elementor-widget-heading\" data-id=\"e940712\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0639\u0627\u062c\u0644 \ud83d\udd34400 \u0634\u0627\u0628 \u0648\u0641\u062a\u0627\u0629 \u064a\u0639\u062a\u0646\u0642\u0648\u0646 \u0627\u0644\u0625\u0633\u0644\u0627\u0645\u261d\ufe0f\u064a\u0648\u0645\u064a\u0627 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \ud83c\uddec\ud83c\udde7 \u0628\u0639\u062f \u0623\u062d\u062f\u0627\u062b \u063a\u0632\u0629 WOMEN IN EUROPE ACCEPT ISLAM\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d32af5f elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d32af5f\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc67231\" data-id=\"fc67231\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da11a9e elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"da11a9e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-45ed70c e-flex e-con-boxed e-con e-parent\" data-id=\"45ed70c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e9fa71b e-con-full e-flex e-con e-child\" data-id=\"e9fa71b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e694189 e-con-full e-flex e-con e-child\" data-id=\"e694189\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d0818c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6d0818c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Z\u00f6gern Sie nicht, sich mit uns in Verbindung zu setzen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9880fc2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9880fc2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Senden Sie uns eine Nachricht, wenn Sie weitere Fragen haben, und wir werden Ihnen so schnell wie m\u00f6glich antworten.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0508e6 elementor-widget-laptop__width-initial elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-shortcode\" data-id=\"c0508e6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3932-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"3932\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/34029#wpcf7-f3932-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/pages\/34029#wpcf7-f3932-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3932\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3932-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"whizcyber-form\">\n\t<div class=\"row\">\n\t\t<div class=\"column\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Rufnummer\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Schreiben Sie Ihre Nachricht hier\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Jetzt senden\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01c227d elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"01c227d\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-adf727a\" data-id=\"adf727a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96fae87 elementor-widget__width-auto elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"96fae87\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"305\" height=\"227\" src=\"https:\/\/tamerbadr.com\/wp-content\/uploads\/2022\/10\/opening-quote-icon.png\" class=\"attachment-full size-full wp-image-1947\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0644\u0645\u0627\u0630\u0627 \u0623\u0633\u0644\u0645\u0648\u0627\u061f \u0646\u062d\u0646 \u0647\u0646\u0627 \u0644\u0646\u0641\u062a\u062d \u0644\u0643 \u0646\u0627\u0641\u0630\u0629 \u0635\u0627\u062f\u0642\u0629\u060c \u0647\u0627\u062f\u0626\u0629\u060c \u0648\u0645\u062d\u062a\u0631\u0645\u0629 \u0646\u062d\u0648 \u0627\u0644\u0625\u0633\u0644\u0627\u0645. \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0635\u0641\u062d\u0629 \u0646\u0633\u0644\u0651\u0637 \u0627\u0644\u0636\u0648\u0621 \u0639\u0644\u0649 \u0642\u0635\u0635 \u0623\u0634\u062e\u0627\u0635 \u0645\u0646 \u062e\u0644\u0641\u064a\u0627\u062a \u0648\u062b\u0642\u0627\u0641\u0627\u062a \u0648\u062f\u064a\u0627\u0646\u0627\u062a \u0645\u062e\u062a\u0644\u0641\u0629\u060c \u0627\u062e\u062a\u0627\u0631\u0648\u0627 \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0639\u0646 \u0642\u0646\u0627\u0639\u0629 \u0628\u0639\u062f \u0631\u062d\u0644\u0629 \u0645\u0646 \u0627\u0644\u0628\u062d\u062b \u0648\u0627\u0644\u062a\u0641\u0643\u064a\u0631.\u0644\u064a\u0633\u062a \u0645\u062c\u0631\u062f \u062d\u0643\u0627\u064a\u0627\u062a \u0634\u062e\u0635\u064a\u0629\u060c \u0628\u0644 \u0634\u0647\u0627\u062f\u0627\u062a \u0635\u0627\u062f\u0642\u0629 \u062a\u0639\u0628\u0651\u0631 \u0639\u0646 \u0627\u0644\u062a\u063a\u064a\u0651\u0631 \u0627\u0644\u0639\u0645\u064a\u0642 \u0627\u0644\u0630\u064a \u0623\u062d\u062f\u062b\u0647 \u0627\u0644\u0625\u0633\u0644\u0627\u0645 \u0641\u064a \u0642\u0644\u0648\u0628\u0647\u0645 \u0648\u0639\u0642\u0648\u0644\u0647\u0645\u060c \u0648\u0639\u0646 \u0627\u0644\u0623\u0633\u0626\u0644\u0629 \u0627\u0644\u062a\u064a \u0648\u062c\u062f\u0648\u0627 \u0644\u0647\u0627 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":4468,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-34029","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/pages\/34029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/comments?post=34029"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/pages\/34029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media\/4468"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/de\/wp-json\/wp\/v2\/media?parent=34029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}