{"id":22043,"date":"2025-03-27T15:35:53","date_gmt":"2025-03-27T15:35:53","guid":{"rendered":"https:\/\/tamerbadr.com\/?p=22043"},"modified":"2025-04-17T07:41:02","modified_gmt":"2025-04-17T07:41:02","slug":"dfhfgh","status":"publish","type":"post","link":"https:\/\/tamerbadr.com\/bn\/archives\/22043","title":{"rendered":"&quot;\u09a6\u09cd\u09af \u0985\u09cd\u09af\u09be\u0993\u09af\u09bc\u09be\u0987\u099f\u09c7\u09a1 \u09b2\u09c7\u099f\u09be\u09b0\u09b8&quot; \u09ac\u0987\u09af\u09bc\u09c7\u09b0 \u09b8\u09c2\u099a\u09c0\u09aa\u09a4\u09cd\u09b0"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22043\" class=\"elementor elementor-22043\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78ed079c e-flex e-con-boxed e-con e-parent\" data-id=\"78ed079c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22966c elementor-widget elementor-widget-text-editor\" data-id=\"22966c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"x1cy8zhl x2bj2ny x78zum5 x1q0g3np\"><div class=\"x1iyjqo2\"><div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\"><div class=\"xu06os2 x1ok221b\"><h1 class=\"html-div xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1q0g3np\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs x4k7w5x x1h91t0o x1h9r5lt x1jfb8zj xv2umb2 x1beo9mf xaigb6o x12ejxvf x3igimt xarpa2k xedcshv x1lytzrv x1t2pt76 x7ja8zs x1qrby5j\">\u09e7\u09ef \u09a1\u09bf\u09b8\u09c7\u09ae\u09cd\u09ac\u09b0, \u09e8\u09e6\u09e7\u09ef<\/span><\/span><\/h1><\/div><\/div><\/div><div><div class=\"x1i10hfl x1qjc9v5 xjqpnuy xa49m3k xqeqjp1 x2hbi6w x9f619 x1ypdohk xdl72j9 x2lah0s xe8uvvx x2lwn1j xeuugli x16tdsg8 x1hl2dhg xggy1nq x1ja2u2z x1t137rt x1o1ewxj x3x9cwd x1e5q0jg x13rtm0m x1q0g3np x87ps6o x1lku1pv x1a2a7pz xjyslct xjbqb8w x13fuv20 xu3j5b3 x1q0q8m5 x26u7qi x972fbf xcfux6l x1qhh985 xm0m39n x3nfvp2 xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1n2onr6 x3ajldb x194ut8o x1vzenxt xd7ygy7 xt298gk x1xhcax0 x1s928wv x10pfhc2 x1j6awrg x1v53gu8 x1tfg27r xitxdhh\" tabindex=\"0\" role=\"button\" aria-expanded=\"false\" aria-haspopup=\"menu\" aria-label=\"\u098f\u0987 \u09aa\u09cb\u09b8\u09cd\u099f\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u0995\u09b0\u09a3\u09c0\u09af\u09bc \u09aa\u09a6\u0995\u09cd\u09b7\u09c7\u09aa\"><div class=\"x1ey2m1c xds687c x17qophe xg01cxk x47corl x10l6tqk x13vifvy x1ebt8du x19991ni x1dhq9h xzolkzo x12go9s9 x1rnf11y xprq8jg\" role=\"none\" data-visualcompletion=\"ignore\">\u00a0<\/div><\/div><\/div><\/div><h1 class=\"xyinxu5 x4uap5 x1g2khh7 xkhd6sd\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u\" dir=\"auto\"><strong>&quot;\u09a6\u09cd\u09af \u0985\u09cd\u09af\u09be\u0993\u09af\u09bc\u09be\u0987\u099f\u09c7\u09a1 \u09b2\u09c7\u099f\u09be\u09b0\u09b8&quot; \u09ac\u0987\u09af\u09bc\u09c7\u09b0 \u09b8\u09c2\u099a\u09c0\u09aa\u09a4\u09cd\u09b0<\/strong><br class=\"html-br\" \/><br class=\"html-br\" \/>\u0986\u09ae\u09be\u09b0 \u09a8\u09a4\u09c1\u09a8 \u09ac\u0987, &quot;\u09a6\u09cd\u09af \u0993\u09af\u09bc\u09c7\u099f\u09bf\u0982 \u09b2\u09c7\u099f\u09be\u09b0\u09b8&quot; \u09aa\u09cd\u09b0\u0995\u09be\u09b6\u09c7\u09b0 \u09aa\u09b0 \u09a5\u09c7\u0995\u09c7, \u0986\u09ae\u09bf \u09af\u09c7\u09ae\u09a8\u099f\u09bf \u0986\u09b6\u09be \u0995\u09b0\u09c7\u099b\u09bf\u09b2\u09be\u09ae, \u0986\u09ae\u09be\u09b0 \u0989\u09aa\u09b0 \u09a8\u09be\u09a8\u09be \u09a7\u09b0\u09a3\u09c7\u09b0 \u0986\u0995\u09cd\u09b0\u09ae\u09a3 \u098f\u09ac\u0982 \u09ad\u09c1\u09b2 \u09a8\u09bf\u09b0\u09cd\u09a6\u09c7\u09b6\u09a8\u09be\u09b0 \u0985\u09ad\u09bf\u09af\u09cb\u0997 \u0986\u09b8\u099b\u09c7\u0964 \u098f\u099f\u09bf\u0987 \u099b\u09bf\u09b2 \u098f\u0995\u099f\u09bf \u09aa\u09cd\u09b0\u09a7\u09be\u09a8 \u0995\u09be\u09b0\u09a3 \u09af\u09be\u09b0 \u0995\u09be\u09b0\u09a3\u09c7 \u0986\u09ae\u09bf \u099b\u09af\u09bc \u09ae\u09be\u09b8 \u0986\u0997\u09c7 \u0986\u09ae\u09be\u09b0 \u09ac\u0987 \u09b2\u09c7\u0996\u09be\u09b0 \u09ac\u09cd\u09af\u09be\u09aa\u09be\u09b0\u09c7 \u09a6\u09cd\u09ac\u09bf\u09a7\u09be\u0997\u09cd\u09b0\u09b8\u09cd\u09a4 \u09b9\u09af\u09bc\u09c7 \u09aa\u09a1\u09bc\u09c7\u099b\u09bf\u09b2\u09be\u09ae \u098f\u09ac\u0982 \u09ac\u09c7\u09b6 \u0995\u09af\u09bc\u09c7\u0995\u09ac\u09be\u09b0 \u09a5\u09be\u09ae\u09bf\u09df\u09c7\u099b\u09bf\u09b2\u09be\u09ae\u0964<br class=\"html-br\" \/>\u0986\u09ae\u09bf \u098f\u0995\u09be\u09a7\u09bf\u0995\u09ac\u09be\u09b0 \u09a4\u09cb\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09b0\u09bf\u099a\u09af\u09bc \u0995\u09b0\u09bf\u09af\u09bc\u09c7 \u09a6\u09c7\u0993\u09af\u09bc\u09be\u09b0 \u099a\u09c7\u09b7\u09cd\u099f\u09be \u0995\u09b0\u09c7\u099b\u09bf \u098f\u09ac\u0982 \u09ac\u09b2\u09c7\u099b\u09bf \u09ac\u0987\u099f\u09bf \u09a8\u09be \u09aa\u09a1\u09bc\u09c7 \u09ac\u09bf\u099a\u09be\u09b0 \u0995\u09b0\u09cb \u09a8\u09be, \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09a6\u09c1\u09b0\u09cd\u09ad\u09be\u0997\u09cd\u09af\u09ac\u09b6\u09a4 \u09a4\u09cb\u09ae\u09be\u09a6\u09c7\u09b0 \u09ac\u09c7\u09b6\u09bf\u09b0\u09ad\u09be\u0997\u0987 \u09a4\u09be\u09a1\u09bc\u09be\u09b9\u09c1\u09a1\u09bc\u09cb \u0995\u09b0\u09c7 \u0986\u09ae\u09be\u0995\u09c7 \u09ac\u09a8\u09cd\u09a7\u09c1\u09a4\u09cd\u09ac \u09a5\u09c7\u0995\u09c7 \u09b8\u09b0\u09bf\u09af\u09bc\u09c7 \u09a6\u09bf\u09af\u09bc\u09c7\u099b\u09bf\u09b2\u09c7, \u0986\u09b0 \u09a4\u09cb\u09ae\u09be\u09a6\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u0995\u09c7\u0989 \u0995\u09c7\u0989 \u09ac\u0987\u099f\u09bf \u09a8\u09be \u09aa\u09a1\u09bc\u09c7\u0987 \u0986\u09ae\u09be\u0995\u09c7 \u0986\u0995\u09cd\u09b0\u09ae\u09a3 \u0995\u09b0\u09c7\u099b\u09bf\u09b2\u09c7, \u09a4\u09be\u0987 \u0986\u09ae\u09bf \u09a4\u09cb\u09ae\u09be\u09a6\u09c7\u09b0 \u0985\u09a8\u09c7\u0995\u0995\u09c7\u0987 \u0986\u0997\u09c7\u0987 \u09ac\u09b2\u09c7\u099b\u09bf \u09af\u09c7 \u09ac\u0987\u099f\u09bf\u0995\u09c7 \u09b8\u0982\u0995\u09cd\u09b7\u09bf\u09aa\u09cd\u09a4 \u0995\u09b0\u09be \u09af\u09be\u09ac\u09c7 \u09a8\u09be\u0964<br class=\"html-br\" \/>\u09af\u09c7\u09ae\u09a8\u099f\u09be \u0986\u09ae\u09bf \u0986\u09aa\u09a8\u09be\u0995\u09c7 \u09ac\u09b2\u09c7\u099b\u09bf, \u09ac\u0987\u099f\u09bf \u09ac\u09a1\u09bc, \u09ea\u09e6\u09e6 \u09aa\u09c3\u09b7\u09cd\u09a0\u09be\u09b0, \u098f\u09ac\u0982 \u0986\u09ae\u09be\u0995\u09c7 \u09af\u09c7 \u09aa\u09cd\u09b0\u09b6\u09cd\u09a8\u0997\u09c1\u09b2\u09bf \u0995\u09b0\u09be \u09b9\u09af\u09bc\u09c7\u099b\u09bf\u09b2 \u09a4\u09be\u09b0 \u0989\u09a4\u09cd\u09a4\u09b0 \u0986\u09ae\u09bf \u09a6\u09bf\u09a4\u09c7 \u09aa\u09be\u09b0\u09ac \u09a8\u09be, \u0995\u09be\u09b0\u09a3 \u0989\u09a4\u09cd\u09a4\u09b0\u0997\u09c1\u09b2\u09bf \u09ac\u0987\u099f\u09bf\u09a4\u09c7 \u09ac\u09bf\u09b8\u09cd\u09a4\u09be\u09b0\u09bf\u09a4\u09ad\u09be\u09ac\u09c7 \u09a6\u09c7\u0993\u09af\u09bc\u09be \u0986\u099b\u09c7, \u098f\u09ac\u0982 \u0986\u09ae\u09bf \u0986\u09aa\u09a8\u09be\u09b0 \u099c\u09a8\u09cd\u09af \u09b8\u09c7\u0997\u09c1\u09b2\u09bf \u09b8\u0982\u0995\u09cd\u09b7\u09c7\u09aa\u09c7 \u09ac\u09b2\u09a4\u09c7 \u09aa\u09be\u09b0\u09ac \u09a8\u09be\u0964<br class=\"html-br\" \/>\u0986\u09ae\u09be\u09b0 \u09a6\u09c3\u09b7\u09cd\u099f\u09bf\u09ad\u0999\u09cd\u0997\u09bf\u09b0 \u09b8\u09ae\u09b0\u09cd\u09a5\u09a8\u09c7 \u09aa\u09b0\u09cd\u09af\u09be\u09aa\u09cd\u09a4 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3 \u09b8\u0982\u0997\u09cd\u09b0\u09b9 \u09a8\u09be \u0995\u09b0\u09be \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u0986\u09ae\u09bf \u098f\u0987 \u09ac\u0987\u099f\u09bf \u09b2\u09c7\u0996\u09be\u09b0 \u0989\u09a6\u09cd\u09af\u09cb\u0997 \u09a8\u09bf\u0987\u09a8\u09bf\u0964 \u0986\u09ae\u09bf \u098f\u09a4 \u09ac\u09cb\u0995\u09be \u09a8\u0987 \u09af\u09c7 \u098f\u0987 \u09ac\u09bf\u09aa\u099c\u09cd\u099c\u09a8\u0995 \u09aa\u09a6\u0995\u09cd\u09b7\u09c7\u09aa \u09a8\u09c7\u09ac, \u09af\u09be\u09b0 \u099c\u09a8\u09cd\u09af \u0986\u09ae\u09be\u0995\u09c7 \u09b8\u09be\u09b0\u09be \u099c\u09c0\u09ac\u09a8 \u0985\u09a8\u09c7\u0995 \u09ae\u09c2\u09b2\u09cd\u09af \u09a6\u09bf\u09a4\u09c7 \u09b9\u09ac\u09c7, \u09af\u09a6\u09bf \u09a8\u09be \u0986\u09ae\u09be\u09b0 \u09a6\u09c3\u09b7\u09cd\u099f\u09bf\u09ad\u0999\u09cd\u0997\u09bf\u09b0 \u09b8\u09ae\u09b0\u09cd\u09a5\u09a8\u09c7 \u09aa\u09b0\u09cd\u09af\u09be\u09aa\u09cd\u09a4 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3 \u098f\u09ac\u0982 \u0995\u09be\u09b0\u09a3 \u09a5\u09be\u0995\u09c7\u0964<br class=\"html-br\" \/>\u0986\u09ae\u09bf \u0986\u09aa\u09a8\u09be\u0995\u09c7 \u09ac\u0987\u099f\u09bf\u09b0 \u09b8\u09c2\u099a\u09c0 \u09aa\u09cd\u09b0\u09a6\u09be\u09a8 \u0995\u09b0\u09ac, \u09af\u09be\u09a4\u09c7 \u09ac\u0987\u099f\u09bf\u09a4\u09c7 \u0995\u09c0 \u0995\u09c0 \u09b2\u09c7\u0996\u09be \u0986\u099b\u09c7 \u09b8\u09c7 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u0986\u09aa\u09a8\u09be\u09b0 \u0995\u09bf\u099b\u09c1 \u09aa\u09cd\u09b0\u09b6\u09cd\u09a8\u09c7\u09b0 \u0989\u09a4\u09cd\u09a4\u09b0 \u098f\u09ac\u0982 \u0986\u09aa\u09a8\u09be\u09b0 \u0995\u09be\u099b \u09a5\u09c7\u0995\u09c7 \u0986\u09ae\u09bf \u09af\u09c7 \u0985\u09a8\u09c7\u0995 \u09aa\u09cd\u09b0\u09b6\u09cd\u09a8\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a4\u09cd\u09af\u09be\u09b6\u09be \u0995\u09b0\u09c7\u099b\u09bf\u09b2\u09be\u09ae \u09a4\u09be\u09b0 \u0989\u09a4\u09cd\u09a4\u09b0 \u09b0\u09af\u09bc\u09c7\u099b\u09c7\u0964<br class=\"html-br\" \/><br class=\"html-br\" \/>\u09ad\u09c2\u09ae\u09bf\u0995\u09be<br class=\"html-br\" \/>\u09aa\u09cd\u09b0\u09a5\u09ae \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u098f\u0995\u099c\u09a8 \u09b0\u09be\u09b8\u09c2\u09b2 \u098f\u09ac\u0982 \u098f\u0995\u099c\u09a8 \u09a8\u09ac\u09c0\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09aa\u09be\u09b0\u09cd\u09a5\u0995\u09cd\u09af<br class=\"html-br\" \/>\u09af\u09c7\u09b8\u09ac \u09a7\u09b0\u09a3\u09c7\u09b0 \u09ae\u09be\u09a8\u09c1\u09b7 \u0993\u09b9\u09c0 \u09b2\u09be\u09ad \u0995\u09b0\u09c7<br class=\"html-br\" \/>\u2022 \u09a7\u09be\u09b0\u09cd\u09ae\u09bf\u0995 \u09ac\u09be \u09ad\u09be\u09b2\u09cb<br class=\"html-br\" \/>\u2022 \u09ac\u09be\u09b0\u09cd\u09a4\u09be\u09ac\u09be\u09b9\u0995\u0997\u09a3<br class=\"html-br\" \/>\u2022 \u09b0\u09b8\u09c2\u09b2\u0997\u09a3\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09cd\u09af<br class=\"html-br\" \/>\u2022 \u09a8\u09ac\u09c0\u0997\u09a3<br class=\"html-br\" \/>\u2022 \u09a8\u09ac\u09c0\u09a6\u09c7\u09b0 \u09ae\u09bf\u09b6\u09a8<br class=\"html-br\" \/>\u2022 \u09b0\u09be\u09b8\u09c2\u09b2 (\u09b8\u09be.)<br class=\"html-br\" \/>\u2022 \u098f\u0995\u099c\u09a8 \u09b0\u09b8\u09c2\u09b2 \u09b9\u09b2\u09c7\u09a8 \u09a4\u09bf\u09a8\u09bf \u09af\u09be\u0995\u09c7 \u09ad\u09bf\u09a8\u09cd\u09a8\u09ae\u09a4\u09be\u09ac\u09b2\u09ae\u09cd\u09ac\u09c0 \u09b8\u09ae\u09cd\u09aa\u09cd\u09b0\u09a6\u09be\u09af\u09bc\u09c7\u09b0 \u0995\u09be\u099b\u09c7 \u09aa\u09be\u09a0\u09be\u09a8\u09cb \u09b9\u09af\u09bc, \u0986\u09b0 \u098f\u0995\u099c\u09a8 \u09a8\u09ac\u09c0 \u09b9\u09b2\u09c7\u09a8 \u09a4\u09bf\u09a8\u09bf \u09af\u09be\u0995\u09c7 \u0990\u0995\u09cd\u09af\u09ae\u09a4\u09c7 \u09a5\u09be\u0995\u09be \u09b8\u09ae\u09cd\u09aa\u09cd\u09b0\u09a6\u09be\u09af\u09bc\u09c7\u09b0 \u0995\u09be\u099b\u09c7 \u09aa\u09be\u09a0\u09be\u09a8\u09cb \u09b9\u09af\u09bc\u0964<br class=\"html-br\" \/>\u2022 \u09a8\u09ac\u09c0 \u0993 \u09b0\u09be\u09b8\u09c2\u09b2\u09a6\u09c7\u09b0 \u09b8\u0982\u0996\u09cd\u09af\u09be<br class=\"html-br\" \/>\u2022 \u09aa\u09be\u09b0\u09cd\u09a5\u0995\u09cd\u09af \u09b9\u09b2\u09cb \u09a4\u09be\u09b0\u09be \u09a8\u09ac\u09c0\u0964<br class=\"html-br\" \/>\u09a6\u09cd\u09ac\u09bf\u09a4\u09c0\u09af\u09bc \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09a8\u09ac\u09c0\u09a6\u09c7\u09b0 \u09b8\u09c0\u09b2\u09ae\u09cb\u09b9\u09b0, \u09b0\u09be\u09b8\u09c2\u09b2\u09a6\u09c7\u09b0 \u09b8\u09c0\u09b2\u09ae\u09cb\u09b9\u09b0 \u09a8\u09af\u09bc<br class=\"html-br\" \/>\u0995\u09c7\u09ac\u09b2 \u09a8\u09ac\u09c0 \u0986\u099b\u09c7\u09a8 \u098f\u09ac\u0982 \u0995\u09c7\u09ac\u09b2 \u09b0\u09be\u09b8\u09c2\u09b2 \u0986\u099b\u09c7\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u0989\u0995\u09cd\u09a4\u09bf\u099f\u09bf\u09b0 \u0985\u0995\u09be\u09b0\u09cd\u09af\u0995\u09b0\u09a4\u09be\u09b0 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3 (\u09a8\u09ac\u09c0 \u098f\u09ac\u0982 \u09b0\u09be\u09b8\u09c2\u09b2\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u0995\u09cb\u09a8 \u09aa\u09be\u09b0\u09cd\u09a5\u0995\u09cd\u09af \u09a8\u09c7\u0987)<br class=\"html-br\" \/>\u2022 \u098f\u0987 \u0995\u09a5\u09be\u09b0 \u0985\u0995\u09be\u09b0\u09cd\u09af\u0995\u09b0\u09a4\u09be\u09b0 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3 (\u09aa\u09cd\u09b0\u09a4\u09cd\u09af\u09c7\u0995 \u09b0\u09be\u09b8\u09c2\u09b2\u0987 \u09a8\u09ac\u09c0, \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u09aa\u09cd\u09b0\u09a4\u09cd\u09af\u09c7\u0995 \u09a8\u09ac\u09c0\u0987 \u09b0\u09be\u09b8\u09c2\u09b2 \u09a8\u09a8)<br class=\"html-br\" \/>\u2022 \u09b6\u09be\u09b8\u09cd\u09a4\u09bf\u09b0 \u09aa\u09cd\u09b0\u09a4\u09cd\u09af\u09be\u09b6\u09bf\u09a4 \u09b2\u0995\u09cd\u09b7\u09a3 \u09aa\u09cd\u09b0\u0995\u09be\u09b6\u09c7\u09b0 \u09aa\u09c2\u09b0\u09cd\u09ac\u09c7\u0987 \u09b0\u09be\u09b8\u09c2\u09b2 \u09aa\u09cd\u09b0\u09c7\u09b0\u09a3\u09c7\u09b0 \u09aa\u09cd\u09b0\u09af\u09bc\u09cb\u099c\u09a8\u09c0\u09af\u09bc\u09a4\u09be<br class=\"html-br\" \/>\u2022 \u09a8\u09ac\u09c1\u0993\u09af\u09bc\u09a4 \u09b9\u09b2\u09cb \u09b8\u09ac\u099a\u09c7\u09af\u09bc\u09c7 \u09b8\u09ae\u09cd\u09ae\u09be\u09a8\u09bf\u09a4 \u098f\u09ac\u0982 \u09b8\u09b0\u09cd\u09ac\u09cb\u099a\u09cd\u099a \u09ae\u09b0\u09cd\u09af\u09be\u09a6\u09be\u0964<br class=\"html-br\" \/>\u2022 \u0995\u09c1\u09b0\u0986\u09a8\u09c7\u09b0 \u0986\u09af\u09bc\u09be\u09a4\u09c7 \u09ac\u09b2\u09be \u09b9\u09af\u09bc\u09c7\u099b\u09c7 \u09af\u09c7, \u09a8\u09ac\u09c0 (\u09b8\u09be\u0983) \u09b9\u09b2\u09c7\u09a8 \u0986\u09b2\u09cd\u09b2\u09be\u09b9\u09b0 \u09b0\u09be\u09b8\u09c2\u09b2 \u098f\u09ac\u0982 \u09a8\u09ac\u09c0\u09a6\u09c7\u09b0 \u09b8\u09c0\u09b2\u09ae\u09cb\u09b9\u09b0\u0964<br class=\"html-br\" \/>\u2022 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09ae\u09c1\u09b9\u09be\u09ae\u09cd\u09ae\u09a6 (\u09b8\u09be\u0983) \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u0993 \u0986\u09b6\u09c0\u09b0\u09cd\u09ac\u09be\u09a6 \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995, \u09a4\u09bf\u09a8\u09bf \u09a8\u09bf\u09b6\u09cd\u099a\u09bf\u09a4 \u0995\u09b0\u09c7\u09a8 \u09af\u09c7 \u09a4\u09bf\u09a8\u09bf \u09b9\u09b2\u09c7\u09a8 \u09b0\u09be\u09b8\u09c2\u09b2\u09a6\u09c7\u09b0 \u09a8\u09c7\u09a4\u09be \u098f\u09ac\u0982 \u09a8\u09ac\u09c0\u09a6\u09c7\u09b0 \u09b8\u09c0\u09b2\u09ae\u09cb\u09b9\u09b0\u0964<br class=\"html-br\" \/>\u2022 \u09a8\u09ac\u09c1\u09df\u09a4\u09c7\u09b0 \u09ae\u09cb\u09b9\u09b0 \u0995\u09c7\u09ac\u09b2 \u09ac\u09bf\u09b6\u09c1\u09a6\u09cd\u09a7 \u09b8\u09c1\u09a8\u09cd\u09a8\u09be\u09b9 \u09a5\u09c7\u0995\u09c7 \u09aa\u09be\u0993\u09df\u09be \u09af\u09be\u09df<br class=\"html-br\" \/>\u2022 &quot;\u09b0\u09bf\u09b8\u09be\u09b2\u09be\u09a4 \u0993 \u09a8\u09ac\u09c1\u09df\u09be\u09a4 \u09ac\u09a8\u09cd\u09a7 \u09b9\u09df\u09c7 \u0997\u09c7\u099b\u09c7, \u09a4\u09be\u0987 \u0986\u09ae\u09be\u09b0 \u09aa\u09b0\u09c7 \u0995\u09cb\u09a8 \u09b0\u09be\u09b8\u09c2\u09b2 \u09ac\u09be \u09a8\u09ac\u09c0 \u09a8\u09c7\u0987&quot; \u098f\u0987 \u09b9\u09be\u09a6\u09bf\u09b8\u099f\u09bf\u09b0 \u09b8\u09a4\u09cd\u09af\u09a4\u09be \u0995\u09c0?<br class=\"html-br\" \/>\u2022 \u0995\u09c1\u09b0\u0986\u09a8\u09c7\u09b0 \u0986\u09af\u09bc\u09be\u09a4 \u09af\u09be \u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u0986\u09b2\u09be\u09ae\u09a4\u0997\u09c1\u09b2\u09bf\u09b0 \u09aa\u09c2\u09b0\u09cd\u09ac\u09c7 \u098f\u09ac\u0982 \u09b8\u09ae\u09af\u09bc\u0995\u09be\u09b2\u09c7 \u09b0\u09be\u09b8\u09c2\u09b2 \u09aa\u09cd\u09b0\u09c7\u09b0\u09a3\u09c7\u09b0 \u0995\u09a5\u09be \u0989\u09b2\u09cd\u09b2\u09c7\u0996 \u0995\u09b0\u09c7<br class=\"html-br\" \/>\u2022 \u0995\u09c1\u09b0\u0986\u09a8\u09c7\u09b0 \u0986\u09af\u09bc\u09be\u09a4 \u09af\u09c7\u0996\u09be\u09a8\u09c7 \u0985\u09a4\u09c0\u09a4 \u0995\u09be\u09b2\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a4\u09c0\u0995\u09cd\u09b7\u09bf\u09a4 \u09b0\u09be\u09b8\u09c2\u09b2\u09a6\u09c7\u09b0 \u0989\u09b2\u09cd\u09b2\u09c7\u0996 \u09b0\u09af\u09bc\u09c7\u099b\u09c7<br class=\"html-br\" \/>\u09a4\u09c3\u09a4\u09c0\u09af\u09bc \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09aa\u09cd\u09b0\u09a4\u09bf\u099f\u09bf \u099c\u09be\u09a4\u09bf\u09b0 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8\u09c7\u09b0 \u09aa\u09c1\u09a8\u09b0\u09be\u09ac\u09c3\u09a4\u09cd\u09a4\u09bf \u09af\u09c7 \u09a4\u09be\u09a6\u09c7\u09b0 \u09a8\u09ac\u09c0 \u09b9\u09b2\u09c7\u09a8 \u09b0\u09b8\u09c2\u09b2\u09a6\u09c7\u09b0 \u09b8\u09c0\u09b2\u09ae\u09cb\u09b9\u09b0<br class=\"html-br\" \/>\u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09ac\u09be\u09ac\u09be-\u09ae\u09be \u098f\u09ac\u0982 \u09a6\u09be\u09a6\u09be\u09a6\u09c7\u09b0 \u0986\u09ae\u09b0\u09be \u098f\u099f\u09be\u0987 \u0995\u09b0\u09a4\u09c7 \u09a6\u09c7\u0996\u09c7\u099b\u09bf\u0964<br class=\"html-br\" \/>\u2022 \u098f\u0987 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8\u09c7\u09b0 \u09aa\u09c1\u09a8\u09b0\u09be\u09ac\u09c3\u09a4\u09cd\u09a4\u09bf \u0995\u09b0\u09be \u09af\u09c7 \u0985\u09a8\u09cd\u09af \u0995\u09cb\u09a8\u0993 \u09b0\u09be\u09b8\u09c2\u09b2 \u09aa\u09be\u09a0\u09be\u09a8\u09cb \u09b9\u09ac\u09c7 \u09a8\u09be<br class=\"html-br\" \/>\u099a\u09a4\u09c1\u09b0\u09cd\u09a5 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u0986\u09ae\u09b0\u09be \u09b0\u09be\u09b8\u09c2\u09b2 \u09a8\u09be \u09aa\u09be\u09a0\u09be\u09a8\u09cb \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u0995\u0996\u09a8\u0993 \u09b6\u09be\u09b8\u09cd\u09a4\u09bf \u09a6\u09c7\u0987 \u09a8\u09be\u0964<br class=\"html-br\" \/>\u2022 \u09b8\u09a4\u09b0\u09cd\u0995\u0995\u09be\u09b0\u09c0 \u09aa\u09be\u09a0\u09be\u09a8\u09cb<br class=\"html-br\" \/>\u2022 \u099c\u09be\u09a4\u09bf\u0997\u09c1\u09b2\u09bf \u09a4\u09be\u09a6\u09c7\u09b0 \u09aa\u09c2\u09b0\u09cd\u09ac\u09aa\u09c1\u09b0\u09c1\u09b7\u09a6\u09c7\u09b0 \u0995\u09be\u099c \u09ae\u09c7\u09a8\u09c7 \u099a\u09b2\u09c7\u0964<br class=\"html-br\" \/>\u2022 \u09b8\u09a4\u09b0\u09cd\u0995\u0995\u09be\u09b0\u09c0\u09a6\u09c7\u09b0 \u0985\u09b8\u09cd\u09ac\u09c0\u0995\u09be\u09b0 \u0995\u09b0\u09be<br class=\"html-br\" \/>\u2022 \u0985\u09b8\u09cd\u09ac\u09c0\u0995\u09be\u09b0\u09c7\u09b0 \u0995\u09cd\u09b7\u09c7\u09a4\u09cd\u09b0\u09c7 \u099c\u09c7\u09a6 \u098f\u09ac\u0982 \u0985\u09a7\u09cd\u09af\u09ac\u09b8\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09ae\u09bf\u09a5\u09cd\u09af\u09be\u09ac\u09be\u09a6\u09c0\u09a6\u09c7\u09b0 \u09a6\u09cd\u09ac\u09be\u09b0\u09be \u09b8\u09a4\u09b0\u09cd\u0995\u0995\u09be\u09b0\u09c0\u09a6\u09c7\u09b0 \u0989\u09aa\u09b9\u09be\u09b8<br class=\"html-br\" \/>\u2022 \u0985\u09a4\u09c0\u09a4\u09c7\u09b0 \u0995\u09bf\u099b\u09c1 \u09ae\u09bf\u09a5\u09cd\u09af\u09be\u09ac\u09be\u09a6\u09c0\u09b0 \u0989\u09a6\u09be\u09b9\u09b0\u09a3<br class=\"html-br\" \/>\u2022 \u09ac\u09cd\u09af\u0999\u09cd\u0997\u09c7\u09b0 \u09aa\u09b0\u09cd\u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09ac\u09cd\u09af\u0999\u09cd\u0997 \u0993 \u0989\u09b8\u09cd\u0995\u09be\u09a8\u09bf\u09b0 \u09aa\u09b0\u09cd\u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09ac\u09bf\u09a4\u09b0\u09cd\u0995\u09c7\u09b0 \u09aa\u09b0\u09cd\u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09ac\u09bf\u09aa\u09a5\u0997\u09be\u09ae\u09c0\u09a4\u09be\u09b0 \u0985\u09ad\u09bf\u09af\u09cb\u0997\u09c7\u09b0 \u09aa\u09b0\u09cd\u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09a4\u09bf\u09b0\u09b8\u09cd\u0995\u09be\u09b0 \u098f\u09ac\u0982 \u09aa\u09be\u0997\u09b2\u09be\u09ae\u09bf\u09b0 \u0985\u09ad\u09bf\u09af\u09cb\u0997\u09c7\u09b0 \u09aa\u09b0\u09cd\u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09ae\u09c3\u09a4\u09cd\u09af\u09c1\u09b0 \u09b9\u09c1\u09ae\u0995\u09bf\u09b0 \u09aa\u09b0\u09cd\u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u0995\u09be\u09ab\u09c7\u09b0\u09a6\u09c7\u09b0 \u09b6\u09be\u09b8\u09cd\u09a4\u09bf \u09a6\u09cd\u09b0\u09c1\u09a4 \u0986\u09a8\u09be\u09b0 \u09aa\u09b0\u09cd\u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09ae\u09bf\u09a5\u09cd\u09af\u09be\u09ac\u09be\u09a6\u09c0\u09a6\u09c7\u09b0 \u09b6\u09be\u09b8\u09cd\u09a4\u09bf<br class=\"html-br\" \/>\u2022 \u0985\u09b8\u09cd\u09ac\u09c0\u0995\u09be\u09b0\u0995\u09be\u09b0\u09c0\u09a6\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u09b8\u09b0\u09cd\u09ac\u09b6\u0995\u09cd\u09a4\u09bf\u09ae\u09be\u09a8 \u0988\u09b6\u09cd\u09ac\u09b0\u09c7\u09b0 \u09b6\u09be\u09b8\u09cd\u09a4\u09bf \u09b9\u09ac\u09c7 \u09b9\u09af\u09bc \u09a7\u09cd\u09ac\u0982\u09b8, \u09a8\u09bf\u09b0\u09cd\u09af\u09be\u09a4\u09a8, \u0985\u09a5\u09ac\u09be \u0989\u09ad\u09af\u09bc\u0987\u0964<br class=\"html-br\" \/>\u2022 \u09af\u0996\u09a8 \u09b0\u09be\u09b8\u09c2\u09b2\u0997\u09a3 \u0985\u09b8\u09cd\u09ac\u09c0\u0995\u09be\u09b0\u0995\u09be\u09b0\u09c0\u09a6\u09c7\u09b0 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u09b9\u09a4\u09be\u09b6 \u09b9\u09af\u09bc\u09c7 \u09aa\u09a1\u09bc\u09c7\u09a8, \u09a4\u0996\u09a8 \u09a4\u09be\u09a6\u09c7\u09b0 \u0995\u09c0 \u09b9\u09af\u09bc?<br class=\"html-br\" \/>\u09ae\u09bf\u09a5\u09cd\u09af\u09be\u09ac\u09be\u09a6\u09c0\u09a6\u09c7\u09b0 \u09ae\u09cb\u0995\u09be\u09ac\u09c7\u09b2\u09be \u0995\u09b0\u09be\u09b0 \u099c\u09a8\u09cd\u09af \u09a8\u09c0\u09a4\u09bf, \u09ac\u09be\u0997\u09cd\u09ae\u09c0\u09a4\u09be \u098f\u09ac\u0982 \u09aa\u09cd\u09b0\u09b0\u09cb\u099a\u09bf\u09a4 \u0995\u09b0\u09be\u09b0 \u0995\u09cd\u09b7\u09ae\u09a4\u09be \u09aa\u09cd\u09b0\u09af\u09bc\u09cb\u099c\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u09b8\u09a4\u09cd\u09af \u0985\u09b8\u09cd\u09ac\u09c0\u0995\u09be\u09b0\u0995\u09be\u09b0\u09c0\u09a6\u09c7\u09b0 \u09aa\u09b0\u09bf\u09a3\u09a4\u09bf \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u099a\u09bf\u09a8\u09cd\u09a4\u09be\u09ad\u09be\u09ac\u09a8\u09be \u098f\u09ac\u0982 \u09ac\u09bf\u09ac\u09c7\u099a\u09a8\u09be \u0995\u09b0\u09be\u0964<br class=\"html-br\" \/>\u09aa\u099e\u09cd\u099a\u09ae \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09af\u09c7\u09a6\u09bf\u09a8 \u098f\u09b0 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be \u0986\u09b8\u09ac\u09c7<br class=\"html-br\" \/>\u2022 \u09aa\u09ac\u09bf\u09a4\u09cd\u09b0 \u0995\u09c1\u09b0\u0986\u09a8\u09c7 \u09b6\u09ac\u09cd\u09a6\u099f\u09bf\u09b0 (\u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be\u09b0) \u09aa\u09c1\u09a8\u09b0\u09be\u09ac\u09c3\u09a4\u09cd\u09a4\u09bf<br class=\"html-br\" \/>\u0985\u09b8\u09cd\u09aa\u09b7\u09cd\u099f \u09aa\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u0995\u09be\u09b0\u09ad\u09c7\u09a6<br class=\"html-br\" \/>\u09b7\u09b7\u09cd\u09a0 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u0985\u099c\u09cd\u099e\u09a4\u09be\u09b0 \u09a6\u09cd\u09ac\u09bf\u09a4\u09c0\u09af\u09bc \u09af\u09c1\u0997 \u098f\u09ac\u0982 \u09a6\u09cd\u09ac\u09bf\u09a4\u09c0\u09af\u09bc \u09ac\u09bf\u099c\u09cd\u099e\u09be\u09aa\u09a8<br class=\"html-br\" \/>\u2022 \u09aa\u09cd\u09b0\u09a5\u09ae \u099c\u09be\u09b9\u09c7\u09b2\u09bf\u09af\u09bc\u09be\u09a4\u09c7\u09b0 \u09af\u09c1\u0997 \u098f\u09ac\u0982 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09ac\u09b0\u09cd\u09a4\u09ae\u09be\u09a8 \u09af\u09c1\u0997\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09ae\u09bf\u09b2<br class=\"html-br\" \/>\u2022 \u09b8\u09be\u09a7\u09be\u09b0\u09a3 \u09a7\u09be\u09b0\u09a3\u09be\u09af\u09bc \u09aa\u09cd\u09b0\u09a5\u09ae \u09aa\u09cd\u09b0\u09be\u0995-\u0987\u09b8\u09b2\u09be\u09ae\u09bf\u0995 \u09af\u09c1\u0997\u09c7\u09b0 \u09af\u09c1\u0997<br class=\"html-br\" \/>\u2022 \u09a6\u09cd\u09ac\u09bf\u09a4\u09c0\u09af\u09bc \u09aa\u09cd\u09b0\u09be\u0995-\u0987\u09b8\u09b2\u09be\u09ae\u09bf\u0995 \u09af\u09c1\u0997\u09c7\u09b0 \u09b8\u09be\u09a7\u09be\u09b0\u09a3 \u09a7\u09be\u09b0\u09a3\u09be<br class=\"html-br\" \/>\u2022 \u09aa\u09cd\u09b0\u09a5\u09ae \u0986\u09a6 \u09af\u09c1\u0997 \u098f\u09ac\u0982 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09ac\u09b0\u09cd\u09a4\u09ae\u09be\u09a8 \u09af\u09c1\u0997\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09ae\u09bf\u09b2<br class=\"html-br\" \/>\u2022 \u0986\u09a6 \u099c\u09be\u09a4\u09bf\u09b0 \u09aa\u09cd\u09b0\u09a5\u09ae \u0986\u09af\u09be\u09ac<br class=\"html-br\" \/>\u2022 \u0985\u09cd\u09af\u09be\u09a1\u09c7\u09b0 \u09a6\u09cd\u09ac\u09bf\u09a4\u09c0\u09af\u09bc \u09af\u09c1\u0997<br class=\"html-br\" \/>\u2022 \u09a6\u09cd\u09ac\u09bf\u09a4\u09c0\u09af\u09bc \u099c\u09be\u09b9\u09bf\u09b2\u09bf\u09df\u09be \u098f\u09ac\u0982 \u09a6\u09cd\u09ac\u09bf\u09a4\u09c0\u09af\u09bc \u0986\u09a6\u09c7\u09b0 \u09af\u09c1\u0997 \u0995\u0996\u09a8 \u09b6\u09c7\u09b7 \u09b9\u09ac\u09c7?<br class=\"html-br\" \/>\u09b8\u09aa\u09cd\u09a4\u09ae \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u098f\u09b0 \u09aa\u09b0\u09c7 \u098f\u0995\u099c\u09a8 \u09b8\u09be\u0995\u09cd\u09b7\u09c0<br class=\"html-br\" \/>\u2022 \u09b8\u09be\u0995\u09cd\u09b7\u09c0 \u0995\u09be\u09b0\u09be?<br class=\"html-br\" \/>\u2022 \u098f\u0987 \u09ae\u09b9\u09be\u09a8 \u0986\u09af\u09bc\u09be\u09a4\u09c7\u09b0 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be: &quot;\u09af\u09be\u09b0 \u0989\u09aa\u09b0 \u09a4\u09be\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1\u09b0 \u09aa\u0995\u09cd\u09b7 \u09a5\u09c7\u0995\u09c7 \u09b8\u09cd\u09aa\u09b7\u09cd\u099f \u09aa\u09cd\u09b0\u09ae\u09be\u09a3 \u09b0\u09af\u09bc\u09c7\u099b\u09c7 \u098f\u09ac\u0982 \u09a4\u09be\u09b0 \u09aa\u0995\u09cd\u09b7 \u09a5\u09c7\u0995\u09c7 \u098f\u0995\u099c\u09a8 \u09b8\u09be\u0995\u09cd\u09b7\u09c0 \u09b0\u09af\u09bc\u09c7\u099b\u09c7 \u09b8\u09c7 \u0995\u09bf \u09a4\u09be \u09aa\u09be\u09a0 \u0995\u09b0\u09ac\u09c7?&quot;<br class=\"html-br\" \/>\u2022 &quot;\u098f\u09ac\u0982 \u09a4\u09be\u0981\u09b0 \u09aa\u0995\u09cd\u09b7 \u09a5\u09c7\u0995\u09c7 \u098f\u0995\u099c\u09a8 \u09b8\u09be\u0995\u09cd\u09b7\u09c0 \u09a4\u09be\u0981\u09b0 \u09aa\u09bf\u099b\u09a8\u09c7 \u0986\u09b8\u09ac\u09c7\u09a8&quot; \u098f\u0987 \u09ae\u09b9\u09ce \u0986\u09af\u09bc\u09be\u09a4\u099f\u09bf \u09a6\u09cd\u09ac\u09be\u09b0\u09be \u0995\u09be\u0995\u09c7 \u09ac\u09cb\u099d\u09be\u09a8\u09cb \u09b9\u09af\u09bc\u09c7\u099b\u09c7?<br class=\"html-br\" \/>\u0985\u09b7\u09cd\u099f\u09ae \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09aa\u09cd\u09b0\u09ae\u09be\u09a3\u09c7\u09b0 \u09ac\u09be\u09b0\u09cd\u09a4\u09be\u09ac\u09be\u09b9\u0995<br class=\"html-br\" \/>\u2022 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3\u09c7\u09b0 \u09a7\u09be\u09b0\u09a3\u09be<br class=\"html-br\" \/>\u2022 \u09b8\u09c2\u09b0\u09be \u0986\u09b2-\u09ac\u09be\u0987\u09af\u09bc\u09c0\u09a8\u09be\u09b9 \u098f\u09b0 \u09ac\u09bf\u0996\u09cd\u09af\u09be\u09a4 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be<br class=\"html-br\" \/>\u2022 \u09b8\u09c2\u09b0\u09be \u0986\u09b2-\u09ac\u09be\u0987\u09af\u09bc\u09c0\u09a8\u09be\u09b9 \u098f\u09b0 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be<br class=\"html-br\" \/>\u2022 \u09b8\u09c2\u09b0\u09be \u0986\u09b2-\u09ac\u09be\u0987\u09af\u09bc\u09cd\u09af\u09bf\u09a8\u09be\u09a4\u09c7 \u0989\u09b2\u09cd\u09b2\u09c7\u0996\u09bf\u09a4 \u09b0\u09be\u09b8\u09c2\u09b2 \u0995\u09c7?<br class=\"html-br\" \/>\u09a8\u09ac\u09ae \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u099a\u09be\u0981\u09a6\u09c7\u09b0 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09a8<br class=\"html-br\" \/>\u2022 \u09ad\u09be\u09b7\u09cd\u09af\u0995\u09be\u09b0\u09a6\u09c7\u09b0 \u09ac\u0995\u09cd\u09a4\u09ac\u09cd\u09af: \u09ae\u09a4\u09be\u09ae\u09a4 \u098f\u09ac\u0982 \u0985\u09a8\u09cd\u09af\u09be\u09a8\u09cd\u09af \u09ae\u09a4\u09be\u09ae\u09a4<br class=\"html-br\" \/>\u2022 \u09ac\u09bf\u09b6\u09c1\u09a6\u09cd\u09a7 \u09b9\u09be\u09a6\u09bf\u09b8 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u0995\u09c0 \u09ac\u09b2\u09be \u09af\u09be\u09df?<br class=\"html-br\" \/>\u2022 \u09b6\u09c7\u0996 \u0986\u09b2-\u0997\u09be\u099c\u09cd\u099c\u09be\u09b2\u09c0\u09b0 \u09ae\u09a4\u09be\u09ae\u09a4<br class=\"html-br\" \/>\u2022 \u098f\u0995\u099f\u09bf \u0985\u09b2\u09cc\u0995\u09bf\u0995 \u0995\u09be\u099c\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u09ac\u09bf\u09b6\u09be\u09b2 \u09a6\u09b0\u09cd\u09b6\u0995\u09c7\u09b0 \u09aa\u09cd\u09b0\u09af\u09bc\u09cb\u099c\u09a8 \u09b9\u09af\u09bc\u0964<br class=\"html-br\" \/>\u2022 \u09a8\u09ac\u09c0\u09a6\u09c7\u09b0 \u09b8\u0995\u09b2 \u0985\u09b2\u09cc\u0995\u09bf\u0995 \u0995\u09be\u099c\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09b8\u09ac\u099a\u09c7\u09af\u09bc\u09c7 \u09ac\u09a1\u09bc \u0985\u09b2\u09cc\u0995\u09bf\u0995 \u0998\u099f\u09a8\u09be \u098f\u09ac\u0982 \u09b8\u09ac\u099a\u09c7\u09af\u09bc\u09c7 \u0995\u09ae \u0989\u09b2\u09cd\u09b2\u09c7\u0996\u09bf\u09a4 \u0985\u09b2\u09cc\u0995\u09bf\u0995 \u0998\u099f\u09a8\u09be?!<br class=\"html-br\" \/>\u2022 \u098f\u0987 \u0985\u09b2\u09cc\u0995\u09bf\u0995 \u0998\u099f\u09a8\u09be\u09b0 \u0995\u09be\u09b0\u09a3\u09c7 \u0995\u09bf \u0995\u09c7\u0989 \u0987\u09b8\u09b2\u09be\u09ae \u0997\u09cd\u09b0\u09b9\u09a3 \u0995\u09b0\u09c7\u099b\u09c7?<br class=\"html-br\" \/>\u2022 \u09af\u09be\u09b0\u09be \u099a\u09a8\u09cd\u09a6\u09cd\u09b0 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09b9\u0993\u09af\u09bc\u09be\u09b0 \u0986\u09af\u09bc\u09be\u09a4 \u0985\u09b8\u09cd\u09ac\u09c0\u0995\u09be\u09b0 \u0995\u09b0\u09c7\u099b\u09bf\u09b2 \u09a4\u09be\u09a6\u09c7\u09b0 \u09b6\u09be\u09b8\u09cd\u09a4\u09bf \u0995\u09cb\u09a5\u09be\u09af\u09bc?<br class=\"html-br\" \/>\u2022 \u099a\u09a8\u09cd\u09a6\u09cd\u09b0 \u0996\u09be\u0981\u099c<br class=\"html-br\" \/>\u2022 \u099a\u09a8\u09cd\u09a6\u09cd\u09b0 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09b9\u0993\u09af\u09bc\u09be\u09b0 \u0986\u09af\u09bc\u09be\u09a4\u099f\u09bf \u09ad\u09ac\u09bf\u09b7\u09cd\u09af\u09a4\u09c7 \u0998\u099f\u09ac\u09c7<br class=\"html-br\" \/>\u2022 \u099a\u09be\u0981\u09a6 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09b9\u09b2\u09c7 \u09b2\u09cb\u0995\u09c7\u09b0\u09be \u09aa\u09cd\u09b0\u09a4\u09c0\u0995\u09cd\u09b7\u09bf\u09a4 \u09b0\u09be\u09b8\u09c2\u09b2\u0995\u09c7 \u0995\u09c0\u09ad\u09be\u09ac\u09c7 \u09ac\u09b0\u09cd\u09a3\u09a8\u09be \u0995\u09b0\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u0995\u09c7 \u09b8\u09c7\u0987 \u09b0\u09b8\u09c2\u09b2 \u09af\u09be\u09b0 \u09ac\u09bf\u09b0\u09c1\u09a6\u09cd\u09a7\u09c7 \u099c\u09be\u09a6\u09c1\u09b0 \u0985\u09ad\u09bf\u09af\u09cb\u0997 \u0986\u09a8\u09be \u09b9\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u099a\u09be\u0981\u09a6 \u0995\u09a4\u0995\u09cd\u09b7\u09a3 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09a5\u09be\u0995\u09ac\u09c7?<br class=\"html-br\" \/>\u099a\u09be\u0981\u09a6\u09c7\u09b0 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09b9\u0993\u09df\u09be \u098f\u0995\u099f\u09bf \u09b8\u09a4\u09b0\u09cd\u0995\u09c0\u0995\u09b0\u09a3 \u099a\u09bf\u09b9\u09cd\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995\u09ad\u09be\u09ac\u09c7 \u099a\u09be\u0981\u09a6 \u0995\u09c0\u09ad\u09be\u09ac\u09c7 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09b9\u09af\u09bc\u09c7\u099b\u09bf\u09b2<br class=\"html-br\" \/>\u2022 \u099a\u09be\u0981\u09a6 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09b9\u0993\u09df\u09be\u09b0 \u09b8\u09be\u09a5\u09c7 \u0995\u09c7\u09df\u09be\u09ae\u09a4\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a7\u09be\u09a8 \u09b2\u0995\u09cd\u09b7\u09a3\u0997\u09c1\u09b2\u09cb\u09b0 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995<br class=\"html-br\" \/>\u2022 \u0995\u09c7\u09a8 \u099a\u09be\u0981\u09a6\u09c7\u09b0 \u09a6\u09cd\u09ac\u09bf\u0996\u09a3\u09cd\u09a1\u09bf\u09a4 \u09b9\u0993\u09df\u09be \u0995\u09c7\u09df\u09be\u09ae\u09a4\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a5\u09ae \u09aa\u09cd\u09b0\u09a7\u09be\u09a8 \u09b2\u0995\u09cd\u09b7\u09a3?<br class=\"html-br\" \/>\u2022 \u09b8\u09c2\u09b0\u09be \u0986\u09b2-\u0995\u09cd\u09ac\u09be\u09ae\u09be\u09b0\u09c7\u09b0 \u09b0\u09b9\u09b8\u09cd\u09af<br class=\"html-br\" \/>\u09a6\u09b6\u09ae \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09aa\u09b0\u09bf\u09b7\u09cd\u0995\u09be\u09b0 \u09a7\u09cb\u0981\u09af\u09bc\u09be<br class=\"html-br\" \/>\u2022 \u09a7\u09cb\u0981\u09af\u09bc\u09be\u09b0 \u0986\u09af\u09bc\u09be\u09a4\u09c7\u09b0 \u09b8\u0982\u0998\u099f\u09a8\u09c7\u09b0 \u09b8\u09ae\u09af\u09bc\u09c7\u09b0 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be\u09b0 \u09aa\u09be\u09b0\u09cd\u09a5\u0995\u09cd\u09af<br class=\"html-br\" \/>\u2022 \u09a8\u09ac\u09c0 (\u09b8\u09be\u0983)-\u098f\u09b0 \u09af\u09c1\u0997\u09c7 \u09a7\u09c2\u09ae\u09aa\u09be\u09a8\u09c7\u09b0 \u0986\u09af\u09bc\u09be\u09a4 \u09ac\u09bf\u09a6\u09cd\u09af\u09ae\u09be\u09a8 \u099b\u09bf\u09b2 \u098f\u0987 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8\u09c7\u09b0 \u0985\u0995\u09be\u09b0\u09cd\u09af\u0995\u09b0\u09a4\u09be\u09b0 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3, \u0986\u09b2\u09cd\u09b2\u09be\u09b9 \u09a4\u09be\u0995\u09c7 \u0986\u09b6\u09c0\u09b0\u09cd\u09ac\u09be\u09a6 \u0995\u09b0\u09c1\u09a8 \u098f\u09ac\u0982 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09a6\u09be\u09a8 \u0995\u09b0\u09c1\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u09a7\u09cb\u0981\u09af\u09bc\u09be\u09b0 \u0986\u09af\u09bc\u09be\u09a4\u099f\u09bf \u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u098f\u09ac\u0982 \u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09aa\u09c2\u09b0\u09cd\u09ac\u09ac\u09b0\u09cd\u09a4\u09c0 \u0986\u09b2\u09be\u09ae\u09a4\u0997\u09c1\u09b2\u09bf\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u098f\u0995\u099f\u09bf\u0964<br class=\"html-br\" \/>\u2022 \u09a7\u09cb\u0981\u09af\u09bc\u09be\u09b0 \u0986\u09af\u09bc\u09be\u09a4\u09c7\u09b0 \u09ac\u09bf\u0996\u09cd\u09af\u09be\u09a4 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be<br class=\"html-br\" \/>\u2022 \u0987\u09ac\u09a8\u09c7 \u0986\u09ac\u09cd\u09ac\u09be\u09b8 \u098f\u09ac\u0982 \u0986\u09b2\u09c0 (\u09b0\u09be\u0983) \u098f\u09b0 \u0995\u09a5\u09be \u0985\u09a8\u09c1\u09b8\u09be\u09b0\u09c7 \u09a7\u09cb\u0981\u09af\u09bc\u09be\u09b0 \u0986\u09af\u09bc\u09be\u09a4\u09c7\u09b0 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be, \u0986\u09b2\u09cd\u09b2\u09be\u09b9 \u09a4\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a4\u09bf \u09b8\u09a8\u09cd\u09a4\u09c1\u09b7\u09cd\u099f \u09a5\u09be\u0995\u09c1\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u0995\u0996\u09a8\u0993 \u0995\u09bf \u098f\u09ae\u09a8 \u0998\u099f\u09c7\u099b\u09c7 \u09af\u09c7, \u0995\u09cb\u09a8 \u09b0\u09be\u09b8\u09c2\u09b2 \u09a4\u09be\u09b0 \u09aa\u09b0\u09ac\u09b0\u09cd\u09a4\u09c0 \u0995\u09af\u09bc\u09c7\u0995 \u09b6\u09a4\u09be\u09ac\u09cd\u09a6\u09c0 \u09aa\u09b0\u09c7 \u0986\u0997\u09a4 \u099c\u09be\u09a4\u09bf\u0995\u09c7 \u09af\u09a8\u09cd\u09a4\u09cd\u09b0\u09a3\u09be\u09a6\u09be\u09df\u0995 \u09b6\u09be\u09b8\u09cd\u09a4\u09bf\u09b0 \u09b8\u09a4\u09b0\u09cd\u0995 \u0995\u09b0\u09c7\u099b\u09bf\u09b2\u09c7\u09a8?<br class=\"html-br\" \/>\u2022 \u0986\u09af\u09bc\u09be\u09a4\u09c7\u09b0 \u09b0\u09b9\u09b8\u09cd\u09af: &quot;\u0985\u09a4\u098f\u09ac \u0985\u09aa\u09c7\u0995\u09cd\u09b7\u09be \u0995\u09b0\u09cb, \u0995\u09be\u09b0\u09a3 \u09a4\u09be\u09b0\u09be \u0985\u09aa\u09c7\u0995\u09cd\u09b7\u09be \u0995\u09b0\u099b\u09c7\u0964&quot;<br class=\"html-br\" \/>\u2022 \u0995\u09c7 \u09b8\u09c7\u0987 \u09b8\u09cd\u09aa\u09b7\u09cd\u099f \u09ac\u09be\u09b0\u09cd\u09a4\u09be\u09ac\u09be\u09b9\u0995 \u09af\u09be\u0995\u09c7 \u09ae\u09be\u09a8\u09c1\u09b7 \u09aa\u09be\u0997\u09b2 \u09b6\u09bf\u0995\u09cd\u09b7\u0995 \u09b9\u09bf\u09b8\u09c7\u09ac\u09c7 \u09ac\u09b0\u09cd\u09a3\u09a8\u09be \u0995\u09b0\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u09b8\u09c2\u09b0\u09be \u0986\u09a6-\u09a6\u09c1\u0996\u09be\u09a8\u09c7 \u0989\u09b2\u09cd\u09b2\u09c7\u0996\u09bf\u09a4 \u098f\u0987 \u09b8\u09cd\u09aa\u09b7\u09cd\u099f \u09b0\u09be\u09b8\u09c2\u09b2 \u0995\u09c0 \u099c\u09cd\u099e\u09be\u09a8 \u09a8\u09bf\u09af\u09bc\u09c7 \u0986\u09b8\u09ac\u09c7\u09a8?<br class=\"html-br\" \/>\u2022 &quot;\u098f\u0995\u099c\u09a8 \u09b8\u09cd\u09aa\u09b7\u09cd\u099f \u09ac\u09be\u09b0\u09cd\u09a4\u09be\u09ac\u09be\u09b9\u0995&quot; \u098f\u09ac\u0982 &quot;\u098f\u0995\u099f\u09bf \u09b8\u09cd\u09aa\u09b7\u09cd\u099f \u09a7\u09cb\u0981\u09af\u09bc\u09be\u09b0 \u09b8\u09be\u09a5\u09c7&quot; \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7\u09b0 \u09b0\u09b9\u09b8\u09cd\u09af \u0995\u09c0?<br class=\"html-br\" \/>\u2022 \u09a7\u09cb\u0981\u09af\u09bc\u09be \u0995\u09bf \u09ae\u09b9\u09be\u0995\u09be\u09b6 \u09a5\u09c7\u0995\u09c7 \u0986\u09b8\u099b\u09c7 \u09a8\u09be\u0995\u09bf \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0 \u09a5\u09c7\u0995\u09c7?<br class=\"html-br\" \/>\u0986\u09b8\u09a8\u09cd\u09a8 \u09a7\u09c2\u09ae\u0995\u09c7\u09a4\u09c1<br class=\"html-br\" \/>\u2022 \u09a7\u09c2\u09ae\u0995\u09c7\u09a4\u09c1\u09af\u09c1\u0995\u09cd\u09a4 \u09a8\u0995\u09cd\u09b7\u09a4\u09cd\u09b0\u09c7\u09b0 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995 \u09a8\u09be\u09ae<br class=\"html-br\" \/>\u2022 \u09a4\u09bf\u09a8\u099f\u09bf \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995 \u0985\u09a8\u09c1\u09ae\u09be\u09a8 \u09a7\u09cb\u0981\u09af\u09bc\u09be\u09b0 \u0995\u09be\u09b0\u09a3 \u09b9\u09ac\u09c7<br class=\"html-br\" \/>\u2022 \u098f\u0995\u099f\u09bf \u09a7\u09c2\u09ae\u0995\u09c7\u09a4\u09c1 \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0\u09a4\u09c7 \u09aa\u09a1\u09bc\u09c7 \u09a7\u09cb\u0981\u09af\u09bc\u09be \u09b8\u09c3\u09b7\u09cd\u099f\u09bf \u0995\u09b0\u09be\u09b0 \u0985\u09a8\u09c1\u09ae\u09be\u09a8<br class=\"html-br\" \/>\u2022 \u098f\u0995\u099f\u09bf \u09ac\u09bf\u09b6\u09be\u09b2 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf\u09b0 \u0995\u09be\u09b0\u09a3\u09c7 \u09a7\u09cb\u0981\u09af\u09bc\u09be\u09b6\u09be \u09b8\u09c3\u09b7\u09cd\u099f\u09bf \u09b9\u09af\u09bc\u09c7\u099b\u09c7 \u098f\u0987 \u0985\u09a8\u09c1\u09ae\u09be\u09a8<br class=\"html-br\" \/>\u2022 Eyjafjallaj\u00f6kull \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf, \u0986\u0987\u09b8\u09b2\u09cd\u09af\u09be\u09a8\u09cd\u09a1<br class=\"html-br\" \/>\u2022 \u09ac\u09bf\u09b6\u09be\u09b2 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf<br class=\"html-br\" \/>\u2022 \u09b8\u09c1\u09aa\u09be\u09b0 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf \u099f\u09cb\u09ac\u09be<br class=\"html-br\" \/>\u2022 \u0987\u09af\u09bc\u09c7\u09b2\u09cb\u09b8\u09cd\u099f\u09cb\u09a8 \u09b8\u09c1\u09aa\u09be\u09b0\u09ad\u09be\u0987\u09b2\u0995\u09cd\u09af\u09be\u09a8\u09cb<br class=\"html-br\" \/>\u2022 \u09a7\u09cb\u0981\u09af\u09bc\u09be \u09ae\u09c1\u09ae\u09bf\u09a8\u0995\u09c7 \u09a0\u09be\u09a8\u09cd\u09a1\u09be\u09b0 \u09ae\u09a4\u09cb \u09a7\u09b0\u09c7, \u0995\u09bf\u09a8\u09cd\u09a4\u09c1 \u0985\u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8\u09c0 \u09a4\u09be \u09ab\u09c1\u0981 \u09a6\u09bf\u09af\u09bc\u09c7 \u09ab\u09c1\u0981 \u09a6\u09bf\u09af\u09bc\u09c7 \u09aa\u09cd\u09b0\u09a4\u09cd\u09af\u09c7\u0995 \u0995\u09be\u09a8 \u09a5\u09c7\u0995\u09c7 \u09ac\u09c7\u09b0\u09bf\u09af\u09bc\u09c7 \u0986\u09b8\u09c7\u0964<br class=\"html-br\" \/>\u2022 \u0985\u09a4\u09bf-\u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf\u09b0 \u0985\u0997\u09cd\u09a8\u09cd\u09af\u09c1\u09ce\u09aa\u09be\u09a4 \u09ac\u09be \u09a7\u09c2\u09ae\u0995\u09c7\u09a4\u09c1\u09b0 \u0986\u0998\u09be\u09a4\u09c7\u09b0 \u09b8\u09ae\u09af\u09bc \u098f\u09ac\u0982 \u0985\u09ac\u09b8\u09cd\u09a5\u09be\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u09a6\u09c7\u0996\u09be\u09a8\u09cb \u09a7\u09cb\u0981\u09af\u09bc\u09be \u099b\u09a1\u09bc\u09bf\u09af\u09bc\u09c7 \u09aa\u09a1\u09bc\u09be\u09b0 \u09aa\u09b0 \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0\u09a4\u09c7 \u099c\u09c0\u09ac\u09a8\u09c7\u09b0 \u09b0\u09c2\u09aa<br class=\"html-br\" \/>\u2022 \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0\u09a4\u09c7 \u09a7\u09cb\u0981\u09af\u09bc\u09be \u0995\u09a4\u0995\u09cd\u09b7\u09a3 \u09b8\u09cd\u09a5\u09be\u09af\u09bc\u09c0 \u09b9\u09af\u09bc? \u09b8\u09c7\u0987 \u09b8\u09ae\u09af\u09bc \u09ae\u09be\u09a8\u09c1\u09b7\u09c7\u09b0 \u09aa\u09cd\u09b0\u09be\u09b0\u09cd\u09a5\u09a8\u09be \u0995\u09c0?<br class=\"html-br\" \/>\u098f\u0995\u09be\u09a6\u09b6 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u09b0\u09be\u09b8\u09c2\u09b2<br class=\"html-br\" \/>\u2022 \u09b0\u09be\u09b8\u09c2\u09b2\u09c1\u09b2\u09cd\u09b2\u09be\u09b9 \u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09b2\u09cd\u09b2\u09be\u09b9\u09c1 \u0986\u09b2\u09be\u0987\u09b9\u09bf \u0993\u09af\u09bc\u09be\u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09ae \u098f\u09b0 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u09b8\u09c1\u09b8\u0982\u09ac\u09be\u09a6<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u09a8\u09be\u09ae\u09c7 \u0997\u09cb\u09aa\u09a8 \u09b0\u09b9\u09b8\u09cd\u09af<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u09a8\u09ac\u09c0 \u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09b2\u09cd\u09b2\u09be\u09b9\u09c1 \u0986\u09b2\u09be\u0987\u09b9\u09bf \u0993\u09af\u09bc\u09be\u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09ae \u098f\u09b0 \u09ac\u09b0\u09cd\u09a3\u09a8\u09be \u09aa\u09cd\u09b0\u09be\u09af\u09bc \u09ac\u09bf\u09b8\u09cd\u09a4\u09be\u09b0\u09bf\u09a4!<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0 \u0995\u09c0 \u09a7\u09b0\u09a3\u09c7\u09b0 \u09b8\u0982\u09b8\u09cd\u0995\u09be\u09b0 \u0986\u09a8\u09ac\u09c7\u09a8?<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0\u0995\u09c7 \u09b8\u09b0\u09cd\u09ac\u09b6\u0995\u09cd\u09a4\u09bf\u09ae\u09be\u09a8 \u0988\u09b6\u09cd\u09ac\u09b0 \u099c\u09be\u09a4\u09bf\u09b0 \u0995\u09be\u099b\u09c7 \u09aa\u09cd\u09b0\u09c7\u09b0\u09a3 \u0995\u09b0\u09ac\u09c7\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0 \u09a4\u0996\u09a8 \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09c2\u09a4 \u09b9\u09ac\u09c7\u09a8 \u09af\u0996\u09a8 \u099c\u09be\u09a4\u09bf \u09b8\u0982\u0998\u09b0\u09cd\u09b7\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09a5\u09be\u0995\u09ac\u09c7, \u098f\u09ac\u0982 \u09a4\u09bf\u09a8\u09bf \u09b6\u09be\u09b8\u09a8 \u0995\u09b0\u09ac\u09c7\u09a8 \u098f\u09ac\u0982 \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0\u0995\u09c7 \u09a8\u09cd\u09af\u09be\u09af\u09bc\u09ac\u09bf\u099a\u09be\u09b0\u09c7 \u09aa\u09c2\u09b0\u09cd\u09a3 \u0995\u09b0\u09ac\u09c7\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u09ac\u09bf\u09b0\u09c1\u09a6\u09cd\u09a7\u09c7 \u09af\u09c1\u09a6\u09cd\u09a7\u0995\u09be\u09b0\u09c0 \u09b8\u09c7\u09a8\u09be\u09ac\u09be\u09b9\u09bf\u09a8\u09c0\u09b0 \u09a1\u09c1\u09ac\u09c7 \u09af\u09be\u0993\u09af\u09bc\u09be\u09b0 \u0985\u09b2\u09cc\u0995\u09bf\u0995 \u0998\u099f\u09a8\u09be<br class=\"html-br\" \/>\u2022 \u0985\u0999\u09cd\u0997\u09c0\u0995\u09be\u09b0<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0 \u098f\u09ac\u0982 \u09ae\u09b9\u09be\u09a8 \u09ae\u09b9\u09be\u0995\u09be\u09ac\u09cd\u09af<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u09af\u09c1\u0997\u09c7 \u09b8\u0995\u09b2 \u09a7\u09b0\u09cd\u09ae\u09c7\u09b0 \u0989\u09aa\u09b0 \u0987\u09b8\u09b2\u09be\u09ae\u09c7\u09b0 \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09be\u09ac<br class=\"html-br\" \/>\u2022 \u09b8\u09b0\u09cd\u09ac\u09b6\u0995\u09cd\u09a4\u09bf\u09ae\u09be\u09a8 \u0986\u09b2\u09cd\u09b2\u09be\u09b9 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u0989\u09aa\u09b0 \u09ac\u09c3\u09b7\u09cd\u099f\u09bf \u09ac\u09b0\u09cd\u09b7\u09a3 \u0995\u09b0\u09c1\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1\u09b0 \u09aa\u09bf\u099b\u09a8\u09c7 \u09a8\u09be\u09ae\u09be\u099c \u09aa\u09a1\u09bc\u09be \u09ac\u09cd\u09af\u0995\u09cd\u09a4\u09bf\u09b0 \u09ac\u09b0\u09cd\u09a3\u09a8\u09be, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u09af\u09c1\u0997\u09c7 \u0995\u09bf \u0986\u09b2-\u0996\u09bf\u09a6\u09b0 \u098f\u09ac\u0982 \u0997\u09c1\u09b9\u09be\u09ac\u09be\u09b8\u09c0\u09b0\u09be \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09c2\u09a4 \u09b9\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u0995\u09bf\u099b\u09c1 \u09a8\u09ac\u09c0\u09b0 \u09b8\u09be\u09a5\u09c7 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u099c\u09c0\u09ac\u09a8\u09c7\u09b0 \u09ae\u09bf\u09b2<br class=\"html-br\" \/>\u2022 \u0995\u09c7\u09a8 \u09ae\u09be\u09b9\u09a6\u09c0\u0995\u09c7 \u098f\u0995\u099c\u09a8 \u09b0\u09be\u09b8\u09c2\u09b2 \u09ac\u09b2\u09c7 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8 \u0995\u09b0\u09be \u09b9\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u09aa\u09ac\u09bf\u09a4\u09cd\u09b0 \u0995\u09cb\u09b0\u0986\u09a8\u09c7\u09b0 \u0986\u09af\u09bc\u09be\u09a4\u09b8\u09ae\u09c2\u09b9\u0995\u09c7 \u09aa\u09ac\u09bf\u09a4\u09cd\u09b0 \u09b9\u09be\u09a6\u09bf\u09b8\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09b8\u0982\u09af\u09c1\u0995\u09cd\u09a4 \u0995\u09b0\u09c7 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u099c\u09c0\u09ac\u09a8 \u0995\u09be\u09b9\u09bf\u09a8\u09c0<br class=\"html-br\" \/>\u09a6\u09cd\u09ac\u09be\u09a6\u09b6 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1<br class=\"html-br\" \/>\u2022 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09c7\u09b0 \u0985\u09b0\u09cd\u09a5<br class=\"html-br\" \/>\u2022 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1 \u09b6\u09ac\u09cd\u09a6\u09c7\u09b0 \u0985\u09b0\u09cd\u09a5<br class=\"html-br\" \/>\u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1 \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09be\u09ac\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09a3<br class=\"html-br\" \/>\u2022 \u09b8\u09c7\u0987 \u09b8\u09cd\u09a5\u09be\u09a8 \u09af\u09c7\u0996\u09be\u09a8\u09c7 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1 \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09c2\u09a4 \u09b9\u09ac\u09c7<br class=\"html-br\" \/>\u2022 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1\u09a6\u09c7\u09b0 \u09a8\u09c8\u09a4\u09bf\u0995 \u09ac\u09c8\u09b6\u09bf\u09b7\u09cd\u099f\u09cd\u09af<br class=\"html-br\" \/>\u2022 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1\u09a6\u09c7\u09b0 \u0997\u09a4\u09bf\u09ac\u09bf\u09a7\u09bf\u09b0 \u0997\u09a4\u09bf<br class=\"html-br\" \/>\u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1 \u09b8\u09cd\u09ac\u09b0\u09cd\u0997 \u098f\u09ac\u0982 \u09a8\u09b0\u0995 \u09a8\u09bf\u09af\u09bc\u09c7 \u0986\u09b8\u09ac\u09c7\u0964<br class=\"html-br\" \/>\u2022 \u099c\u09a1\u09bc \u0993 \u09aa\u09cd\u09b0\u09be\u09a3\u09c0\u099c \u09ac\u09b8\u09cd\u09a4\u09c1 \u09a4\u09be\u0981\u09b0 \u0986\u09a6\u09c7\u09b6\u09c7 \u09b8\u09be\u09a1\u09bc\u09be \u09a6\u09c7\u09af\u09bc\u0964<br class=\"html-br\" \/>\u2022 \u09b8\u09c7 \u098f\u0995\u099c\u09a8 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8\u09c0 \u09af\u09c1\u09ac\u0995\u0995\u09c7 \u09b9\u09a4\u09cd\u09af\u09be \u0995\u09b0\u09c7 \u098f\u09ac\u0982 \u09a4\u09be\u09b0\u09aa\u09b0 \u09a4\u09be\u0995\u09c7 \u099c\u09c0\u09ac\u09bf\u09a4 \u0995\u09b0\u09c7\u0964<br class=\"html-br\" \/>\u2022 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09b2\u09cb\u09ad\u09a8 \u0995\u09c0\u09ad\u09be\u09ac\u09c7 \u09aa\u09cd\u09b0\u09a4\u09bf\u09b0\u09cb\u09a7 \u0995\u09b0\u09be \u09af\u09be\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1, \u09ae\u09be\u09b9\u09a6\u09c0 \u098f\u09ac\u0982 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995<br class=\"html-br\" \/>\u2022 \u0995\u09c7\u09a8 \u09b8\u09c7\u0987 \u09b8\u09ae\u09af\u09bc\u09c7 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1\u09a6\u09c7\u09b0 \u09ac\u09bf\u099a\u09be\u09b0 \u09b9\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u0996\u09cd\u09b0\u09c0\u09b7\u09cd\u099f\u09b6\u09a4\u09cd\u09b0\u09c1\u09a6\u09c7\u09b0 \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09be\u09ac\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09a3 \u098f\u09ac\u0982 \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09a3\u0997\u09c1\u09b2\u09bf\u09b0 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995 \u0985\u09a8\u09c1\u09ae\u09be\u09a8\u09c7\u09b0 \u09b8\u09be\u09a5\u09c7 \u09a4\u09be\u09a6\u09c7\u09b0 \u09b8\u0982\u09af\u09cb\u0997<br class=\"html-br\" \/>\u09a4\u09cd\u09b0\u09af\u09bc\u09cb\u09a6\u09b6 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09af\u09c0\u09b6\u09c1\u09b0 \u0985\u09ac\u09a4\u09b0\u09a3, \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995<br class=\"html-br\" \/>\u2022 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1\u09b0 \u09ac\u09b0\u09cd\u09a3\u09a8\u09be, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995<br class=\"html-br\" \/>\u2022 \u0988\u09b8\u09be (\u0986\u0983) \u0995\u09c0\u09ad\u09be\u09ac\u09c7 \u0985\u09ac\u09a4\u09b0\u09a3 \u0995\u09b0\u09c7\u099b\u09bf\u09b2\u09c7\u09a8?<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0\u09b0 \u09af\u09c1\u0997\u09c7 \u0988\u09b8\u09be (\u0986\u0983)-\u098f\u09b0 \u0985\u09ac\u09a4\u09b0\u09a3<br class=\"html-br\" \/>\u2022 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995, \u09af\u09c7 \u0995\u09be\u099c\u0997\u09c1\u09b2\u09bf \u0995\u09b0\u09ac\u09c7\u09a8 \u098f\u09ac\u0982 \u09a4\u09be\u0981\u09b0 \u09b0\u09be\u099c\u09a4\u09cd\u09ac\u0995\u09be\u09b2\u09c7 \u0995\u09c0 \u0998\u099f\u09ac\u09c7<br class=\"html-br\" \/>\u0987\u09af\u09bc\u09be\u099c\u09c1\u099c \u0993 \u09ae\u09be\u099c\u09c1\u099c<br class=\"html-br\" \/>\u2022 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1\u09b0 \u09af\u09c1\u0997\u09c7 \u09b8\u0995\u09b2 \u09a7\u09b0\u09cd\u09ae\u09c7\u09b0 \u0989\u09aa\u09b0\u09c7 \u0987\u09b8\u09b2\u09be\u09ae\u09c7\u09b0 \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09be\u09ac\u0964<br class=\"html-br\" \/>\u2022 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995, \u09b9\u099c\u09cd\u099c \u0993 \u0993\u09ae\u09b0\u09be\u09b0 \u09b8\u09ae\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u09af\u09c0\u09b6\u09c1\u09b0 \u0985\u09ac\u09a4\u09b0\u09a3\u09c7\u09b0 \u09aa\u09b0, \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995, \u09a4\u09be\u0981\u09b0 \u0985\u09ac\u09b8\u09cd\u09a5\u09be\u09a8\u09c7\u09b0 \u09b8\u09ae\u09af\u09bc\u0995\u09be\u09b2 \u098f\u09ac\u0982 \u09a4\u09be\u09b0\u09aa\u09b0 \u09a4\u09be\u0981\u09b0 \u09ae\u09c3\u09a4\u09cd\u09af\u09c1\u09b0 \u09b8\u09ae\u09af\u09bc\u0995\u09be\u09b2<br class=\"html-br\" \/>\u2022 \u09ae\u09be\u09b9\u09a6\u09c0 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u0988\u09b8\u09be (\u0986\u0983) \u098f\u0987 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8\u09c7\u09b0 \u0985\u0995\u09be\u09b0\u09cd\u09af\u0995\u09b0\u09a4\u09be\u09b0 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995\u0964<br class=\"html-br\" \/>\u2022 \u0988\u09b8\u09be (\u0986\u0983) \u0995\u09bf \u09b6\u09be\u09b8\u0995 \u09b9\u09bf\u09b8\u09c7\u09ac\u09c7 \u0985\u09ac\u09a4\u09c0\u09b0\u09cd\u09a3 \u09b9\u09ac\u09c7\u09a8, \u09a8\u09be\u0995\u09bf \u09a8\u09ac\u09c0 \u09b9\u09bf\u09b8\u09c7\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3 \u09af\u09c7 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995, \u098f\u0995\u099c\u09a8 \u09a8\u09ac\u09c0 \u09b9\u09bf\u09b8\u09c7\u09ac\u09c7 \u09aa\u09c1\u09a8\u09b0\u09c1\u09a4\u09cd\u09a5\u09bf\u09a4 \u09b9\u09af\u09bc\u09c7\u099b\u09bf\u09b2\u09c7\u09a8 \u098f\u09ac\u0982 \u098f\u0995\u099c\u09a8 \u09b6\u09be\u09b8\u0995 \u09a8\u09ac\u09c0 \u09b9\u09bf\u09b8\u09c7\u09ac\u09c7 \u09ab\u09bf\u09b0\u09c7 \u0986\u09b8\u09ac\u09c7\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u09af\u09c0\u09b6\u09c1, \u09a4\u09be\u0981\u09b0 \u0989\u09aa\u09b0 \u09b6\u09be\u09a8\u09cd\u09a4\u09bf \u09ac\u09b0\u09cd\u09b7\u09bf\u09a4 \u09b9\u09cb\u0995, \u09b6\u09c7\u09b7 \u09af\u09c1\u0997\u09c7 \u0995\u09c7\u09ac\u09b2 \u098f\u0995\u099c\u09a8 \u09b6\u09be\u09b8\u0995 \u09b9\u09bf\u09b8\u09c7\u09ac\u09c7 \u09ab\u09bf\u09b0\u09c7 \u0986\u09b8\u09ac\u09c7\u09a8, \u098f\u0987 \u09ac\u09bf\u09b6\u09cd\u09ac\u09be\u09b8\u09c7\u09b0 \u09ac\u09bf\u09aa\u09a6\u0964<br class=\"html-br\" \/>\u2022 \u09b8\u09b0\u09cd\u09ac\u09b6\u0995\u09cd\u09a4\u09bf\u09ae\u09be\u09a8 \u0986\u09b2\u09cd\u09b2\u09be\u09b9 \u0995\u09bf \u09ae\u09be\u09b9\u09a6\u09c0 \u098f\u09ac\u0982 \u0986\u09ae\u09be\u09a6\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ad\u09c1 \u0988\u09b8\u09be (\u0986\u0983)-\u098f\u09b0 \u09aa\u09b0\u09c7 \u0986\u09b0 \u098f\u0995\u099c\u09a8 \u09b0\u09be\u09b8\u09c2\u09b2 \u09aa\u09be\u09a0\u09be\u09ac\u09c7\u09a8?<br class=\"html-br\" \/>\u099a\u09a4\u09c1\u09b0\u09cd\u09a6\u09b6 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09ac\u09be\u09b0\u09cd\u09a4\u09be\u09ac\u09be\u09b9\u0995 \u09aa\u09b6\u09c1<br class=\"html-br\" \/>\u2022 \u09ad\u09be\u09b7\u09be\u09af\u09bc \u09aa\u09cd\u09b0\u09be\u09a3\u09c0\u09b0 \u09b8\u0982\u099c\u09cd\u099e\u09be<br class=\"html-br\" \/>\u2022 \u0987\u09b8\u09b2\u09be\u09ae\u09c0 \u0986\u0987\u09a8 \u0985\u09a8\u09c1\u09b8\u09be\u09b0\u09c7 \u09aa\u09cd\u09b0\u09be\u09a3\u09c0\u09b0 \u09b8\u0982\u099c\u09cd\u099e\u09be<br class=\"html-br\" \/>\u2022 \u09aa\u09b6\u09c1\u09b0 \u0986\u09ac\u09bf\u09b0\u09cd\u09ad\u09be\u09ac\u09c7\u09b0 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3<br class=\"html-br\" \/>\u2022 \u09af\u09c7 \u099c\u09be\u09df\u0997\u09be \u09a5\u09c7\u0995\u09c7 \u09aa\u09cd\u09b0\u09be\u09a3\u09c0\u099f\u09bf \u09ac\u09c7\u09b0\u09bf\u09df\u09c7 \u0986\u09b8\u09c7<br class=\"html-br\" \/>\u2022 \u09aa\u09b6\u09c1\u09b0 \u0995\u09be\u099c<br class=\"html-br\" \/>\u2022 \u09aa\u09b6\u09c1\u09b0 \u09aa\u09cd\u09b0\u0995\u09c3\u09a4\u09bf \u098f\u09ac\u0982 \u09a4\u09be\u09b0 \u09ac\u09b0\u09cd\u09a3\u09a8\u09be \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u09ae\u09be\u09a8\u09c1\u09b7\u09c7\u09b0 \u09ac\u0995\u09cd\u09a4\u09ac\u09cd\u09af<br class=\"html-br\" \/>\u2022 \u09aa\u09cd\u09b0\u09be\u09a3\u09c0\u099f\u09bf \u09af\u09c7 \u098f\u0995\u099c\u09a8 \u09ac\u09be\u09b0\u09cd\u09a4\u09be\u09ac\u09be\u09b9\u0995 \u09a4\u09be\u09b0 \u09aa\u09cd\u09b0\u09ae\u09be\u09a3<br class=\"html-br\" \/>\u09aa\u099e\u09cd\u099a\u09a6\u09b6 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09b8\u09c2\u09b0\u09cd\u09af \u09aa\u09b6\u09cd\u099a\u09bf\u09ae \u09a6\u09bf\u0995 \u09a5\u09c7\u0995\u09c7 \u0989\u09a6\u09bf\u09a4 \u09b9\u09af\u09bc<br class=\"html-br\" \/>\u2022 \u0985\u09a8\u09c1\u09a4\u09be\u09aa\u09c7\u09b0 \u09a6\u09b0\u099c\u09be \u09ac\u09a8\u09cd\u09a7 \u0995\u09b0\u09be<br class=\"html-br\" \/>\u2022 \u098f\u0987 \u0986\u09af\u09bc\u09be\u09a4\u09c7\u09b0 \u09b8\u09ae\u09b8\u09be\u09ae\u09df\u09bf\u0995\u09b0\u09be \u0995\u09bf \u09a4\u09be\u09a6\u09c7\u09b0 \u099c\u09a8\u09cd\u09af \u0985\u09a8\u09c1\u09a4\u09be\u09aa\u09c7\u09b0 \u09a6\u09b0\u099c\u09be \u09ac\u09a8\u09cd\u09a7 \u0995\u09b0\u09c7 \u09a6\u09c7\u0993\u09df\u09be\u09b0 \u09af\u09cb\u0997\u09cd\u09af?<br class=\"html-br\" \/>\u2022 \u09aa\u09b6\u09cd\u099a\u09bf\u09ae \u09a6\u09bf\u0995 \u09a5\u09c7\u0995\u09c7 \u09b8\u09c2\u09b0\u09cd\u09af\u09cb\u09a6\u09af\u09bc\u09c7\u09b0 \u09aa\u09c2\u09b0\u09cd\u09ac\u09ac\u09b0\u09cd\u09a4\u09c0 \u099a\u09bf\u09b9\u09cd\u09a8<br class=\"html-br\" \/>\u2022 \u09b8\u09cc\u09b0\u099c\u0997\u09a4\u09c7\u09b0 \u0997\u09cd\u09b0\u09b9 \u098f\u09ac\u0982 \u099a\u09be\u0981\u09a6\u09c7\u09b0 \u0998\u09c2\u09b0\u09cd\u09a3\u09a8\u09c7\u09b0 \u09a6\u09bf\u0995 \u0995\u09c0?<br class=\"html-br\" \/>\u2022 \u09aa\u09b6\u09cd\u099a\u09bf\u09ae \u09a6\u09bf\u0995 \u09a5\u09c7\u0995\u09c7 \u09b8\u09c2\u09b0\u09cd\u09af \u0993\u09a0\u09be\u09b0 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be<br class=\"html-br\" \/>\u2022 \u09b6\u09c1\u0995\u09cd\u09b0<br class=\"html-br\" \/>\u2022 \u09b6\u09c1\u0995\u09cd\u09b0 \u0997\u09cd\u09b0\u09b9\u09c7\u09b0 \u0989\u09aa\u09b0 \u09b8\u09c2\u09b0\u09cd\u09af \u09aa\u09b6\u09cd\u099a\u09bf\u09ae \u09a6\u09bf\u0995 \u09a5\u09c7\u0995\u09c7 \u0995\u09c7\u09a8 \u0989\u09a6\u09bf\u09a4 \u09b9\u09af\u09bc?<br class=\"html-br\" \/>\u2022 \u09b6\u09c1\u0995\u09cd\u09b0 \u0997\u09cd\u09b0\u09b9 \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0\u09b0 \u09ad\u09ac\u09bf\u09b7\u09cd\u09af\u09ce\u0964<br class=\"html-br\" \/>\u2022 \u09b8\u09c2\u09b0\u09cd\u09af\u09cb\u09a6\u09af\u09bc \u098f\u09ac\u0982 \u09b8\u09c2\u09b0\u09cd\u09af\u09be\u09b8\u09cd\u09a4\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09ac\u09bf\u099a\u09be\u09b0 \u09a6\u09bf\u09ac\u09b8 \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u0995\u09a4 \u09b8\u09ae\u09af\u09bc \u09b2\u09be\u0997\u09c7?<br class=\"html-br\" \/>\u09b7\u09cb\u09a1\u09bc\u09b6 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u09a4\u09bf\u09a8\u099f\u09bf \u0997\u09cd\u09b0\u09b9\u09a3<br class=\"html-br\" \/>\u2022 \u0997\u09cd\u09b0\u09b9\u09a3\u09c7\u09b0 \u0985\u09b0\u09cd\u09a5 \u0995\u09c0 \u098f\u09ac\u0982 \u098f\u09b0 \u09aa\u09cd\u09b0\u0995\u09c3\u09a4\u09bf \u0995\u09c0?<br class=\"html-br\" \/>\u2022 \u09a4\u09bf\u09a8\u099f\u09bf \u0997\u09cd\u09b0\u09b9\u09a3 \u0995\u09cb\u09a5\u09be\u09af\u09bc \u0998\u099f\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u098f\u0987 \u0997\u09cd\u09b0\u09b9\u09a3\u0997\u09c1\u09b2\u09bf \u0995\u09bf \u0985\u09a4\u09c0\u09a4\u09c7 \u0998\u099f\u09c7\u099b\u09c7?<br class=\"html-br\" \/>\u2022 \u09a4\u09bf\u09a8\u099f\u09bf \u0997\u09cd\u09b0\u09b9\u09a3\u09c7\u09b0 \u0986\u0987\u09a8\u09bf \u0995\u09be\u09b0\u09a3<br class=\"html-br\" \/>\u2022 \u099c\u09cd\u099e\u09be\u09a8\u09c7\u09b0 \u0995\u09cd\u09b7\u09a4\u09bf \u098f\u09ac\u0982 \u0985\u099c\u09cd\u099e\u09a4\u09be\u09b0 \u0989\u09a4\u09cd\u09a5\u09be\u09a8<br class=\"html-br\" \/>\u2022 \u09af\u09c0\u09b6\u09c1 (\u0986\u0983)-\u098f\u09b0 \u09ae\u09c3\u09a4\u09cd\u09af\u09c1 \u098f\u09ac\u0982 \u0986\u09a6\u09c7\u09a8 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf\u09b0 \u0985\u0997\u09cd\u09a8\u09cd\u09af\u09c1\u09ce\u09aa\u09be\u09a4\u09c7\u09b0 \u09ae\u09a7\u09cd\u09af\u09ac\u09b0\u09cd\u09a4\u09c0 \u09b8\u09ae\u09af\u09bc\u09c7 \u09ae\u0995\u09cd\u0995\u09be \u0993 \u09ae\u09a6\u09bf\u09a8\u09be\u09b0 \u0985\u09ac\u09b8\u09cd\u09a5\u09be<br class=\"html-br\" \/>\u2022 \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09a3\u0997\u09c1\u09b2\u09bf\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09a4\u09bf\u09a8\u099f\u09bf \u0997\u09cd\u09b0\u09b9\u09a3\u09c7\u09b0 \u0995\u09cd\u09b0\u09ae<br class=\"html-br\" \/>\u2022 \u09a4\u09bf\u09a8\u099f\u09bf \u0997\u09cd\u09b0\u09b9\u09a3\u09c7\u09b0 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995 \u0995\u09be\u09b0\u09a3<br class=\"html-br\" \/>\u09b8\u09aa\u09cd\u09a4\u09a6\u09b6 \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u0986\u09a6\u09c7\u09a8\u09c7\u09b0 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf \u098f\u09ac\u0982 \u09b6\u09c1\u09ad \u09ac\u09be\u09a4\u09be\u09b8<br class=\"html-br\" \/>\u2022 \u098f\u09a1\u09c7\u09a8 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u09a4\u09a5\u09cd\u09af<br class=\"html-br\" \/>\u2022 \u0986\u09a6\u09c7\u09a8 \u09b6\u09b9\u09b0 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u09a8\u09ac\u09c0 \u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09b2\u09cd\u09b2\u09be\u09b9\u09c1 \u0986\u09b2\u09be\u0987\u09b9\u09bf \u0993\u09af\u09bc\u09be\u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09ae\u09c7\u09b0 \u09b9\u09be\u09a6\u09bf\u09b8\u09c7\u09b0 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995, \u09ad\u09cc\u0997\u09cb\u09b2\u09bf\u0995, \u0990\u09a4\u09bf\u09b9\u09be\u09b8\u09bf\u0995 \u098f\u09ac\u0982 \u0986\u09a7\u09cd\u09af\u09be\u09a4\u09cd\u09ae\u09bf\u0995 \u0985\u09b2\u09cc\u0995\u09bf\u0995 \u0998\u099f\u09a8\u09be\u0964<br class=\"html-br\" \/>\u2022 \u09aa\u09ac\u09bf\u09a4\u09cd\u09b0 \u09b9\u09be\u09a6\u09bf\u09b8\u09c7 \u0986\u09a6\u09c7\u09a8 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf<br class=\"html-br\" \/>\u2022 \u0986\u0997\u09c1\u09a8 \u0995\u09cb\u09a5\u09be\u09af\u09bc \u09ac\u09c7\u09b0 \u09b9\u09ac\u09c7 \u09b8\u09c7 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09c7 \u09a8\u09ac\u09c0 \u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09b2\u09cd\u09b2\u09be\u09b9\u09c1 \u0986\u09b2\u09be\u0987\u09b9\u09bf \u0993\u09af\u09bc\u09be\u09b8\u09be\u09b2\u09cd\u09b2\u09be\u09ae\u09c7\u09b0 \u09b9\u09be\u09a6\u09bf\u09b8\u09c7 \u09ad\u09bf\u09a8\u09cd\u09a8\u09a4\u09be \u09b0\u09af\u09bc\u09c7\u099b\u09c7\u0964<br class=\"html-br\" \/>\u2022 \u098f\u0995\u099f\u09bf \u09b8\u09c1\u09aa\u09be\u09b0 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf \u09b9\u09b2 \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a5\u09ae \u099a\u09bf\u09b9\u09cd\u09a8 \u098f\u09ac\u0982 \u098f\u0995\u099f\u09bf \u09b8\u09c1\u09aa\u09be\u09b0 \u0986\u0997\u09cd\u09a8\u09c7\u09af\u09bc\u0997\u09bf\u09b0\u09bf \u09b9\u09b2 \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09b6\u09c7\u09b7 \u099a\u09bf\u09b9\u09cd\u09a8\u0964<br class=\"html-br\" \/>\u2022 \u09ad\u09be\u09b2\u09cb \u09ac\u09be\u09a4\u09be\u09b8<br class=\"html-br\" \/>\u2022 \u09ad\u09be\u09b2\u09cb \u09ac\u09be\u09a4\u09be\u09b8\u09c7\u09b0 \u09b8\u09ae\u09af\u09bc \u0995\u09c0?<br class=\"html-br\" \/>\u2022 \u0985\u09ac\u09b6\u09bf\u09b7\u09cd\u099f \u09ae\u09be\u09a8\u09c1\u09b7\u09b0\u09be \u0995\u09c0\u09ad\u09be\u09ac\u09c7 \u09b2\u09c7\u09ad\u09be\u09a8\u09cd\u099f\u09c7 \u09b8\u09cd\u09a5\u09be\u09a8\u09be\u09a8\u09cd\u09a4\u09b0\u09bf\u09a4 \u09b9\u09ac\u09c7?<br class=\"html-br\" \/>\u2022 \u09a6\u09c1\u09a8\u09bf\u09af\u09bc\u09be\u09a4\u09c7 \u098f\u0995\u09a4\u09cd\u09b0\u09bf\u09a4 \u09b9\u0993\u09af\u09bc\u09be \u098f\u09ac\u0982 \u0986\u0996\u09c7\u09b0\u09be\u09a4\u09c7 \u098f\u0995\u09a4\u09cd\u09b0\u09bf\u09a4 \u09b9\u0993\u09af\u09bc\u09be<br class=\"html-br\" \/>\u0986\u09a0\u09be\u09b0\u09cb \u0985\u09a7\u09cd\u09af\u09be\u09df: \u09b2\u09c7\u09ad\u09be\u09a8\u09cd\u099f\u09c7 \u09b8\u09ae\u09ac\u09c7\u09a4 \u09b9\u0993\u09df\u09be\u09b0 \u09ad\u09c2\u09ae\u09bf \u098f\u09ac\u0982 \u09ac\u09bf\u099a\u09be\u09b0 \u09a6\u09bf\u09ac\u09b8<br class=\"html-br\" \/>\u2022 \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u0986\u0997\u09c7 \u09b2\u09c7\u09ad\u09be\u09a8\u09cd\u099f\u09c7 \u09ac\u09cd\u09af\u09be\u09aa\u0995\u09ad\u09be\u09ac\u09c7 \u0995\u09cb\u09a8 \u0989\u09aa\u09be\u09b8\u09a8\u09be \u09aa\u09cd\u09b0\u099a\u09b2\u09bf\u09a4 \u099b\u09bf\u09b2?<br class=\"html-br\" \/>\u2022 \u09b0\u09be\u09b8\u09cd\u09a4\u09be\u09af\u09bc \u09aa\u09cd\u09b0\u0995\u09be\u09b6\u09cd\u09af\u09c7 \u09ac\u09cd\u09af\u09ad\u09bf\u099a\u09be\u09b0<br class=\"html-br\" \/>\u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4 \u0995\u09c7\u09ac\u09b2 \u09a8\u09bf\u0995\u09c3\u09b7\u09cd\u099f\u09a4\u09ae \u09b8\u09c3\u09b7\u09cd\u099f\u09bf\u09b0 \u0989\u09aa\u09b0\u0987 \u09b8\u0982\u0998\u099f\u09bf\u09a4 \u09b9\u09ac\u09c7\u0964<br class=\"html-br\" \/>\u098f\u0987 \u09b8\u09ae\u09af\u09bc \u09ae\u09be\u09a8\u09c1\u09b7\u0995\u09c7 \u0985\u09ac\u09be\u0995 \u0995\u09b0\u09c7 \u098f\u09ac\u0982 \u0985\u09ac\u09be\u0995 \u0995\u09b0\u09c7 \u09a6\u09c7\u09af\u09bc\u0964<br class=\"html-br\" \/>\u2022 \u09aa\u09c1\u09a8\u09b0\u09c1\u09a4\u09cd\u09a5\u09be\u09a8\u09c7\u09b0 \u09a6\u09bf\u09a8<br class=\"html-br\" \/>\u0989\u09a8\u09bf\u09b6\u09a4\u09ae \u0985\u09a7\u09cd\u09af\u09be\u09af\u09bc: \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u0986\u09b2\u09be\u09ae\u09a4 \u09b8\u09ae\u09cd\u09aa\u09b0\u09cd\u0995\u09bf\u09a4 \u09ac\u09bf\u09ad\u09bf\u09a8\u09cd\u09a8 \u09aa\u09b0\u09bf\u09b8\u0982\u0996\u09cd\u09af\u09be\u09a8<br class=\"html-br\" \/>\u2022 \u09af\u09c7\u09b8\u09ac \u0986\u09af\u09bc\u09be\u09a4\u09c7 \u09aa\u09cd\u09b0\u09a4\u09c0\u0995\u09cd\u09b7\u09bf\u09a4 \u09b0\u09be\u09b8\u09c2\u09b2\u09a6\u09c7\u09b0 \u0995\u09a5\u09be \u0989\u09b2\u09cd\u09b2\u09c7\u0996 \u0995\u09b0\u09be \u09b9\u09af\u09bc\u09c7\u099b\u09c7<br class=\"html-br\" \/>\u2022 \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09a3\u0997\u09c1\u09b2\u09bf\u09b0 \u0995\u09be\u09b2\u0995\u09cd\u09b0\u09ae<br class=\"html-br\" \/>\u2022 \u0995\u09c7\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09a3 \u09aa\u09cd\u09b0\u0995\u09be\u09b6 \u09aa\u09c7\u09a4\u09c7 \u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4 \u0986\u09b8\u09be\u09b0 \u0986\u0997 \u09aa\u09b0\u09cd\u09af\u09a8\u09cd\u09a4 \u09b8\u09ae\u09af\u09bc \u09b2\u09be\u0997\u09ac\u09c7<br class=\"html-br\" \/>\u2022 \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0 \u0995\u09a4\u0997\u09c1\u09b2\u09bf \u09ac\u09bf\u09b6\u09be\u09b2 \u09aa\u09cd\u09b0\u09be\u0995\u09c3\u09a4\u09bf\u0995 \u09a6\u09c1\u09b0\u09cd\u09af\u09cb\u0997 \u09aa\u09cd\u09b0\u09a4\u09cd\u09af\u0995\u09cd\u09b7 \u0995\u09b0\u09ac\u09c7<br class=\"html-br\" \/>\u2022 \u09aa\u09c3\u09a5\u09bf\u09ac\u09c0\u09a4\u09c7 \u09af\u09c7 \u09ac\u09bf\u09b6\u09be\u09b2 \u09aa\u09cd\u09b0\u09be\u0995\u09c3\u09a4\u09bf\u0995 \u09a6\u09c1\u09b0\u09cd\u09af\u09cb\u0997 \u0986\u09b8\u09ac\u09c7 \u09a4\u09be\u09b0 \u09ac\u09c8\u099c\u09cd\u099e\u09be\u09a8\u09bf\u0995 \u09ac\u09cd\u09af\u09be\u0996\u09cd\u09af\u09be<br class=\"html-br\" \/>\u2022 \u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a7\u09be\u09a8 \u09b2\u0995\u09cd\u09b7\u09a3\u0997\u09c1\u09b2\u09bf\u09b0 \u09b8\u09ae\u09af\u09bc\u0995\u09be\u09b2\u09c7 \u09ae\u09be\u09a8\u09c1\u09b7\u09c7\u09b0 \u0985\u09ad\u09bf\u09ac\u09be\u09b8\u09a8 \u09aa\u09cd\u09b0\u0995\u09cd\u09b0\u09bf\u09af\u09bc\u09be\u09b0 \u09ae\u09be\u09a8\u099a\u09bf\u09a4\u09cd\u09b0<br class=\"html-br\" \/>\u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u09b2\u0995\u09cd\u09b7\u09a3 \u09aa\u09cd\u09b0\u0995\u09be\u09b6\u09c7\u09b0 \u09b8\u09ae\u09af\u09bc \u09b8\u09ad\u09cd\u09af\u09a4\u09be\u09b0 \u0985\u0997\u09cd\u09b0\u09af\u09be\u09a4\u09cd\u09b0\u09be<br class=\"html-br\" \/>\u2022 \u0995\u09bf\u09af\u09bc\u09be\u09ae\u09a4\u09c7\u09b0 \u0986\u09b2\u09be\u09ae\u09a4 \u09aa\u09cd\u09b0\u0995\u09be\u09b6\u09c7\u09b0 \u09b8\u09ae\u09af\u09bc \u09ae\u09c3\u09a4 \u0993 \u09ae\u09c3\u09a4\u09a6\u09c7\u09b0 \u0986\u09a8\u09c1\u09ae\u09be\u09a8\u09bf\u0995 \u09b8\u0982\u0996\u09cd\u09af\u09be<br class=\"html-br\" \/>\u0989\u09aa\u09b8\u0982\u09b9\u09be\u09b0<br class=\"html-br\" \/><br class=\"html-br\" \/>* * *<br class=\"html-br\" \/><br class=\"html-br\" \/>\u09ae\u09bf\u09b6\u09b0\u09c7\u09b0 \u09ad\u09c7\u09a4\u09b0\u09c7 \u09ac\u09be \u09ac\u09be\u0987\u09b0\u09c7 \u09a5\u09c7\u0995\u09c7 \u09aa\u09cd\u09b0\u09a4\u09c0\u0995\u09cd\u09b7\u09bf\u09a4 \u099a\u09bf\u09a0\u09bf\u09aa\u09a4\u09cd\u09b0\u09c7\u09b0 \u09ac\u0987\u099f\u09bf \u09aa\u09c7\u09a4\u09c7, \u0986\u09a6\u09bf\u09ac \u09b2\u09be\u0987\u09ac\u09cd\u09b0\u09c7\u09b0\u09bf\u09b0 \u09b8\u09be\u09a5\u09c7 \u09ab\u09cb\u09a8\u09c7 \u09ac\u09be \u09b9\u09cb\u09af\u09bc\u09be\u099f\u09b8\u0985\u09cd\u09af\u09be\u09aa\u09c7\u09b0 \u09ae\u09be\u09a7\u09cd\u09af\u09ae\u09c7 \u09af\u09cb\u0997\u09be\u09af\u09cb\u0997 \u0995\u09b0\u09c1\u09a8, \u099f\u09c7\u09b2\u09bf\u09ab\u09cb\u09a8 \u09a8\u09ae\u09cd\u09ac\u09b0 00201111513811<br class=\"html-br\" \/><span class=\"html-span xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x1hl2dhg x16tdsg8 x1vvkbs\"><a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xkrqix3 x1sur9pj xzsf02u x1s688f\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/ADIBBOOKSTORS\/?__tn__=-UK*F\">https:\/\/www.facebook.com\/ADIBBOOKSTORS\/<\/a><\/span><br class=\"html-br\" \/><br class=\"html-br\" \/>\u0985\u09a5\u09ac\u09be \u0986\u09aa\u09a8\u09bf \u0986\u09aa\u09a8\u09be\u09b0 \u09a8\u09bf\u0995\u099f\u09a4\u09ae \u09b2\u09be\u0987\u09ac\u09cd\u09b0\u09c7\u09b0\u09bf\u09a4\u09c7 \u09af\u09c7\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8 \u098f\u09ac\u0982 \u09a4\u09be\u09a6\u09c7\u09b0 \u0986\u09ae\u09be\u09b0 \u09ac\u0987\u09af\u09bc\u09c7\u09b0 \u09a8\u09be\u09ae (\u09a6\u09cd\u09af \u0993\u09af\u09bc\u09c7\u099f\u09bf\u0982 \u09b2\u09c7\u099f\u09be\u09b0\u09b8), \u0986\u09a6\u09bf\u09ac \u09b2\u09be\u0987\u09ac\u09cd\u09b0\u09c7\u09b0\u09bf\u09b0 \u09a4\u09a5\u09cd\u09af \u098f\u09ac\u0982 \u098f\u09b0 \u09ab\u09cb\u09a8 \u09a8\u09ae\u09cd\u09ac\u09b0 \u09a6\u09bf\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8 \u09af\u09be\u09a4\u09c7 \u09a4\u09be\u09b0\u09be \u09a4\u09be\u09a6\u09c7\u09b0 \u09b8\u09cd\u09ac\u09be\u09ad\u09be\u09ac\u09bf\u0995 \u09aa\u09a6\u09cd\u09a7\u09a4\u09bf\u09a4\u09c7 \u0986\u09ae\u09be\u09b0 \u09ac\u0987\u099f\u09bf \u09a4\u09be\u09a6\u09c7\u09b0 \u0995\u09be\u099b \u09a5\u09c7\u0995\u09c7 \u09aa\u09c7\u09a4\u09c7 \u09aa\u09be\u09b0\u09c7\u09a8\u0964<br class=\"html-br\" \/>\u0986\u09ae\u09be\u09b0 \u09ac\u0987\u09af\u09bc\u09c7\u09b0 \u0987\u09b2\u09c7\u0995\u099f\u09cd\u09b0\u09a8\u09bf\u0995 \u0995\u09aa\u09bf \u09aa\u09be\u0993\u09af\u09bc\u09be\u09b0 \u0995\u09a5\u09be \u09ac\u09b2\u09a4\u09c7 \u0997\u09c7\u09b2\u09c7, \u09ac\u09b0\u09cd\u09a4\u09ae\u09be\u09a8\u09c7 \u098f\u099f\u09bf \u0986\u09ae\u09be\u09b0 \u098f\u09ac\u0982 \u09aa\u09cd\u09b0\u0995\u09be\u09b6\u09a8\u09be \u09b8\u0982\u09b8\u09cd\u09a5\u09be\u09b0 \u09ae\u09a7\u09cd\u09af\u09c7 \u09ac\u0987\u099f\u09bf \u09ae\u09c1\u09a6\u09cd\u09b0\u09bf\u09a4 \u0986\u0995\u09be\u09b0\u09c7 \u09aa\u09cd\u09b0\u0995\u09be\u09b6\u09c7\u09b0 \u099a\u09c1\u0995\u09cd\u09a4\u09bf\u09b0 \u0995\u09be\u09b0\u09a3\u09c7 \u09aa\u09be\u0993\u09af\u09bc\u09be \u09af\u09be\u099a\u09cd\u099b\u09c7 \u09a8\u09be, \u098f\u09ac\u0982 \u0986\u09ae\u09bf \u09a8\u09bf\u0995\u099f \u09ad\u09ac\u09bf\u09b7\u09cd\u09af\u09a4\u09c7 \u098f\u0987 \u09b8\u09ae\u09b8\u09cd\u09af\u09be\u099f\u09bf \u09b8\u09ae\u09be\u09a7\u09be\u09a8 \u0995\u09b0\u09be\u09b0 \u099a\u09c7\u09b7\u09cd\u099f\u09be \u0995\u09b0\u09ac, \u0987\u09a8\u09b6\u09be\u0986\u09b2\u09cd\u09b2\u09be\u09b9\u0964\u00a0<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>19 \u062f\u064a\u0633\u0645\u0628\u0631 2019 \u00a0 \u0641\u0647\u0631\u0633 \u0643\u062a\u0627\u0628 \u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629 \u0643\u0645\u0627 \u062a\u0648\u0642\u0639\u062a \u0641\u0645\u0646\u0630 \u0625\u0635\u062f\u0627\u0631 \u0643\u062a\u0627\u0628\u064a \u0627\u0644\u062c\u062f\u064a\u062f (\u0627\u0644\u0631\u0633\u0627\u0626\u0644 \u0627\u0644\u0645\u0646\u062a\u0638\u0631\u0629) \u0641\u0642\u062f \u0642\u0648\u0628\u0644\u062a \u0628\u0633\u064a\u0644 \u0645\u0646 \u0627\u0644\u0647\u062c\u0648\u0645 \u0648\u0627\u0644\u0627\u062a\u0647\u0627\u0645\u0627\u062a \u0628\u0627\u0644\u0636\u0644\u0627\u0644 \u0648\u0647\u0630\u0647 \u0643\u0627\u0646\u062a \u0645\u0646 \u0623\u0647\u0645 \u0627\u0644\u0623\u0633\u0628\u0627\u0628 \u0627\u0644\u062a\u064a \u062c\u0639\u0644\u062a\u0646\u064a \u0623\u062a\u0631\u062f\u062f \u0648\u0623\u062a\u0648\u0642\u0641 \u0639\u062f\u0629 \u0645\u0631\u0627\u062a \u0628\u062e\u0635\u0648\u0635 \u062a\u0623\u0644\u064a\u0641 \u0643\u062a\u0627\u0628\u064a \u0645\u0646\u0630 \u0633\u062a\u0629 \u0623\u0634\u0647\u0631\u0648\u0642\u062f \u062d\u0627\u0648\u0644\u062a \u0627\u0644\u062a\u0645\u0647\u064a\u062f \u0644\u0643\u0645 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0645\u0631\u0629 \u0648\u0642\u0644\u062a \u0644\u0643\u0645 \u0644\u0627 \u062a\u062d\u0643\u0645\u0648\u0627 \u0639\u0644\u0649 \u0627\u0644\u0643\u062a\u0627\u0628 \u062f\u0648\u0646 \u0642\u0631\u0627\u0621\u062a\u0647 \u0648\u0644\u0643\u0646 [&hellip;]<\/p>","protected":false},"author":2,"featured_media":22045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[113],"tags":[],"class_list":{"0":"post-22043","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-113"},"_links":{"self":[{"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/posts\/22043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/comments?post=22043"}],"version-history":[{"count":0,"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/posts\/22043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/media\/22045"}],"wp:attachment":[{"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/media?parent=22043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/categories?post=22043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tamerbadr.com\/bn\/wp-json\/wp\/v2\/tags?post=22043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}